{"id":74703,"date":"2026-02-05T14:50:15","date_gmt":"2026-02-05T14:50:15","guid":{"rendered":"https:\/\/loginfo24.com\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/"},"modified":"2026-02-05T14:50:15","modified_gmt":"2026-02-05T14:50:15","slug":"mudanca-de-gestao-na-lufthansa-cargo","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/","title":{"rendered":"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo"},"content":{"rendered":"<p>Lufthansa Cargo anunciou v\u00e1rias mudan\u00e7as na gest\u00e3o que entrar\u00e3o em vigor em fevereiro de 2026. Gunnar L\u00f6hr (esquerda) assumir\u00e1, a partir de 15 de fevereiro de 2026, a responsabilidade pela regi\u00e3o DACH, bem como o gerenciamento de contas-chave para as regi\u00f5es Europa, Oriente M\u00e9dio e \u00c1frica. Antes, L\u00f6hr atuou como Head of Supply Management and Infrastructure e traz ampla experi\u00eancia de diversos mercados internacionais. Ele come\u00e7ou sua carreira na Lufthansa Cargo em 2002 e, desde ent\u00e3o, ocupou v\u00e1rias posi\u00e7\u00f5es de lideran\u00e7a na ind\u00fastria de frete a\u00e9reo.<\/p>\n<h3>Novas posi\u00e7\u00f5es de lideran\u00e7a e seus antecedentes<\/h3>\n<p>L\u00f6hr sucede Philip Rauchhaus (meio), que assumir\u00e1 a posi\u00e7\u00e3o de Vice President of Global Revenue Management and Pricing a partir de 1\u00ba de janeiro de 2026. Rauchhaus sucede Helge Kr\u00fcger-Lorenzen, que se aposentar\u00e1 ap\u00f3s 38 anos no Lufthansa Group. Anand Kulkarni, Head of Global Markets da Lufthansa Cargo, comentou positivamente sobre a nomea\u00e7\u00e3o de L\u00f6hr e destacou sua vasta experi\u00eancia em lideran\u00e7a e a capacidade de trazer novos impulsos nas rela\u00e7\u00f5es com os clientes.<\/p>\n<p>Markus Cirjan (direita) assumir\u00e1 a lideran\u00e7a operacional do hub em Munique no pr\u00f3ximo momento poss\u00edvel. Atualmente, ele \u00e9 Director Sales &amp; Handling para os EUA Mid-Atlantic &amp; Ohio Valley e, desde sua entrada na Lufthansa Cargo em 2013, passou por v\u00e1rias posi\u00e7\u00f5es na \u00e1rea de Lean Management e vendas nos EUA. Cirjan sucede Ivo Seehann, que assumir\u00e1 novas fun\u00e7\u00f5es no \u00e2mbito da coopera\u00e7\u00e3o com a Swiss WorldCargo. Frank Bauer, membro do conselho de opera\u00e7\u00f5es da Lufthansa Cargo, expressou satisfa\u00e7\u00e3o com a mudan\u00e7a de Cirjan para Munique e sua expertise na \u00e1rea de log\u00edstica.<\/p>\n<p>Essas mudan\u00e7as na gest\u00e3o da Lufthansa Cargo fazem parte de uma reorienta\u00e7\u00e3o estrat\u00e9gica que visa melhorar a efici\u00eancia e as rela\u00e7\u00f5es com os clientes. Os novos l\u00edderes trazem experi\u00eancias diversificadas de diferentes mercados, o que pode ser significativo para o desenvolvimento futuro da empresa.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.lufthansa-cargo.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.lufthansa-cargo.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Lufthansa Cargo anuncia v\u00e1rias mudan\u00e7as na gest\u00e3o a partir de fevereiro de 2026, com o objetivo de melhorar a efici\u00eancia e as rela\u00e7\u00f5es com os clientes, al\u00e9m de trazer novos impulsos.<\/p>\n","protected":false},"author":12,"featured_media":74698,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6663,7340,6679,1615,6665,1618],"tags":[],"class_list":["post-74703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alemanha","category-amerikas","category-europa","category-pessoas-e-empresas","category-suica","category-transporte-aereo-de-mercadorias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A Lufthansa Cargo anuncia v\u00e1rias mudan\u00e7as na gest\u00e3o a partir de fevereiro de 2026, com o objetivo de melhorar a efici\u00eancia e as rela\u00e7\u00f5es com os clientes, al\u00e9m de trazer novos impulsos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-05T14:50:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/20260204-PM-1200x675.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo\",\"datePublished\":\"2026-02-05T14:50:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/\"},\"wordCount\":355,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/20260204-PM.png\",\"articleSection\":[\"Alemanha\",\"Amerikas\",\"Europa\",\"Pessoas e empresas\",\"Su\u00ed\u00e7a\",\"Transporte a\u00e9reo de mercadorias\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/\",\"name\":\"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/20260204-PM.png\",\"datePublished\":\"2026-02-05T14:50:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/20260204-PM.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/20260204-PM.png\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/02\\\/05\\\/mudanca-de-gestao-na-lufthansa-cargo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/","og_locale":"pt_PT","og_type":"article","og_title":"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo - Loginfo24","og_description":"A Lufthansa Cargo anuncia v\u00e1rias mudan\u00e7as na gest\u00e3o a partir de fevereiro de 2026, com o objetivo de melhorar a efici\u00eancia e as rela\u00e7\u00f5es com os clientes, al\u00e9m de trazer novos impulsos.","og_url":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-02-05T14:50:15+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/20260204-PM-1200x675.png","type":"image\/png"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andreas Haug","Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo","datePublished":"2026-02-05T14:50:15+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/"},"wordCount":355,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/20260204-PM.png","articleSection":["Alemanha","Amerikas","Europa","Pessoas e empresas","Su\u00ed\u00e7a","Transporte a\u00e9reo de mercadorias"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/","url":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/","name":"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/20260204-PM.png","datePublished":"2026-02-05T14:50:15+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/20260204-PM.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/20260204-PM.png","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/02\/05\/mudanca-de-gestao-na-lufthansa-cargo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Mudan\u00e7a de gest\u00e3o na Lufthansa Cargo"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/loginfo24.com\/pt-pt\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/74703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=74703"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/74703\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/74698"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=74703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=74703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=74703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}