{"id":72717,"date":"2026-01-12T10:55:45","date_gmt":"2026-01-12T10:55:45","guid":{"rendered":"https:\/\/loginfo24.dashboard.brand-architecture.at\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/"},"modified":"2026-01-12T10:55:45","modified_gmt":"2026-01-12T10:55:45","slug":"mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/","title":{"rendered":"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque"},"content":{"rendered":"<p>Governa Kathy Hochul anunciou que mais de 101 milh\u00f5es de d\u00f3lares americanos ser\u00e3o disponibilizados para 25 projetos em Nova York. Esses projetos visam modernizar as linhas de transporte de mercadorias e as instala\u00e7\u00f5es portu\u00e1rias no \u00e2mbito do Programa de Assist\u00eancia ao Transporte Ferrovi\u00e1rio de Passageiros e Cargas (PFRAP). Os investimentos devem melhorar a confiabilidade e a resili\u00eancia de rotas comerciais significativas, ao mesmo tempo em que apoiam o combate \u00e0s mudan\u00e7as clim\u00e1ticas, conforme informa o escrit\u00f3rio de imprensa da governadora. O foco dos projetos est\u00e1 na renova\u00e7\u00e3o de trilhos e pontes, na amplia\u00e7\u00e3o da capacidade, na aquisi\u00e7\u00e3o de ve\u00edculos ferrovi\u00e1rios mais ecol\u00f3gicos, bem como na moderniza\u00e7\u00e3o e expans\u00e3o da infraestrutura ferrovi\u00e1ria em terminais de carga e instala\u00e7\u00f5es portu\u00e1rias.<\/p>\n<p>Entre outros, o estado est\u00e1 financiando com 1,7 milh\u00f5es de d\u00f3lares a conex\u00e3o de uma instala\u00e7\u00e3o de gr\u00e3os \u00e0 Finger Lakes Railway em Waterloo, com 3,2 milh\u00f5es de d\u00f3lares a conex\u00e3o direta \u00e0 South Buffalo Railroad no local da UFP em Lackawanna, e com 4,6 milh\u00f5es de d\u00f3lares a renova\u00e7\u00e3o de pontes e trilhos na Buffalo and Pittsburgh Railroad. Al\u00e9m disso, 1,6 milh\u00f5es de d\u00f3lares est\u00e3o sendo disponibilizados para melhorar a infraestrutura ferrovi\u00e1ria em Sangerfield.<\/p>\n<p><a href=\"https:\/\/www.governor.ny.gov\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.governor.ny.gov<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A governadora Kathy Hochul anunciou que mais de 101 milh\u00f5es de d\u00f3lares ser\u00e3o investidos em 25 projetos para a moderniza\u00e7\u00e3o do transporte de cargas em Nova York<\/p>\n","protected":false},"author":10,"featured_media":72712,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1616],"tags":[4152,4153,4154,3946,4155,4156,4157,4158,4159,4160,4161,4162,4163,4164,1970,4165,4166,4167,4168,4169,3961,4170,4171,4172,4173,2136,4174,4175,4176,4177,4178,4179,4180,4181,4182,4183,4184,1916,4185,4186,4187,4188,4189,4190,4191,4192],"class_list":["post-72717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intermodal-rodoviario","tag-bridge-renovation","tag-brueckensanierung","tag-buffalo-and-pittsburgh-railroad","tag-capacity-expansion","tag-changement-climatique","tag-climate-change","tag-deutsch-gueterverkehr","tag-eco-friendly-tracks","tag-expansion-de-capacite","tag-finger-lakes-railway","tag-fret-ferroviaire","tag-getreideanlage","tag-grain-facility","tag-hafenanlagen","tag-handelsrouten","tag-infrastructure-ferroviaire","tag-infrastructure-projects","tag-infrastrukturprojekte","tag-installation-de-cereales","tag-installations-portuaires","tag-kapazitaetserweiterung","tag-kathy-hochul","tag-klimawandel","tag-logistics-francais-transport-de-marchandises","tag-logistik-english-freight-transport","tag-logistique","tag-modernisation-des-transports","tag-new-york","tag-pfrap","tag-port-facilities","tag-projets-dinfrastructure","tag-rail-freight","tag-rail-infrastructure","tag-rail-vehicles","tag-renovation-de-ponts","tag-routes-commerciales","tag-schienenfahrzeuge","tag-schienengueterverkehr","tag-schieneninfrastruktur","tag-south-buffalo-railroad","tag-trade-routes","tag-transportation-modernization","tag-umweltfreundliche-gleise","tag-vehicules-ferroviaires","tag-verkehrsmodernisierung","tag-voies-ecologiques"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A governadora Kathy Hochul anunciou que mais de 101 milh\u00f5es de d\u00f3lares ser\u00e3o investidos em 25 projetos para a moderniza\u00e7\u00e3o do transporte de cargas em Nova York\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-12T10:55:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeremy Soland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Soland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/\"},\"author\":{\"name\":\"Jeremy Soland\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\"},\"headline\":\"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque\",\"datePublished\":\"2026-01-12T10:55:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg\",\"keywords\":[\"bridge renovation\",\"Br\u00fcckensanierung\",\"Buffalo and Pittsburgh Railroad\",\"capacity expansion\",\"changement climatique\",\"climate change\",\"Deutsch G\u00fcterverkehr\",\"eco-friendly tracks\",\"expansion de capacit\u00e9\",\"Finger Lakes Railway\",\"fret ferroviaire\",\"Getreideanlage\",\"grain facility\",\"Hafenanlagen\",\"Handelsrouten\",\"infrastructure ferroviaire\",\"infrastructure projects\",\"Infrastrukturprojekte\",\"installation de c\u00e9r\u00e9ales\",\"installations portuaires\",\"Kapazit\u00e4tserweiterung\",\"Kathy Hochul\",\"Klimawandel\",\"logistics Fran\u00e7ais transport de marchandises\",\"Logistik English freight transport\",\"logistique\",\"modernisation des transports\",\"New York\",\"PFRAP\",\"port facilities\",\"projets d'infrastructure\",\"rail freight\",\"rail infrastructure\",\"rail vehicles\",\"r\u00e9novation de ponts\",\"routes commerciales\",\"Schienenfahrzeuge\",\"Schieneng\u00fcterverkehr\",\"Schieneninfrastruktur\",\"South Buffalo Railroad\",\"trade routes\",\"transportation modernization\",\"umweltfreundliche Gleise\",\"v\u00e9hicules ferroviaires\",\"Verkehrsmodernisierung\",\"voies \u00e9cologiques\"],\"articleSection\":[\"Intermodal \\\/ Rodovi\u00e1rio\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/\",\"name\":\"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg\",\"datePublished\":\"2026-01-12T10:55:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2026\\\/01\\\/12\\\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\",\"name\":\"Jeremy Soland\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/author\\\/jeremy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/","og_locale":"pt_PT","og_type":"article","og_title":"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque - Loginfo24","og_description":"A governadora Kathy Hochul anunciou que mais de 101 milh\u00f5es de d\u00f3lares ser\u00e3o investidos em 25 projetos para a moderniza\u00e7\u00e3o do transporte de cargas em Nova York","og_url":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-01-12T10:55:45+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg","type":"image\/jpeg"}],"author":"Jeremy Soland","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Jeremy Soland","Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/"},"author":{"name":"Jeremy Soland","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa"},"headline":"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque","datePublished":"2026-01-12T10:55:45+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg","keywords":["bridge renovation","Br\u00fcckensanierung","Buffalo and Pittsburgh Railroad","capacity expansion","changement climatique","climate change","Deutsch G\u00fcterverkehr","eco-friendly tracks","expansion de capacit\u00e9","Finger Lakes Railway","fret ferroviaire","Getreideanlage","grain facility","Hafenanlagen","Handelsrouten","infrastructure ferroviaire","infrastructure projects","Infrastrukturprojekte","installation de c\u00e9r\u00e9ales","installations portuaires","Kapazit\u00e4tserweiterung","Kathy Hochul","Klimawandel","logistics Fran\u00e7ais transport de marchandises","Logistik English freight transport","logistique","modernisation des transports","New York","PFRAP","port facilities","projets d'infrastructure","rail freight","rail infrastructure","rail vehicles","r\u00e9novation de ponts","routes commerciales","Schienenfahrzeuge","Schieneng\u00fcterverkehr","Schieneninfrastruktur","South Buffalo Railroad","trade routes","transportation modernization","umweltfreundliche Gleise","v\u00e9hicules ferroviaires","Verkehrsmodernisierung","voies \u00e9cologiques"],"articleSection":["Intermodal \/ Rodovi\u00e1rio"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/","url":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/","name":"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg","datePublished":"2026-01-12T10:55:45+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/AdobeStock_42993719-6-scaled-aspect-ratio-1400-788-1-scaled-1.jpeg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2026\/01\/12\/mais-de-101-milhoes-de-dolares-para-o-transporte-de-mercadorias-em-nova-iorque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Mais de 101 milh\u00f5es de d\u00f3lares para o transporte de mercadorias em Nova Iorque"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa","name":"Jeremy Soland","url":"https:\/\/loginfo24.com\/pt-pt\/author\/jeremy\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/72717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=72717"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/72717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/72712"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=72717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=72717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=72717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}