{"id":69823,"date":"2025-07-13T17:13:16","date_gmt":"2025-07-13T15:13:16","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/"},"modified":"2025-07-13T17:13:16","modified_gmt":"2025-07-13T15:13:16","slug":"drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/","title":{"rendered":"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia"},"content":{"rendered":"<h5><strong>driveMybox, a plataforma digital de transporte de contentores com sede em Hamburgo,<\/strong><strong> expande-se para o Sudeste da Europa. Ap\u00f3s a Alemanha, It\u00e1lia e Hungria<\/strong><strong> (como hub regional para a Europa de Leste), a Gr\u00e9cia ser\u00e1 o quarto pa\u00eds a fazer parte da<\/strong><strong> rede driveMybox \u2013 e atender\u00e1 tamb\u00e9m os mercados na Bulg\u00e1ria e<\/strong><strong> na Maced\u00f4nia do Norte. Com isso, a empresa marca mais um marco no caminho<\/strong><strong> para uma solu\u00e7\u00e3o digital europeia para o transporte de contentores.<\/strong><\/h5>\n<p>(Hamburgo) Com esta entrada no mercado, a driveMybox traz sua inovadora plataforma totalmente digitalizada para uma regi\u00e3o estrategicamente importante. A nova localiza\u00e7\u00e3o permitir\u00e1 que a empresa atenda, a partir de agora, um dos principais corredores de transporte na regi\u00e3o do Mediterr\u00e2neo \u2013 com ainda mais flexibilidade, transpar\u00eancia e efici\u00eancia para clientes e prestadores de servi\u00e7os de transporte. A representa\u00e7\u00e3o da driveMybox no Sudeste da Europa ser\u00e1 feita atrav\u00e9s de uma nova empresa, a driveMybox Greece S.A.<\/p>\n<p>\u201cCom a Alemanha, It\u00e1lia e nosso hub na Europa de Leste na Hungria, j\u00e1 estabelecemos uma base forte no continente. A Gr\u00e9cia \u00e9 um passo estrat\u00e9gico l\u00f3gico a seguir\u201d, afirma Patrick Jandt, CEO da driveMybox. \u201cJuntos, estamos agora expandindo nossa solu\u00e7\u00e3o log\u00edstica inteligente \u2013 para um transporte de contentores digital e inovador em toda a Europa.\u201d<\/p>\n<p>Gordon Friza, CFO da driveMybox, acrescenta<strong>: <\/strong>\u201cCada novo mercado n\u00e3o \u00e9 apenas parte da nossa estrat\u00e9gia de crescimento a longo prazo, mas tamb\u00e9m abre significativos potenciais econ\u00f4micos locais. Com a expans\u00e3o da driveMybox na Gr\u00e9cia, Bulg\u00e1ria e Maced\u00f4nia do Norte, estamos confiantes de que podemos construir uma forte presen\u00e7a na regi\u00e3o do Mediterr\u00e2neo \u2013 e assim impulsionar tanto nosso alcance operacional quanto nosso objetivo de tornar o transporte de contentores na Europa mais conectado, eficiente e sustent\u00e1vel.\u201d<\/p>\n<p>Com a assinatura do contrato, a fase de implementa\u00e7\u00e3o come\u00e7a agora: a equipe da driveMybox est\u00e1 trabalhando em estreita colabora\u00e7\u00e3o com a nova equipe na Gr\u00e9cia para adaptar a plataforma \u00e0s exig\u00eancias do mercado local. Esta abordagem colaborativa garante que as condi\u00e7\u00f5es regionais sejam consideradas \u2013 mantendo a experi\u00eancia do usu\u00e1rio intuitiva e eficiente que caracteriza a driveMybox.<\/p>\n<p>Constantinos Mouskos, CEO da driveMybox Greece: \u201cEstamos muito felizes em trazer a driveMybox para a Gr\u00e9cia e permitir que empresas de transporte e carregadores possam processar ordens de transporte de forma significativamente mais eficiente. Com a plataforma, iniciamos uma atualiza\u00e7\u00e3o digital urgentemente necess\u00e1ria para o mercado log\u00edstico local \u2013 e estamos ansiosos para moldar juntos o futuro digital do transporte em nossa regi\u00e3o e al\u00e9m.\u201d<\/p>\n<h5>Tornar-se a empresa l\u00edder em transporte digital de contentores<\/h5>\n<p>driveMybox foi lan\u00e7ada em 2020 na Alemanha e expandiu-se para a It\u00e1lia em 2021 e para a Hungria em 2024 \u2013 a partir de onde tamb\u00e9m atende clientes na Rom\u00eania e na Eslov\u00eania. Al\u00e9m disso, a driveMybox oferece transportes transfronteiri\u00e7os para os respectivos pa\u00edses vizinhos. A miss\u00e3o \u00e9 clara: tornar-se a solu\u00e7\u00e3o digital l\u00edder para o transporte de contentores na Europa \u2013 e a longo prazo, em todo o mundo.<\/p>\n<p>Foto: \u00a9 driveMybox \/ <em><strong>Legenda da imagem<\/strong> (da esquerda para a direita): Gordon Friza, CFO da driveMybox \/ Constantinos Mouskos, CEO da driveMybox Greece \/ Patrick Jandt, CEO da driveMybox<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>driveMybox, a plataforma digital de transporte de contentores com sede em Hamburgo, expande-se para o Sudeste da Europa. Ap\u00f3s a Alemanha, It\u00e1lia e Hungria (como hub<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4767,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1561,1559],"tags":[],"class_list":["post-69823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"driveMybox, a plataforma digital de transporte de contentores com sede em Hamburgo, expande-se para o Sudeste da Europa. Ap\u00f3s a Alemanha, It\u00e1lia e Hungria (como hub [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-13T15:13:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/driveMybox_13.7.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1245\" \/>\n\t<meta property=\"og:image:height\" content=\"773\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia\",\"datePublished\":\"2025-07-13T15:13:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/\"},\"wordCount\":577,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/driveMybox_13.7.25.jpg\",\"articleSection\":[\"Categories\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/\",\"name\":\"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/driveMybox_13.7.25.jpg\",\"datePublished\":\"2025-07-13T15:13:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/driveMybox_13.7.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/driveMybox_13.7.25.jpg\",\"width\":1245,\"height\":773},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/07\\\/13\\\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/","og_locale":"pt_PT","og_type":"article","og_title":"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia - Loginfo24","og_description":"driveMybox, a plataforma digital de transporte de contentores com sede em Hamburgo, expande-se para o Sudeste da Europa. Ap\u00f3s a Alemanha, It\u00e1lia e Hungria (como hub [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-07-13T15:13:16+00:00","og_image":[{"width":1245,"height":773,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/driveMybox_13.7.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/"},"author":{"name":"","@id":""},"headline":"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia","datePublished":"2025-07-13T15:13:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/"},"wordCount":577,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/driveMybox_13.7.25.jpg","articleSection":["Categories","Regions","Shipping &amp; Ports"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/","url":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/","name":"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/driveMybox_13.7.25.jpg","datePublished":"2025-07-13T15:13:16+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/driveMybox_13.7.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/driveMybox_13.7.25.jpg","width":1245,"height":773},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/07\/13\/drivemybox-a-plataforma-digital-de-transporte-de-contentores-chega-a-grecia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"driveMybox, a plataforma digital de transporte de contentores, chega \u00e0 Gr\u00e9cia"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/69823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=69823"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/69823\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/4767"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=69823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=69823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=69823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}