{"id":69322,"date":"2025-05-28T19:49:21","date_gmt":"2025-05-28T17:49:21","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/"},"modified":"2025-05-28T19:49:21","modified_gmt":"2025-05-28T17:49:21","slug":"g-englmayer-junta-se-a-cargoboard-austria","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/","title":{"rendered":"G. Englmayer junta-se \u00e0 Cargoboard Austria"},"content":{"rendered":"<h5><strong>Cargoboard e a tradicional empresa de transporte austr\u00edaca G. Englmayer unem for\u00e7as: G. Englmayer junta-se \u00e0 Cargoboard Austria a partir de 1 de junho de 2025. O objetivo do acordo \u00e9 expandir de forma direcionada a posi\u00e7\u00e3o de mercado conjunta na \u00c1ustria e aumentar ainda mais a qualidade do servi\u00e7o.<\/strong><\/h5>\n<p>(Paderborn\/Wels) Englmayer traz n\u00e3o apenas d\u00e9cadas de experi\u00eancia, mas tamb\u00e9m uma rede de transporte nacional pr\u00f3pria e uma forte presen\u00e7a no mercado da Europa Oriental, criando assim condi\u00e7\u00f5es ideais para combinar inova\u00e7\u00e3o digital e excel\u00eancia operacional com esta parceria estrat\u00e9gica. A partir do pr\u00f3ximo m\u00eas, todo o neg\u00f3cio da Cargoboard na \u00c1ustria ser\u00e1 gerido pela nova empresa. A gest\u00e3o da Cargoboard Austria ser\u00e1 assumida por Lukas Petrasch, CEO da Cargoboard, Daniel Grobbel, procurador da Cargoboard Austria, e Josef Sch\u00f6llhuber, procurador da G. Englmayer.<\/p>\n<p>A \u00c1ustria ocupa o segundo lugar em termos de receita para a Cargoboard, atr\u00e1s da Rep\u00fablica Federal. A participa\u00e7\u00e3o da G. Englmayer na plataforma de transporte digital demonstra o impacto que modelos de neg\u00f3cios inovadores podem ter na expans\u00e3o de empresas tradicionais estabelecidas. Os parceiros esbo\u00e7am os efeitos de sinergia previstos da seguinte forma: G. Englmayer posiciona-se de forma segura para o futuro no ambiente digital e a Cargoboard assegura qualidade operacional, combinada com for\u00e7a regional.<\/p>\n<h5><strong>Alian\u00e7a estrat\u00e9gica para o mercado austr\u00edaco<\/strong><\/h5>\n<p>&#8220;Fundamos a Cargoboard Austria de forma consciente e antecipada para criar uma base s\u00f3lida para uma parceria forte. Com a G. Englmayer, temos exatamente o parceiro certo ao nosso lado para expandir nossa posi\u00e7\u00e3o de mercado de forma sustent\u00e1vel&#8221;, diz Lukas Petrasch.<\/p>\n<p>Josef Sch\u00f6llhuber tamb\u00e9m v\u00ea um grande potencial: &#8220;A Cargoboard traz sua plataforma digital, que mudar\u00e1 de forma sustent\u00e1vel o mercado de transporte. N\u00f3s trazemos o conhecimento do mercado local e a excel\u00eancia operacional. Assim, surge uma situa\u00e7\u00e3o de ganha-ganha.&#8221;<\/p>\n<p>Desde a sua funda\u00e7\u00e3o na Alemanha, a Cargoboard tem mostrado com sucesso como a digitaliza\u00e7\u00e3o funciona na log\u00edstica: uma plataforma intuitiva, processos enxutos e parceiros fortes como a rede Cargoline. Este conceito vi\u00e1vel ser\u00e1 agora adaptado de forma adequada para a \u00c1ustria.<\/p>\n<h5><strong>Oferta de transporte visivelmente melhorada<\/strong><\/h5>\n<p>A gest\u00e3o atrav\u00e9s de uma empresa austr\u00edaca simplifica os processos, proporciona caminhos mais curtos e traz clareza legal. Ao mesmo tempo, a oferta de transporte para o pa\u00eds alpino \u2013 seja na importa\u00e7\u00e3o ou na exporta\u00e7\u00e3o \u2013 \u00e9 visivelmente melhorada. Gra\u00e7as \u00e0 estreita interliga\u00e7\u00e3o entre a plataforma digital e a compet\u00eancia log\u00edstica local, os clientes beneficiam de prazos de entrega r\u00e1pidos e processos mais suaves no transporte de mercadorias.<\/p>\n<p>Foto: \u00a9 G. Englmayer \/ <strong><em>Legenda da imagem<\/em><\/strong><em> (da esq. para a dir.): Andreas Gaber (CEO da G. Englmayer), Mag. Klaus K\u00f6glberger (membro do conselho da funda\u00e7\u00e3o), Mag. Alexander P\u00f6ttinger (CFO da G. Englmayer), Robert Breitwieser (COO da G. Englmayer), Daniel Grobbel (procurador da Cargoboard Austria), Dr. Gernot Fellner (not\u00e1rio e membro do conselho da funda\u00e7\u00e3o), Lukas Petrasch<\/em> (CEO da Cargoboard) e Josef Sch\u00f6llhuber (procurador da G. Englmayer)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cargoboard e a tradicional empresa de transporte austr\u00edaca G. Englmayer unem for\u00e7as: G. Englmayer junta-se \u00e0 Cargoboard Austria a partir de 1 de junho de 2025.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4951,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561],"tags":[],"class_list":["post-69322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>G. Englmayer junta-se \u00e0 Cargoboard Austria - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"G. Englmayer junta-se \u00e0 Cargoboard Austria - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Cargoboard e a tradicional empresa de transporte austr\u00edaca G. Englmayer unem for\u00e7as: G. Englmayer junta-se \u00e0 Cargoboard Austria a partir de 1 de junho de 2025. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-28T17:49:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"2110\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"G. Englmayer junta-se \u00e0 Cargoboard Austria\",\"datePublished\":\"2025-05-28T17:49:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/\"},\"wordCount\":535,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"articleSection\":[\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/\",\"name\":\"G. Englmayer junta-se \u00e0 Cargoboard Austria - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"datePublished\":\"2025-05-28T17:49:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargoboard_28.5.25-scaled-1.jpg\",\"width\":2560,\"height\":2110},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/05\\\/28\\\/g-englmayer-junta-se-a-cargoboard-austria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"G. Englmayer junta-se \u00e0 Cargoboard Austria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"G. Englmayer junta-se \u00e0 Cargoboard Austria - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/","og_locale":"pt_PT","og_type":"article","og_title":"G. Englmayer junta-se \u00e0 Cargoboard Austria - Loginfo24","og_description":"Cargoboard e a tradicional empresa de transporte austr\u00edaca G. Englmayer unem for\u00e7as: G. Englmayer junta-se \u00e0 Cargoboard Austria a partir de 1 de junho de 2025. [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-05-28T17:49:21+00:00","og_image":[{"width":2560,"height":2110,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/"},"author":{"name":"","@id":""},"headline":"G. Englmayer junta-se \u00e0 Cargoboard Austria","datePublished":"2025-05-28T17:49:21+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/"},"wordCount":535,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","articleSection":["Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/","url":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/","name":"G. Englmayer junta-se \u00e0 Cargoboard Austria - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","datePublished":"2025-05-28T17:49:21+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargoboard_28.5.25-scaled-1.jpg","width":2560,"height":2110},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/05\/28\/g-englmayer-junta-se-a-cargoboard-austria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"G. Englmayer junta-se \u00e0 Cargoboard Austria"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/69322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=69322"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/69322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/4951"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=69322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=69322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=69322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}