{"id":68927,"date":"2025-04-27T11:58:20","date_gmt":"2025-04-27T09:58:20","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/"},"modified":"2025-04-27T11:58:20","modified_gmt":"2025-04-27T09:58:20","slug":"webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/","title":{"rendered":"Webfleet torna frotas ainda mais seguras com o Video 2.0"},"content":{"rendered":"<h5><strong>Com o Webfleet Video 2.0, a Webfleet, a solu\u00e7\u00e3o de gest\u00e3o de frotas comprovada mundialmente da Bridgestone, lan\u00e7a uma solu\u00e7\u00e3o avan\u00e7ada suportada por IA no mercado. O objetivo \u00e9 tornar as frotas mais seguras e melhorar a conformidade com as regulamenta\u00e7\u00f5es locais, bem como a efici\u00eancia operacional atrav\u00e9s de insights em v\u00eddeo em tempo real.<\/strong><\/h5>\n<p>\u00ad(Leipzig) A solu\u00e7\u00e3o aprimorada baseia-se no sucesso do Webfleet Video e introduz duas novas c\u00e2maras de \u00faltima gera\u00e7\u00e3o \u2013 CAM Lite e CAM Pro. Estas analisam, com a ajuda de IA e vis\u00e3o computacional, o comportamento de condu\u00e7\u00e3o, o estado das estradas e poss\u00edveis perigos de forma ainda mais precisa. O sistema \u00e9 complementado por um extenso portf\u00f3lio de c\u00e2maras adicionais e acess\u00f3rios para atender a todas as necessidades dos clientes e casos de uso espec\u00edficos. O sistema aprimorado integra seguran\u00e7a, conformidade e gest\u00e3o de seguros numa \u00fanica plataforma abrangente. Ele reconhece e alerta os motoristas sobre muitos riscos potenciais, incluindo o uso de telem\u00f3veis ao volante, aproxima\u00e7\u00e3o excessiva ou fadiga do condutor, bem como comportamentos arriscados de outros participantes do tr\u00e2nsito. O feedback em tempo real, impulsionado por IA, ajuda os motoristas a reagir de forma adequada imediatamente.<\/p>\n<h5>Monitorizar o comportamento de condu\u00e7\u00e3o ao longo do tempo<\/h5>\n<p>Os gestores de frotas obt\u00eam com o Webfleet Video 2.0 insights precisos e baseados em dados, gra\u00e7as \u00e0 integra\u00e7\u00e3o do Webfleet OptiDrive 360, e podem monitorizar e melhorar o comportamento de condu\u00e7\u00e3o ao longo do tempo. C\u00e2maras adicionais capturam especificamente o ambiente do ve\u00edculo e protegem bens sens\u00edveis. Em caso de incidentes, as grava\u00e7\u00f5es de v\u00eddeo s\u00e3o automaticamente armazenadas e carregadas na nuvem \u2013 uma vantagem na investiga\u00e7\u00e3o de acidentes, para acelerar reclama\u00e7\u00f5es de seguros e prevenir tentativas de fraude.<\/p>\n<p>\u201cCom o Webfleet Video 2.0, estabelecemos um novo padr\u00e3o para a seguran\u00e7a e prote\u00e7\u00e3o de frotas de ve\u00edculos\u201d, diz Jan-Maarten de Vries, Presidente de Solu\u00e7\u00f5es de Gest\u00e3o de Frotas da Bridgestone. \u201cCom monitoriza\u00e7\u00e3o suportada por IA e an\u00e1lise de v\u00eddeo em tempo real, apoiamos as frotas a identificar riscos precocemente, aliviar a carga dos motoristas e proteger melhor os ve\u00edculos e as cargas. A nossa nova solu\u00e7\u00e3o oferece mais transpar\u00eancia e controlo e ajuda as frotas a tomar decis\u00f5es mais inteligentes e baseadas em dados, que melhoram tanto a seguran\u00e7a quanto a efici\u00eancia.\u201d<\/p>\n<h5>A conformidade com o RGPD \u00e9 garantida<\/h5>\n<p>Para garantir que as diretrizes de prote\u00e7\u00e3o de dados, como o RGPD, sejam cumpridas de forma fi\u00e1vel, os gestores de frotas mant\u00eam o controlo na plataforma Webfleet a qualquer momento \u2013 desde as configura\u00e7\u00f5es da c\u00e2mara at\u00e9 ao armazenamento de dados, criptografia e direitos de acesso. Se necess\u00e1rio, capas de lente opcionais proporcionam prote\u00e7\u00e3o adicional da privacidade \u2013 mesmo em opera\u00e7\u00f5es internacionais. O Webfleet Video 2.0 ser\u00e1 lan\u00e7ado inicialmente na UE, com outras regi\u00f5es a seguir. Com fun\u00e7\u00f5es de seguran\u00e7a suportadas por IA, efic\u00e1cia de prote\u00e7\u00e3o melhorada, conformidade com regulamenta\u00e7\u00f5es e vantagens de custo, a Webfleet continua a liderar inova\u00e7\u00f5es na gest\u00e3o de frotas.<\/p>\n<p>Foto: \u00a9 Webfleet<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com o Webfleet Video 2.0, a Webfleet, a solu\u00e7\u00e3o de gest\u00e3o de frotas comprovada mundialmente da Bridgestone, lan\u00e7a uma solu\u00e7\u00e3o avan\u00e7ada suportada por IA no mercado.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5098,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-68927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Webfleet torna frotas ainda mais seguras com o Video 2.0 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Webfleet torna frotas ainda mais seguras com o Video 2.0 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Com o Webfleet Video 2.0, a Webfleet, a solu\u00e7\u00e3o de gest\u00e3o de frotas comprovada mundialmente da Bridgestone, lan\u00e7a uma solu\u00e7\u00e3o avan\u00e7ada suportada por IA no mercado. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-27T09:58:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Webfleet_27.4.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1228\" \/>\n\t<meta property=\"og:image:height\" content=\"747\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Webfleet torna frotas ainda mais seguras com o Video 2.0\",\"datePublished\":\"2025-04-27T09:58:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/\"},\"wordCount\":554,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Webfleet_27.4.25.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/\",\"name\":\"Webfleet torna frotas ainda mais seguras com o Video 2.0 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Webfleet_27.4.25.jpg\",\"datePublished\":\"2025-04-27T09:58:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Webfleet_27.4.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Webfleet_27.4.25.jpg\",\"width\":1228,\"height\":747},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2025\\\/04\\\/27\\\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Webfleet torna frotas ainda mais seguras com o Video 2.0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Webfleet torna frotas ainda mais seguras com o Video 2.0 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/","og_locale":"pt_PT","og_type":"article","og_title":"Webfleet torna frotas ainda mais seguras com o Video 2.0 - Loginfo24","og_description":"Com o Webfleet Video 2.0, a Webfleet, a solu\u00e7\u00e3o de gest\u00e3o de frotas comprovada mundialmente da Bridgestone, lan\u00e7a uma solu\u00e7\u00e3o avan\u00e7ada suportada por IA no mercado. [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-04-27T09:58:20+00:00","og_image":[{"width":1228,"height":747,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Webfleet_27.4.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/"},"author":{"name":"","@id":""},"headline":"Webfleet torna frotas ainda mais seguras com o Video 2.0","datePublished":"2025-04-27T09:58:20+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/"},"wordCount":554,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Webfleet_27.4.25.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/","url":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/","name":"Webfleet torna frotas ainda mais seguras com o Video 2.0 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Webfleet_27.4.25.jpg","datePublished":"2025-04-27T09:58:20+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Webfleet_27.4.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Webfleet_27.4.25.jpg","width":1228,"height":747},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2025\/04\/27\/webfleet-torna-frotas-ainda-mais-seguras-com-o-video-2-0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Webfleet torna frotas ainda mais seguras com o Video 2.0"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/68927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=68927"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/68927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/5098"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=68927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=68927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=68927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}