{"id":67022,"date":"2024-10-29T18:14:07","date_gmt":"2024-10-29T17:14:07","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/"},"modified":"2024-10-29T18:14:07","modified_gmt":"2024-10-29T17:14:07","slug":"cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/","title":{"rendered":"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos"},"content":{"rendered":"<h5><strong>As empresas parceiras do cons\u00f3rcio de transporte Cargo24, juntamente com a empresa de software Eponet AG, est\u00e3o construindo a primeira infraestrutura de carregamento abrangente para caminh\u00f5es el\u00e9tricos (eLKW) em toda a Su\u00ed\u00e7a. Um marco para o desenvolvimento sustent\u00e1vel da ind\u00fastria log\u00edstica.<\/strong><\/h5>\n<p>(Schafisheim, Romanshorn) Na busca por mais sustentabilidade e uma redu\u00e7\u00e3o significativa das emiss\u00f5es de CO2, a mobilidade el\u00e9trica est\u00e1 se tornando cada vez mais valorizada na ind\u00fastria de log\u00edstica de transporte da Su\u00ed\u00e7a. Caminh\u00f5es el\u00e9tricos (eLKW) eram muito raros nas estradas su\u00ed\u00e7as at\u00e9 agora. Isso deve mudar no futuro. A Cargo24, uma empresa l\u00edder na \u00e1rea de log\u00edstica e transporte, juntamente com suas 20 empresas parceiras, decidiu construir e compartilhar a primeira infraestrutura de carregamento abrangente em toda a Su\u00ed\u00e7a. Todas as empresas parceiras se comprometeram a instalar pelo menos uma esta\u00e7\u00e3o de carregamento para eLKW em suas respectivas localiza\u00e7\u00f5es at\u00e9, no m\u00e1ximo, 2027.<\/p>\n<p>Para amortizar rapidamente os altos investimentos atuais em eLKW e na infraestrutura de carregamento correspondente, as empresas parceiras disponibilizam a infraestrutura de carregamento entre si em condi\u00e7\u00f5es vantajosas. Toda a infraestrutura de carregamento de todas as empresas de log\u00edstica \u00e9 controlada pelo mesmo software, garantindo um processamento e faturamento eficientes de todas as opera\u00e7\u00f5es de carregamento das empresas parceiras. Ap\u00f3s uma intensa fase de avalia\u00e7\u00e3o, a Cargo24 decidiu utilizar a solu\u00e7\u00e3o da empresa de software Eponet AG em Romanshorn para o gerenciamento de todas as esta\u00e7\u00f5es de carregamento.<\/p>\n<h5>Opera\u00e7\u00f5es de carregamento s\u00e3o iniciadas por cart\u00f5es RFID<\/h5>\n<p>Concretamente, a Eponet fornece a todos os transportadores log\u00edsticos envolvidos seus pr\u00f3prios cart\u00f5es RFID, com os quais as opera\u00e7\u00f5es de carregamento podem ser iniciadas, principalmente nas pr\u00f3prias esta\u00e7\u00f5es, mas tamb\u00e9m nas esta\u00e7\u00f5es de carregamento de todas as empresas parceiras. Esses cart\u00f5es RFID s\u00e3o registrados no portal da Eponet e podem ser facilmente e convenientemente desbloqueados para as respectivas esta\u00e7\u00f5es de carregamento no cons\u00f3rcio. As empresas parceiras estabelecem entre si as condi\u00e7\u00f5es para o uso da infraestrutura de carregamento, criando assim a base para um compartilhamento abrangente de esta\u00e7\u00f5es de carregamento. A Eponet registra todas as opera\u00e7\u00f5es de carregamento em seu portal e liquida as transa\u00e7\u00f5es m\u00fatuas de forma simples e transparente.<\/p>\n<p>A infraestrutura de carregamento tamb\u00e9m estar\u00e1 dispon\u00edvel no futuro para empresas de transporte selecionadas na Su\u00ed\u00e7a e no exterior que n\u00e3o pertencem ao cons\u00f3rcio Cargo24. Gra\u00e7as a essa rede de carregamento abrangente, a log\u00edstica de transporte su\u00ed\u00e7a assume um papel pioneiro neste setor para a Europa Central.<\/p>\n<p>Robert Einstein, CEO da Cargo24: \u201cEstamos felizes em receber a Eponet como parceira de software para o compartilhamento de esta\u00e7\u00f5es de carregamento em nosso cons\u00f3rcio. Suas solu\u00e7\u00f5es inovadoras, seu entusiasmo pela mobilidade el\u00e9trica e sua expertise nos convenceram. A Eponet se encaixa perfeitamente em nossos objetivos de sustentabilidade, pois queremos operar nossa distribui\u00e7\u00e3o de forma mais ecol\u00f3gica a m\u00e9dio prazo.\u201d<\/p>\n<h5>Marco importante<\/h5>\n<p>Daniel Hofer, CEO da Eponet: \u201cA parceria com a Cargo24 \u00e9 um marco importante para nossa empresa. Estamos muito orgulhosos de termos conseguido convencer a Cargo24 das capacidades do nosso software e do nosso portal e estamos ansiosos para contribuir com nosso know-how para o futuro sustent\u00e1vel da ind\u00fastria de transporte.\u201d<\/p>\n<p>Foto: \u00a9 Cargo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As empresas parceiras do cons\u00f3rcio de transporte Cargo24, juntamente com a empresa de software Eponet AG, est\u00e3o construindo a primeira infraestrutura de carregamento abrangente para caminh\u00f5es<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5816,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-67022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"As empresas parceiras do cons\u00f3rcio de transporte Cargo24, juntamente com a empresa de software Eponet AG, est\u00e3o construindo a primeira infraestrutura de carregamento abrangente para caminh\u00f5es [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-29T17:14:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargo24_29.10.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1406\" \/>\n\t<meta property=\"og:image:height\" content=\"780\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos\",\"datePublished\":\"2024-10-29T17:14:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/\"},\"wordCount\":594,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargo24_29.10.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/\",\"name\":\"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargo24_29.10.24.jpg\",\"datePublished\":\"2024-10-29T17:14:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargo24_29.10.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Cargo24_29.10.24.jpg\",\"width\":1406,\"height\":780},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/10\\\/29\\\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/","og_locale":"pt_PT","og_type":"article","og_title":"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos - Loginfo24","og_description":"As empresas parceiras do cons\u00f3rcio de transporte Cargo24, juntamente com a empresa de software Eponet AG, est\u00e3o construindo a primeira infraestrutura de carregamento abrangente para caminh\u00f5es [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-10-29T17:14:07+00:00","og_image":[{"width":1406,"height":780,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargo24_29.10.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/"},"author":{"name":"","@id":""},"headline":"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos","datePublished":"2024-10-29T17:14:07+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/"},"wordCount":594,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargo24_29.10.24.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/","url":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/","name":"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargo24_29.10.24.jpg","datePublished":"2024-10-29T17:14:07+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargo24_29.10.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Cargo24_29.10.24.jpg","width":1406,"height":780},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/10\/29\/cargo24-e-eponet-com-infraestrutura-de-carregamento-em-toda-a-suica-para-caminhoes-eletricos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Cargo24 e Eponet com infraestrutura de carregamento em toda a Su\u00ed\u00e7a para caminh\u00f5es el\u00e9tricos"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/67022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=67022"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/67022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/5816"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=67022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=67022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=67022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}