{"id":65575,"date":"2024-06-11T18:04:00","date_gmt":"2024-06-11T16:04:00","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/"},"modified":"2024-06-11T18:04:00","modified_gmt":"2024-06-11T16:04:00","slug":"zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/","title":{"rendered":"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul"},"content":{"rendered":"<h5><strong>GUD Filters, marca l\u00edder em filtros automotivos na \u00c1frica do Sul desde 1949, <\/strong><strong>otimiza seus processos de armaz\u00e9m com <\/strong><strong>ZetesMedea Full Pallet Inventory<\/strong><strong>. Esta solu\u00e7\u00e3o inovadora aproveita as vantagens da tecnologia de vis\u00e3o computacional e permite otimizar os estoques e aumentar a efici\u00eancia nos centros de distribui\u00e7\u00e3o.<\/strong><\/h5>\n<p>(Wien\/Johannesburg) No contexto do aumento da excel\u00eancia operacional, a GUD Filters estava em busca de uma solu\u00e7\u00e3o para otimizar seus processos de gest\u00e3o de estoque. O desafio de manter os estoques com precis\u00e3o em meio \u00e0 distribui\u00e7\u00e3o de uma ampla gama de produtos levou a empresa a procurar uma solu\u00e7\u00e3o que pudesse aumentar a efici\u00eancia sem comprometer o atendimento ao cliente. Por isso, foi introduzida uma abordagem mais avan\u00e7ada para evitar as desvantagens das contagens de estoque constantes e trabalhosas. &#8220;A interrup\u00e7\u00e3o semestral para invent\u00e1rios precisos mostrou claramente que uma mudan\u00e7a era imprescind\u00edvel para melhorar a efici\u00eancia de nossas opera\u00e7\u00f5es e a presta\u00e7\u00e3o de nossos servi\u00e7os. O desafio estava em encontrar uma solu\u00e7\u00e3o que nos permitisse maximizar nosso espa\u00e7o nos corredores estreitos&#8221;, afirma James Naidoo, chefe do departamento de TI da GUD Filters.<\/p>\n<p><strong>Inova\u00e7\u00e3o e efici\u00eancia<\/strong><\/p>\n<p>Para enfrentar esses desafios, a GUD Filters decidiu implementar o ZetesMedea. Na solu\u00e7\u00e3o, uma esta\u00e7\u00e3o ImageID \u00e9 instalada em um empilhador. Esta esta\u00e7\u00e3o captura dados e automatiza a contagem de estoques de paletes, permitindo uma coleta de dados r\u00e1pida e precisa. &#8220;Nossa decis\u00e3o por ZetesMedea baseou-se no hist\u00f3rico de sucesso da Zetes, na robustez de sua tecnologia e em nosso compromisso m\u00fatuo com a excel\u00eancia operacional&#8221;, complementa Naidoo.<\/p>\n<p>Foto: \u00a9 Zetes<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GUD Filters, marca l\u00edder em filtros automotivos na \u00c1frica do Sul desde 1949, otimiza seus processos de armaz\u00e9m com ZetesMedea Full Pallet Inventory. Esta solu\u00e7\u00e3o inovadora<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6399,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1560,1561],"tags":[],"class_list":["post-65575","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"GUD Filters, marca l\u00edder em filtros automotivos na \u00c1frica do Sul desde 1949, otimiza seus processos de armaz\u00e9m com ZetesMedea Full Pallet Inventory. Esta solu\u00e7\u00e3o inovadora [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T16:04:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zetes_11.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1239\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul\",\"datePublished\":\"2024-06-11T16:04:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/\"},\"wordCount\":297,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zetes_11.6.24.jpg\",\"articleSection\":[\"Categories\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/\",\"name\":\"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zetes_11.6.24.jpg\",\"datePublished\":\"2024-06-11T16:04:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zetes_11.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Zetes_11.6.24.jpg\",\"width\":1239,\"height\":725},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/11\\\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/","og_locale":"pt_PT","og_type":"article","og_title":"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul - Loginfo24","og_description":"GUD Filters, marca l\u00edder em filtros automotivos na \u00c1frica do Sul desde 1949, otimiza seus processos de armaz\u00e9m com ZetesMedea Full Pallet Inventory. Esta solu\u00e7\u00e3o inovadora [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-11T16:04:00+00:00","og_image":[{"width":1239,"height":725,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zetes_11.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/"},"author":{"name":"","@id":""},"headline":"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul","datePublished":"2024-06-11T16:04:00+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/"},"wordCount":297,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zetes_11.6.24.jpg","articleSection":["Categories","Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/","url":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/","name":"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zetes_11.6.24.jpg","datePublished":"2024-06-11T16:04:00+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zetes_11.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Zetes_11.6.24.jpg","width":1239,"height":725},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/11\/zetesmedea-otimiza-processos-de-armazem-na-gud-na-africa-do-sul\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"ZetesMedea otimiza processos de armaz\u00e9m na GUD na \u00c1frica do Sul"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/65575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=65575"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/65575\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/6399"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=65575"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=65575"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=65575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}