{"id":65533,"date":"2024-06-06T13:09:28","date_gmt":"2024-06-06T11:09:28","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/"},"modified":"2024-06-06T13:09:28","modified_gmt":"2024-06-06T11:09:28","slug":"trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/","title":{"rendered":"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach"},"content":{"rendered":"<h5>O servi\u00e7o expresso trans-o-flex, especializado em medicamentos e outros bens sens\u00edveis como cosm\u00e9ticos ou eletr\u00f4nicos, est\u00e1 a construir um novo local em Steinach, na Baviera. Ontem, em Steinach, localizado diretamente na A3 entre Regensburg e Deggendorf, a trans-o-flex celebrou a festa da constru\u00e7\u00e3o de um novo centro log\u00edstico.<\/h5>\n<p>\u201cCom o novo centro de distribui\u00e7\u00e3o, n\u00e3o apenas aumentamos nossa capacidade, mas tamb\u00e9m podemos criar mais sinergias entre nossas duas redes\u201d, disse o CEO da trans-o-flex, Martin Reder, durante a festa da constru\u00e7\u00e3o. \u201cAtualmente, nesta regi\u00e3o, existem um local da trans-o-flex Express e um da trans-o-flex ThermoMed. No futuro, ambas as redes operar\u00e3o sob um mesmo teto.\u201d Para isso, ser\u00e1 constru\u00edda uma sala de distribui\u00e7\u00e3o completamente climatizada em um terreno de 33.360 metros quadrados. A \u00e1rea maior \u00e9 destinada \u00e0 distribui\u00e7\u00e3o de produtos em temperatura ambiente entre 15 e 25 graus Celsius, enquanto uma \u00e1rea menor \u00e9 destinada a produtos refrigerados, que ser\u00e3o manuseados e transportados pela trans-o-flex ThermoMed entre 2 e 8 graus. A entrada em opera\u00e7\u00e3o est\u00e1 prevista para maio de 2025.<\/p>\n<h5>Capacidade para 4.200 pacotes por hora<\/h5>\n<p>A partir de Steinach, a trans-o-flex pretende entregar e recolher mercadorias entre Regensburg e Passau, bem como de Landshut at\u00e9 as fronteiras com a \u00c1ustria e a Rep\u00fablica Checa. As mercadorias ser\u00e3o classificadas em uma linha de transporte autom\u00e1tica, projetada para at\u00e9 4.200 pacotes por hora. A sala de distribui\u00e7\u00e3o ter\u00e1 29 port\u00f5es para caminh\u00f5es e 79 port\u00f5es para carga e descarga de furg\u00f5es.<\/p>\n<p>\u201cUma diferen\u00e7a essencial em rela\u00e7\u00e3o aos centros de triagem convencionais \u00e9 a sustentabilidade da instala\u00e7\u00e3o\u201d, explicou Reder. \u201cNo telhado, ser\u00e3o instalados pain\u00e9is solares e a eletricidade produzida ser\u00e1 utilizada na pr\u00f3pria sala, alimentando a bomba de calor para aquecimento ou sendo direcionada para pontos de carregamento para os ve\u00edculos el\u00e9tricos dos nossos funcion\u00e1rios.\u201d Conex\u00f5es para o futuro carregamento de caminh\u00f5es el\u00e9tricos e furg\u00f5es el\u00e9tricos est\u00e3o sendo preparadas. \u201cO centro de triagem possui um forte isolamento t\u00e9rmico devido \u00e0 sua climatiza\u00e7\u00e3o ativa, as luzes LED proporcionam muita ilumina\u00e7\u00e3o com pouco consumo de energia e toda a \u00e1gua da chuva que cai nos telhados e \u00e1reas impermeabilizadas do terreno ser\u00e1 captada e controlada para infiltra\u00e7\u00e3o.\u201d Por \u00faltimo, mas n\u00e3o menos importante, paredes de prote\u00e7\u00e3o ac\u00fastica ser\u00e3o erguidas ao redor do terreno, que ser\u00e3o completamente cobertas de vegeta\u00e7\u00e3o. Para que o sistema de climatiza\u00e7\u00e3o da sala seja utilizado o m\u00ednimo poss\u00edvel, ele ser\u00e1 operado em combina\u00e7\u00e3o com um resfriamento livre. Somente quando a temperatura desejada na sala n\u00e3o puder mais ser alcan\u00e7ada atrav\u00e9s da circula\u00e7\u00e3o de ar por grelhas de entrada de ar e ventiladores de exaust\u00e3o, o ar condicionado precisar\u00e1 ser acionado. Assim, mesmo com um consumo de energia minimizado, a climatiza\u00e7\u00e3o necess\u00e1ria para a seguran\u00e7a dos bens sens\u00edveis transportados ser\u00e1 garantida a todo momento.<\/p>\n<h5>A comunidade de Steinach celebra a cria\u00e7\u00e3o de 100 novos postos de trabalho<\/h5>\n<p>A sustentabilidade especial do centro log\u00edstico tamb\u00e9m foi destacada durante a festa da constru\u00e7\u00e3o pela Christine Hammerschick, primeira prefeita da comunidade de Steinach: \u201cA trans-o-flex demonstra aqui como a frequentemente criticada ind\u00fastria de transporte pode prestar seus servi\u00e7os de forma ecol\u00f3gica, garantindo assim a provis\u00e3o da nossa popula\u00e7\u00e3o com medicamentos importantes de forma duradoura. O fato de que isso est\u00e1 associado a mais de 100 postos de trabalho na nossa regi\u00e3o \u00e9 algo que eu, como prefeita, s\u00f3 posso saudar.\u201d<\/p>\n<p>Foto: \u00a9 trans-o-flex \/ <em><strong>Legenda da imagem<\/strong> (da esquerda para a direita): Christine Hammerschick, primeira prefeita de Steinach, Hans-Peter Flei\u00dfner, supervis\u00e3o da constru\u00e7\u00e3o, Martin Reder, CEO da trans-o-flex Express, Dietmar Nunne, s\u00f3cio-gerente da K\u00f6gel &amp; Nunne Bau GmbH e Maik Linnem\u00fcller, gerente de projeto na K\u00f6gel &amp; Nunne Bau GmbH<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O servi\u00e7o expresso trans-o-flex, especializado em medicamentos e outros bens sens\u00edveis como cosm\u00e9ticos ou eletr\u00f4nicos, est\u00e1 a construir um novo local em Steinach, na Baviera. Ontem,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6417,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-65533","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"O servi\u00e7o expresso trans-o-flex, especializado em medicamentos e outros bens sens\u00edveis como cosm\u00e9ticos ou eletr\u00f4nicos, est\u00e1 a construir um novo local em Steinach, na Baviera. Ontem, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T11:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_6.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1369\" \/>\n\t<meta property=\"og:image:height\" content=\"774\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach\",\"datePublished\":\"2024-06-06T11:09:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/\"},\"wordCount\":671,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_6.6.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/\",\"name\":\"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_6.6.24.jpg\",\"datePublished\":\"2024-06-06T11:09:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_6.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/trans-o-flex_6.6.24.jpg\",\"width\":1369,\"height\":774},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/06\\\/06\\\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/","og_locale":"pt_PT","og_type":"article","og_title":"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach - Loginfo24","og_description":"O servi\u00e7o expresso trans-o-flex, especializado em medicamentos e outros bens sens\u00edveis como cosm\u00e9ticos ou eletr\u00f4nicos, est\u00e1 a construir um novo local em Steinach, na Baviera. Ontem, [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-06T11:09:28+00:00","og_image":[{"width":1369,"height":774,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_6.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/"},"author":{"name":"","@id":""},"headline":"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach","datePublished":"2024-06-06T11:09:28+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/"},"wordCount":671,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_6.6.24.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/","url":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/","name":"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_6.6.24.jpg","datePublished":"2024-06-06T11:09:28+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_6.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/trans-o-flex_6.6.24.jpg","width":1369,"height":774},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/06\/06\/trans-o-flex-celebra-a-festa-da-construcao-do-centro-logistico-em-steinach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"trans-o-flex celebra a festa da constru\u00e7\u00e3o do centro log\u00edstico em Steinach"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/65533","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=65533"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/65533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/6417"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=65533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=65533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=65533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}