{"id":65309,"date":"2024-05-21T19:09:53","date_gmt":"2024-05-21T17:09:53","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/"},"modified":"2024-05-21T19:09:53","modified_gmt":"2024-05-21T17:09:53","slug":"db-schenker-transporta-920-quilometros-de-cabos-do-japao","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/","title":{"rendered":"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o"},"content":{"rendered":"<h5><strong>Cerca de 920.000 metros de cabos e aproximadamente 43.000 toneladas de peso total: os especialistas em log\u00edstica de projeto da DB Schenker est\u00e3o atualmente a lidar com um dos projetos log\u00edsticos mais abrangentes para a transi\u00e7\u00e3o energ\u00e9tica. Num conceito de transporte multimodal integrado para o fabricante Sumitomo Electric Industries Ltd., um total de 876 bobinas de cabos est\u00e3o a ser transportadas de Kobe, no Jap\u00e3o, e de Mannheim para os tr\u00eas locais de Emden, Wesel e Krefeld.<\/strong><\/h5>\n<p>(Essen\/Mannheim) L\u00e1, ser\u00e3o armazenadas at\u00e9 serem requisitadas pela gest\u00e3o do projeto. As bobinas de cabos ser\u00e3o instaladas no chamado Corredor A-Norte do operador da rede de transmiss\u00e3o Amprion numa nova linha de eletricidade. Assim, a utiliza\u00e7\u00e3o da energia e\u00f3lica do Mar do Norte ser\u00e1 poss\u00edvel em \u00e1reas urbanas no oeste da Alemanha.<\/p>\n<p>Thorsten Meincke, membro do conselho para carga a\u00e9rea e mar\u00edtima da DB Schenker: &#8220;Como l\u00edder mundial em log\u00edstica de projeto, a DB Schenker oferece aos seus clientes solu\u00e7\u00f5es \u00f3timas de ponta a ponta de uma \u00fanica fonte. Temos uma vasta experi\u00eancia na gest\u00e3o de projetos complexos em termos geogr\u00e1ficos, temporais e de volume. Estamos orgulhosos de que nossas especialistas e especialistas estejam a contribuir para o sucesso da transi\u00e7\u00e3o energ\u00e9tica neste desafio.&#8221; <\/p>\n<p>Daniel Wieland, Vice-Presidente S\u00eanior de Projetos Globais e Solu\u00e7\u00f5es Industriais da DB Schenker: &#8220;Nossa equipe global de especialistas orquestra este extenso grande projeto. Desde a concep\u00e7\u00e3o, planejamento e coordena\u00e7\u00e3o dos transportes multimodais at\u00e9 \u00e0 desalfandegagem, armazenamento e entrega, nosso cliente recebe servi\u00e7os personalizados, seguros e confi\u00e1veis de nossos especialistas em projetos.&#8221;<\/p>\n<p>As bobinas de cabos, que pesam at\u00e9 85 toneladas, t\u00eam um di\u00e2metro de mais de quatro metros e podem ter at\u00e9 oito metros de comprimento. A linha de eletricidade do Corredor A-Norte forma uma art\u00e9ria principal da transi\u00e7\u00e3o energ\u00e9tica e transporta energia e\u00f3lica do norte para as \u00e1reas urbanas da Ren\u00e2nia do Norte-Vestf\u00e1lia.<\/p>\n<p>A partir do local de produ\u00e7\u00e3o no Jap\u00e3o, a DB Schenker transporta as bobinas de cabos por navio de carga do porto de Kobe para Emden ou para os portos ocidentais em Antu\u00e9rpia e Roterd\u00e3o. A partir da\u00ed, os transportes de conex\u00e3o at\u00e9 Krefeld e Wesel s\u00e3o realizados por barco interior. Paralelamente, a DB Schenker traz bobinas de cabos de um segundo local de produ\u00e7\u00e3o em Mannheim tanto por barco interior como por caminh\u00e3o de transporte pesado para os tr\u00eas armaz\u00e9ns intermedi\u00e1rios.<\/p>\n<h5>Conceito de transporte multimodal de uma \u00fanica fonte<\/h5>\n<p>Para o fabricante de cabos, Sumitomo, a DB Schenker oferece assim um conceito de transporte multimodal de uma \u00fanica fonte. Este abrange toda a cadeia de valor log\u00edstica, incluindo a coordena\u00e7\u00e3o de todos os meios de transporte, e inclui o transporte inicial da f\u00e1brica por caminh\u00e3o e barco interior, a movimenta\u00e7\u00e3o portu\u00e1ria, o monitoramento da carga e o fretamento de navios de carga multiprop\u00f3sito, a desalfandegagem, autoriza\u00e7\u00f5es especiais de autoridades, bem como a disponibiliza\u00e7\u00e3o, organiza\u00e7\u00e3o e supervis\u00e3o de armaz\u00e9ns intermedi\u00e1rios com mais de 11.000 metros quadrados em Emden, Wesel e Krefeld. Solu\u00e7\u00f5es de TI espec\u00edficas para o projeto fornecem informa\u00e7\u00f5es atualizadas sobre o progresso total do projeto.<\/p>\n<p>Foto: \u00a9 DB Schenker<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cerca de 920.000 metros de cabos e aproximadamente 43.000 toneladas de peso total: os especialistas em log\u00edstica de projeto da DB Schenker est\u00e3o atualmente a lidar<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6510,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-65309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Cerca de 920.000 metros de cabos e aproximadamente 43.000 toneladas de peso total: os especialistas em log\u00edstica de projeto da DB Schenker est\u00e3o atualmente a lidar [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-21T17:09:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Schenker_21.5.2024.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1254\" \/>\n\t<meta property=\"og:image:height\" content=\"754\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o\",\"datePublished\":\"2024-05-21T17:09:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/\"},\"wordCount\":576,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Schenker_21.5.2024.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/\",\"name\":\"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Schenker_21.5.2024.jpg\",\"datePublished\":\"2024-05-21T17:09:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Schenker_21.5.2024.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DB_Schenker_21.5.2024.jpg\",\"width\":1254,\"height\":754},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/05\\\/21\\\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/","og_locale":"pt_PT","og_type":"article","og_title":"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o - Loginfo24","og_description":"Cerca de 920.000 metros de cabos e aproximadamente 43.000 toneladas de peso total: os especialistas em log\u00edstica de projeto da DB Schenker est\u00e3o atualmente a lidar [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-05-21T17:09:53+00:00","og_image":[{"width":1254,"height":754,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Schenker_21.5.2024.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/"},"author":{"name":"","@id":""},"headline":"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o","datePublished":"2024-05-21T17:09:53+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/"},"wordCount":576,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Schenker_21.5.2024.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/","url":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/","name":"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Schenker_21.5.2024.jpg","datePublished":"2024-05-21T17:09:53+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Schenker_21.5.2024.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DB_Schenker_21.5.2024.jpg","width":1254,"height":754},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/05\/21\/db-schenker-transporta-920-quilometros-de-cabos-do-japao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"DB Schenker transporta 920 quil\u00f3metros de cabos do Jap\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/65309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=65309"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/65309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/6510"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=65309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=65309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=65309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}