{"id":64943,"date":"2024-04-21T08:42:29","date_gmt":"2024-04-21T06:42:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/"},"modified":"2024-04-21T08:42:29","modified_gmt":"2024-04-21T06:42:29","slug":"dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/","title":{"rendered":"DHL Group expande o programa de ajuda GoHelp para a Europa"},"content":{"rendered":"<h5>Em colabora\u00e7\u00e3o com as Na\u00e7\u00f5es Unidas, a DHL Group disponibiliza desde 2005 a sua experi\u00eancia em log\u00edstica e a sua rede global no \u00e2mbito do programa GoHelp, para apoiar a\u00e7\u00f5es de ajuda em \u00e1reas afetadas por desastres. O grupo log\u00edstico est\u00e1 a expandir as suas atividades e lan\u00e7a o GoHelp Europe. No aeroporto de Istambul, de 19 a 21 de abril de 2024, ter\u00e1 lugar o primeiro treinamento de uma equipe europeia de resposta a desastres (DRT) com 50 participantes.<\/h5>\n<p>(Bonn\/Istambul) O GoHelp est\u00e1 dividido em duas \u00e1reas de atua\u00e7\u00e3o: ajuda em desastres e preven\u00e7\u00e3o de desastres: as DRTs s\u00e3o enviadas a aeroportos em regi\u00f5es afetadas, quando solicitadas pelo Escrit\u00f3rio das Na\u00e7\u00f5es Unidas para a Coordena\u00e7\u00e3o de Assuntos Humanit\u00e1rios. O programa &#8220;Prepare os Aeroportos para Desastres&#8221; prepara o pessoal do aeroporto e as organiza\u00e7\u00f5es locais de prote\u00e7\u00e3o civil para gerenciar a chegada de suprimentos de ajuda.<\/p>\n<div class=\"component-margin c-text-generic has-rte component-small \">\n<div class=\"has-rte\">\n<p class=\"has-rte\">&#8220;A Europa est\u00e1 cada vez mais afetada por crises relacionadas ao clima, como as inunda\u00e7\u00f5es na Alemanha e na B\u00e9lgica em 2021. Al\u00e9m disso, os terr\u00edveis terremotos na Turquia e no Marrocos no ano passado&#8221;, diz Christoph Selig, Vice-Presidente de Comunica\u00e7\u00f5es e Programas de Sustentabilidade da DHL Group. &#8220;Diante desses eventos e ap\u00f3s um sucesso nos \u00faltimos 15 anos na Am\u00e9rica Latina, na regi\u00e3o da \u00c1sia-Pac\u00edfico, no Oriente M\u00e9dio e na \u00c1frica, estamos agora expandindo o programa GoHelp para a Europa. Com nosso compromisso, trazemos nossa compet\u00eancia central em log\u00edstica para apoiar as pessoas afetadas por desastres e disponibilizamos nossa rede global para o bem comum. Assim, garantimos uma ajuda humanit\u00e1ria mais eficiente e melhor coordenada.&#8221; Com o lan\u00e7amento do GoHelp Europe, o programa agora cobre todas as \u00e1reas em risco de desastres em todo o mundo.<\/p>\n<p class=\"has-rte\">As DRTs ajudam a otimizar os processos log\u00edsticos e oferecem apoio r\u00e1pido e gratuito em aeroportos em \u00e1reas de emerg\u00eancia dentro de 72 horas. Na Europa, as opera\u00e7\u00f5es das DRTs podem ir al\u00e9m do apoio nos aeroportos. Volunt\u00e1rios s\u00e3o familiarizados, em m\u00f3dulos te\u00f3ricos e pr\u00e1ticos, com v\u00e1rios aspectos da ajuda em desastres e da gest\u00e3o de desastres. O foco est\u00e1 na otimiza\u00e7\u00e3o dos processos de transporte e nas t\u00e9cnicas para montagem e desmontagem de paletes, especialmente para paletes de carga a\u00e9rea, fechos e redes. Al\u00e9m disso, o treinamento transmite habilidades importantes, como a opera\u00e7\u00e3o de empilhadeiras e uma comunica\u00e7\u00e3o eficaz por r\u00e1dio.<\/p>\n<h5>Confer\u00eancia Global GoHelp em Istambul<\/h5>\n<p class=\"has-rte\">A DHL Group tamb\u00e9m realizar\u00e1 uma confer\u00eancia global GoHelp em Istambul nos dias 22 e 23 de abril. O encontro serve como uma plataforma para a troca entre parceiros internos e externos, bem como para discuss\u00f5es e iniciativas direcionadas no setor humanit\u00e1rio. O p\u00fablico-alvo e os participantes s\u00e3o representantes do programa GoHelp, profissionais internos das divis\u00f5es da DHL, bem como parceiros e colegas das Na\u00e7\u00f5es Unidas e de outras organiza\u00e7\u00f5es. Outro objetivo da confer\u00eancia \u00e9 destacar os sucessos do programa GoHelp, o lan\u00e7amento do GoHelp Europe e o 15\u00ba anivers\u00e1rio do Prepare os Aeroportos para Desastres.<\/p>\n<p>Foto: \u00a9 DHL Group<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Em colabora\u00e7\u00e3o com as Na\u00e7\u00f5es Unidas, a DHL Group disponibiliza desde 2005 a sua experi\u00eancia em log\u00edstica e a sua rede global no \u00e2mbito do programa<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6649,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-64943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHL Group expande o programa de ajuda GoHelp para a Europa - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHL Group expande o programa de ajuda GoHelp para a Europa - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Em colabora\u00e7\u00e3o com as Na\u00e7\u00f5es Unidas, a DHL Group disponibiliza desde 2005 a sua experi\u00eancia em log\u00edstica e a sua rede global no \u00e2mbito do programa [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-21T06:42:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_21.4.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1371\" \/>\n\t<meta property=\"og:image:height\" content=\"837\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DHL Group expande o programa de ajuda GoHelp para a Europa\",\"datePublished\":\"2024-04-21T06:42:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/\"},\"wordCount\":552,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_21.4.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/\",\"name\":\"DHL Group expande o programa de ajuda GoHelp para a Europa - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_21.4.24.jpg\",\"datePublished\":\"2024-04-21T06:42:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_21.4.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DHL_21.4.24.jpg\",\"width\":1371,\"height\":837},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/21\\\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DHL Group expande o programa de ajuda GoHelp para a Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHL Group expande o programa de ajuda GoHelp para a Europa - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/","og_locale":"pt_PT","og_type":"article","og_title":"DHL Group expande o programa de ajuda GoHelp para a Europa - Loginfo24","og_description":"Em colabora\u00e7\u00e3o com as Na\u00e7\u00f5es Unidas, a DHL Group disponibiliza desde 2005 a sua experi\u00eancia em log\u00edstica e a sua rede global no \u00e2mbito do programa [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-04-21T06:42:29+00:00","og_image":[{"width":1371,"height":837,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_21.4.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/"},"author":{"name":"","@id":""},"headline":"DHL Group expande o programa de ajuda GoHelp para a Europa","datePublished":"2024-04-21T06:42:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/"},"wordCount":552,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_21.4.24.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/","url":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/","name":"DHL Group expande o programa de ajuda GoHelp para a Europa - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_21.4.24.jpg","datePublished":"2024-04-21T06:42:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_21.4.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DHL_21.4.24.jpg","width":1371,"height":837},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/21\/dhl-group-expande-o-programa-de-ajuda-gohelp-para-a-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"DHL Group expande o programa de ajuda GoHelp para a Europa"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/64943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=64943"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/64943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/6649"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=64943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=64943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=64943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}