{"id":64919,"date":"2024-04-18T17:38:08","date_gmt":"2024-04-18T15:38:08","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/"},"modified":"2024-04-18T17:38:08","modified_gmt":"2024-04-18T15:38:08","slug":"hgk-shipping-com-marco-para-a-navegacao-interior-da-europa","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/","title":{"rendered":"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa"},"content":{"rendered":"<h5><strong>Com a constru\u00e7\u00e3o de um novo tipo de navio, a HGK Shipping estabelece mais um marco para a navega\u00e7\u00e3o interior da Europa. O novo projeto, denominado &#8220;Pioneer&#8221;, ser\u00e1 equipado com uma tecnologia inovadora de sistema de tanque e carga. Isso permitir\u00e1 o transporte de gases tanto em forma l\u00edquida a frio quanto em forma l\u00edquida sob press\u00e3o.<\/strong><strong> Em um momento em que o futuro do fornecimento de energia est\u00e1 sendo moldado, o navio estabelece novos padr\u00f5es para o transporte seguro e eficiente do importante portador de energia am\u00f4nia a partir de hidrog\u00eanio &#8220;verde&#8221;. Al\u00e9m disso, o conceito permite o transporte de di\u00f3xido de carbono inevit\u00e1vel.<\/strong><\/h5>\n<p>(K\u00f6ln\/Dusiburg) A HGK Shipping, como l\u00edder do setor, apoia a constru\u00e7\u00e3o desta revolucion\u00e1ria s\u00e9rie de navios nas iniciativas europeias para a descarboniza\u00e7\u00e3o da economia e da sociedade. Com esses modelos, a empresa cria uma oferta de transporte aprimorada para am\u00f4nia l\u00edquida a frio (NH<sub>3<\/sub>) e di\u00f3xido de carbono l\u00edquido (LCO<sub>2<\/sub>) em vias naveg\u00e1veis.<\/p>\n<h5><strong>Alternativas de transporte eficientes<\/strong><\/h5>\n<p>&#8220;Com este tipo de navio inovador, j\u00e1 estamos preparando o caminho para as exig\u00eancias log\u00edsticas de uma navega\u00e7\u00e3o interior sustent\u00e1vel&#8221;, explica Steffen Bauer, CEO da HGK Shipping, sobre os planos da maior empresa de navega\u00e7\u00e3o interior da Europa. &#8220;As quantidades de transporte previstas para hidrog\u00eanio e seus derivados, como am\u00f4nia, mas tamb\u00e9m para di\u00f3xido de carbono l\u00edquido, n\u00e3o poder\u00e3o ser transportadas exclusivamente por dutos. Por isso, queremos oferecer ao mercado alternativas de transporte eficientes atrav\u00e9s da via naveg\u00e1vel.&#8221;<\/p>\n<p>O conceito do navio da HGK Shipping foca nas principais mercadorias de transporte para o sucesso da transi\u00e7\u00e3o energ\u00e9tica em rela\u00e7\u00e3o ao fornecimento e descarte. Atualmente, um g\u00e1s como a am\u00f4nia na navega\u00e7\u00e3o interior s\u00f3 pode ser transportado sob press\u00e3o dos portos para o interior. Com o novo projeto, cuja tecnologia tamb\u00e9m \u00e9 projetada para navios de motor costeiros, isso ocorre em forma l\u00edquida a frio, ou seja, a temperaturas de at\u00e9 menos 33 graus Celsius. Tamb\u00e9m s\u00e3o eliminados processos de transbordo complicados nos portos, que anteriormente estavam associados a um aquecimento intensivo em termos de energia. O tipo de navio foi desenvolvido especificamente para o tr\u00e1fego entre os portos ARA e o interior do Reno. Com dimens\u00f5es de 135 metros de comprimento e 17,5 metros de largura, o novo navio pode transportar significativamente mais volume em compara\u00e7\u00e3o com os atuais navios-tanque de g\u00e1s.<\/p>\n<p>Anke Bestmann, Diretora da Unidade de Neg\u00f3cios de Transporte de G\u00e1s da HGK Shipping, enfatiza: &#8220;Nossa experi\u00eancia de d\u00e9cadas no transporte de gases liquefeitos sob press\u00e3o agora se expande gra\u00e7as \u00e0 nova solu\u00e7\u00e3o, permitindo tamb\u00e9m o transporte em estado l\u00edquido a frio. Isso fortalecer\u00e1 nossa posi\u00e7\u00e3o no mercado da navega\u00e7\u00e3o de navios-tanque de g\u00e1s na Europa.&#8221;<\/p>\n<h5><strong>Transporte de quantidades inevit\u00e1veis de di\u00f3xido de carbono<\/strong><\/h5>\n<p>O conceito prev\u00ea que os novos navios tamb\u00e9m possam transportar as quantidades de di\u00f3xido de carbono inevit\u00e1veis dos locais de produ\u00e7\u00e3o da ind\u00fastria \u2013 em forma l\u00edquida, ou seja, como LCO<sub>2<\/sub>. Em f\u00e1bricas e portos, atualmente est\u00e3o sendo criadas capacidades de transbordo e armazenamento utilizando a metodologia CCS (a sigla significa Captura e Armazenamento de Di\u00f3xido de Carbono) para o armazenamento geol\u00f3gico planejado do di\u00f3xido de carbono em locais adequados, incluindo reservat\u00f3rios de petr\u00f3leo esgotados e dep\u00f3sitos de g\u00e1s natural.<\/p>\n<h5>Resultado de um intenso trabalho de desenvolvimento<\/h5>\n<p>&#8220;O inovador sistema de tanque e carga para este tipo espec\u00edfico de navio \u00e9 o resultado de um intenso trabalho de desenvolvimento em colabora\u00e7\u00e3o com parceiros internacionais da navega\u00e7\u00e3o mar\u00edtima e nosso pr\u00f3prio centro de design&#8221;, diz Tim G\u00f6dde, Diretor da Unidade de Neg\u00f3cios de Gest\u00e3o de Navios da HGK Shipping. &#8220;As inova\u00e7\u00f5es t\u00e9cnicas j\u00e1 utilizadas em constru\u00e7\u00f5es anteriores, como o conceito de propuls\u00e3o diesel-el\u00e9trica e a constru\u00e7\u00e3o para \u00e1guas rasas, tamb\u00e9m ser\u00e3o integradas no novo modelo.&#8221;<\/p>\n<p>Foto: \u00a9 HGK Shipping<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com a constru\u00e7\u00e3o de um novo tipo de navio, a HGK Shipping estabelece mais um marco para a navega\u00e7\u00e3o interior da Europa. O novo projeto, denominado<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561,1559],"tags":[],"class_list":["post-64919","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Com a constru\u00e7\u00e3o de um novo tipo de navio, a HGK Shipping estabelece mais um marco para a navega\u00e7\u00e3o interior da Europa. O novo projeto, denominado [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-18T15:38:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HGK_18.4.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1666\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa\",\"datePublished\":\"2024-04-18T15:38:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/\"},\"wordCount\":716,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HGK_18.4.24.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/\",\"name\":\"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HGK_18.4.24.jpg\",\"datePublished\":\"2024-04-18T15:38:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HGK_18.4.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/HGK_18.4.24.jpg\",\"width\":1666,\"height\":933},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/18\\\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/","og_locale":"pt_PT","og_type":"article","og_title":"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa - Loginfo24","og_description":"Com a constru\u00e7\u00e3o de um novo tipo de navio, a HGK Shipping estabelece mais um marco para a navega\u00e7\u00e3o interior da Europa. O novo projeto, denominado [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-04-18T15:38:08+00:00","og_image":[{"width":1666,"height":933,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HGK_18.4.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/"},"author":{"name":"","@id":""},"headline":"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa","datePublished":"2024-04-18T15:38:08+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/"},"wordCount":716,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HGK_18.4.24.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/","url":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/","name":"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HGK_18.4.24.jpg","datePublished":"2024-04-18T15:38:08+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HGK_18.4.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/HGK_18.4.24.jpg","width":1666,"height":933},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/18\/hgk-shipping-com-marco-para-a-navegacao-interior-da-europa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"HGK Shipping com marco para a navega\u00e7\u00e3o interior da Europa"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/64919","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=64919"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/64919\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/6659"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=64919"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=64919"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=64919"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}