{"id":64729,"date":"2024-04-04T16:27:29","date_gmt":"2024-04-04T14:27:29","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/"},"modified":"2024-04-04T16:27:29","modified_gmt":"2024-04-04T14:27:29","slug":"vnst20-pro-da-visionnav-impressiona-na-estreia-europeia","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/","title":{"rendered":"VNST20 PRO da VisionNav impressiona na estreia europeia"},"content":{"rendered":"<h5><strong>A VisionNav Robotics apresentou na LogiMAT 2024, a feira internacional de solu\u00e7\u00f5es de intralog\u00edstica e gest\u00e3o de processos em Estugarda, a sua mais recente solu\u00e7\u00e3o autom\u00e1tica para carregar e descarregar caminh\u00f5es-trailer \u2013 com a rec\u00e9m-apresentada rob\u00f3tica AGV VNST20 PRO \u2013 a um p\u00fablico europeu.<\/strong><\/h5>\n<p>(Estugarda) Na estreia europeia da solu\u00e7\u00e3o inovadora do especialista em rob\u00f3tica de transporte de materiais, foi demonstrado como ela pode carregar e descarregar caminh\u00f5es-trailer em apenas 45 minutos.<\/p>\n<p>O potente empilhador aut\u00f3nomo VNST20 PRO da VisionNav combina um avan\u00e7ado sistema de controlo de rob\u00f4s (RCS) para planeamento de frotas e tecnologia de posicionamento 3D-LiDAR-SLAM para precis\u00e3o l\u00edder de mercado. O VNST20 PRO foi desenvolvido especificamente para transporte em solo e agora nos permite carregar e descarregar reboques.<\/p>\n<p>Na LogiMAT 2024, estava em exibi\u00e7\u00e3o no estande da VisionNav um display imersivo que permitia uma explora\u00e7\u00e3o tecnologicamente avan\u00e7ada das capacidades do VNST20 PRO, representando um passo evolutivo no desenvolvimento do carregamento e descarregamento de caminh\u00f5es-trailer.<\/p>\n<h5><strong>Percep\u00e7\u00e3o 3D poderosa<\/strong><\/h5>\n<p>Equipado com um potente RCS que utiliza as mais modernas tecnologias de percep\u00e7\u00e3o 3D, mapeamento, localiza\u00e7\u00e3o e roteamento, o VNST20 PRO gera estrat\u00e9gias eficientes de carga e descarga.<\/p>\n<p>Com o posicionamento 3D-LiDAR-SLAM, o sistema dedicado e propriet\u00e1rio oferece uma utiliza\u00e7\u00e3o do espa\u00e7o aumentada, alta adapta\u00e7\u00e3o a cen\u00e1rios, alta compatibilidade e redund\u00e2ncia de solu\u00e7\u00f5es confi\u00e1veis, para permitir uma movimenta\u00e7\u00e3o de carga r\u00e1pida, segura e eficiente.<\/p>\n<h5>Dispon\u00edvel na Europa a partir de 2025<\/h5>\n<p>O VNST20 PRO estar\u00e1 dispon\u00edvel na Europa a partir de 2025 e pode se adaptar a diferentes caminh\u00f5es, mercadorias e ambientes, utilizando a percep\u00e7\u00e3o auto-adaptativa para diferentes ambientes e mapeamento din\u00e2mico para roteamento din\u00e2mico no cont\u00eainer. \u00c9 compat\u00edvel com uma variedade de caminh\u00f5es na Europa e Am\u00e9rica do Norte e pode ser ajustado para uma variedade de paletes, incluindo EPAL e CHEP. O VNST20 PRO pode ser facilmente alternado para o modo manual, a fim de evitar atrasos operacionais.<\/p>\n<p>O VNST20 PRO melhora a efici\u00eancia e a seguran\u00e7a do trabalho e representa o auge da rob\u00f3tica AGV. Ele transforma a movimenta\u00e7\u00e3o de carga, permitindo um r\u00e1pido carregamento e descarregamento de caminh\u00f5es-trailer em apenas 45 minutos. Esta abordagem inovadora revoluciona os m\u00e9todos tradicionais de opera\u00e7\u00e3o de caminh\u00f5es-trailer. Em sua estreia europeia, o VNST20 PRO recebeu um feedback positivo.<\/p>\n<p>Foto: \u00a9 VisionNav<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A VisionNav Robotics apresentou na LogiMAT 2024, a feira internacional de solu\u00e7\u00f5es de intralog\u00edstica e gest\u00e3o de processos em Estugarda, a sua mais recente solu\u00e7\u00e3o autom\u00e1tica<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-64729","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>VNST20 PRO da VisionNav impressiona na estreia europeia - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VNST20 PRO da VisionNav impressiona na estreia europeia - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A VisionNav Robotics apresentou na LogiMAT 2024, a feira internacional de solu\u00e7\u00f5es de intralog\u00edstica e gest\u00e3o de processos em Estugarda, a sua mais recente solu\u00e7\u00e3o autom\u00e1tica [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T14:27:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/VisionNav_4.4.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1240\" \/>\n\t<meta property=\"og:image:height\" content=\"916\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"VNST20 PRO da VisionNav impressiona na estreia europeia\",\"datePublished\":\"2024-04-04T14:27:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/\"},\"wordCount\":423,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/VisionNav_4.4.24.jpg\",\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/\",\"name\":\"VNST20 PRO da VisionNav impressiona na estreia europeia - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/VisionNav_4.4.24.jpg\",\"datePublished\":\"2024-04-04T14:27:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/VisionNav_4.4.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/VisionNav_4.4.24.jpg\",\"width\":1240,\"height\":916},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2024\\\/04\\\/04\\\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"VNST20 PRO da VisionNav impressiona na estreia europeia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"VNST20 PRO da VisionNav impressiona na estreia europeia - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/","og_locale":"pt_PT","og_type":"article","og_title":"VNST20 PRO da VisionNav impressiona na estreia europeia - Loginfo24","og_description":"A VisionNav Robotics apresentou na LogiMAT 2024, a feira internacional de solu\u00e7\u00f5es de intralog\u00edstica e gest\u00e3o de processos em Estugarda, a sua mais recente solu\u00e7\u00e3o autom\u00e1tica [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-04-04T14:27:29+00:00","og_image":[{"width":1240,"height":916,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/VisionNav_4.4.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/"},"author":{"name":"","@id":""},"headline":"VNST20 PRO da VisionNav impressiona na estreia europeia","datePublished":"2024-04-04T14:27:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/"},"wordCount":423,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/VisionNav_4.4.24.jpg","articleSection":["Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/","url":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/","name":"VNST20 PRO da VisionNav impressiona na estreia europeia - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/VisionNav_4.4.24.jpg","datePublished":"2024-04-04T14:27:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/VisionNav_4.4.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/VisionNav_4.4.24.jpg","width":1240,"height":916},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2024\/04\/04\/vnst20-pro-da-visionnav-impressiona-na-estreia-europeia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"VNST20 PRO da VisionNav impressiona na estreia europeia"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/64729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=64729"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/64729\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/6735"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=64729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=64729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=64729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}