{"id":63572,"date":"2023-11-30T18:32:06","date_gmt":"2023-11-30T17:32:06","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/"},"modified":"2023-11-30T18:32:06","modified_gmt":"2023-11-30T17:32:06","slug":"hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/","title":{"rendered":"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero"},"content":{"rendered":"<div class=\"content--static\">\n<section class=\"hero --image \">\n<div class=\"hero__head container\">\n<div class=\"hero__content w-full md:w-9\/12 lg:w-7\/12\">\n<h5>Com o objetivo de tornar o transporte rodovi\u00e1rio mais sustent\u00e1vel, a Hellmann Worldwide Logistics estabelece uma parceria inovadora com a shipzero. A empresa de Hamburgo \u00e9 especializada na medi\u00e7\u00e3o e redu\u00e7\u00e3o de emiss\u00f5es de CO2 no transporte de mercadorias em todo o mundo. A colabora\u00e7\u00e3o baseia-se em um projeto piloto que est\u00e1 em andamento desde abril deste ano. No \u00e2mbito da coopera\u00e7\u00e3o, a shipzero apoia todo o processo de gest\u00e3o de dados e determina as emiss\u00f5es de CO2 para o neg\u00f3cio global de transporte rodovi\u00e1rio da Hellmann.<\/h5>\n<p>(Osnabr\u00fcck\/Hamburgo) A shipzero tamb\u00e9m incorpora dados prim\u00e1rios de parceiros log\u00edsticos externos no c\u00e1lculo, de modo que as medi\u00e7\u00f5es de CO2 n\u00e3o se baseiem \u2013 como era comum at\u00e9 agora \u2013 em proje\u00e7\u00f5es e valores m\u00e9dios, mas sim em dados de consumo reais.<\/p><\/div>\n<\/div>\n<\/section>\n<\/div>\n<div class=\"content--components\">\n<div class=\"field--field-components\">\n<div id=\"paragraph--id--12461\" class=\"paragraph paragraph--section\">\n<div class=\"field--field-type\">\n<div class=\"paragraph paragraph--grid container\">\n<div class=\"flex flex-wrap c-grid\">\n<div class=\"paragraph paragraph--column c-column lg:w-7\/12 w-full ml-0\">\n<div class=\"paragraph paragraph--text text\">\n<div class=\"field--field-text\">Para determinar valores de emiss\u00f5es precisos, ocorre uma troca de dados atrav\u00e9s da plataforma da shipzero entre a Hellmann e seus parceiros de transporte, permitindo a coleta precisa de emiss\u00f5es de escopo 3 por cliente, remessa e trecho de rota. Estes dados s\u00e3o ent\u00e3o integrados no c\u00e1lculo da pegada de carbono corporativa, auditorias externas, bem como relat\u00f3rios de clientes e de sustentabilidade, apoiando assim a conformidade com novos requisitos regulat\u00f3rios que entrar\u00e3o em vigor em 2024. Atrav\u00e9s da prepara\u00e7\u00e3o e an\u00e1lise baseada em dados de informa\u00e7\u00f5es de tr\u00e1fego, a Hellmann pode identificar projetos concretos de descarboniza\u00e7\u00e3o dentro da cadeia de suprimentos e implement\u00e1-los em conjunto com seus parceiros.<br \/>\u201cNo mundo de hoje, a sustentabilidade \u00e9 um tema central e as regulamenta\u00e7\u00f5es legais tamb\u00e9m exigem transpar\u00eancia na cadeia de suprimentos. A Hellmann enfrentou esse desafio como um dos primeiros grandes prestadores de servi\u00e7os log\u00edsticos e utiliza a tecnologia inovadora da shipzero para criar c\u00e1lculos precisos de emiss\u00f5es de CO2 por remessa para transportes rodovi\u00e1rios com base em dados prim\u00e1rios. Assim, n\u00e3o apenas respondemos \u00e0s exig\u00eancias dos clientes e \u00e0s diretrizes regulat\u00f3rias, mas tamb\u00e9m podemos otimizar nossas cadeias de suprimentos com base na nova transpar\u00eancia de dados e reduzir as emiss\u00f5es de CO2 no transporte rodovi\u00e1rio. \u00c9 claro tamb\u00e9m: quanto mais dados prim\u00e1rios estiverem dispon\u00edveis, mais precisa ser\u00e1 a medi\u00e7\u00e3o. Por isso, estamos atualmente em estreito contato com nossos prestadores de servi\u00e7os de transporte externos para integr\u00e1-los a este projeto inovador\u201d, diz Jens Wollesen, Chief Operating Officer da Hellmann Worldwide Logistics.<\/p>\n<h5>Transpar\u00eancia profunda e capacidade de decis\u00e3o<\/h5>\n<p>\u201cNosso objetivo \u00e9 criar uma transpar\u00eancia profunda e capacidade de decis\u00e3o para a Hellmann em seu processo de descarboniza\u00e7\u00e3o \u2013 e isso de acordo com padr\u00f5es internacionais confi\u00e1veis. Para isso, estamos atualmente construindo uma base de dados e infraestrutura consistentes\u201d, diz Tobias Bohnhoff, CEO da shipzero.<br \/>Foto: \u00a9 Hellmann<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Com o objetivo de tornar o transporte rodovi\u00e1rio mais sustent\u00e1vel, a Hellmann Worldwide Logistics estabelece uma parceria inovadora com a shipzero. A empresa de Hamburgo \u00e9<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7211,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1561],"tags":[],"class_list":["post-63572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Com o objetivo de tornar o transporte rodovi\u00e1rio mais sustent\u00e1vel, a Hellmann Worldwide Logistics estabelece uma parceria inovadora com a shipzero. A empresa de Hamburgo \u00e9 [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-30T17:32:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hellmann_30.11.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1241\" \/>\n\t<meta property=\"og:image:height\" content=\"716\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero\",\"datePublished\":\"2023-11-30T17:32:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/\"},\"wordCount\":503,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hellmann_30.11.23.jpg\",\"articleSection\":[\"Categories\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/\",\"name\":\"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hellmann_30.11.23.jpg\",\"datePublished\":\"2023-11-30T17:32:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hellmann_30.11.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hellmann_30.11.23.jpg\",\"width\":1241,\"height\":716},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/30\\\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/","og_locale":"pt_PT","og_type":"article","og_title":"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero - Loginfo24","og_description":"Com o objetivo de tornar o transporte rodovi\u00e1rio mais sustent\u00e1vel, a Hellmann Worldwide Logistics estabelece uma parceria inovadora com a shipzero. A empresa de Hamburgo \u00e9 [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-11-30T17:32:06+00:00","og_image":[{"width":1241,"height":716,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hellmann_30.11.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/"},"author":{"name":"","@id":""},"headline":"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero","datePublished":"2023-11-30T17:32:06+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/"},"wordCount":503,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hellmann_30.11.23.jpg","articleSection":["Categories","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/","url":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/","name":"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hellmann_30.11.23.jpg","datePublished":"2023-11-30T17:32:06+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hellmann_30.11.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hellmann_30.11.23.jpg","width":1241,"height":716},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/30\/hellmann-medira-emissoes-no-futuro-com-a-ajuda-da-shipzero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Hellmann medir\u00e1 emiss\u00f5es no futuro com a ajuda da Shipzero"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=63572"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/7211"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=63572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=63572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=63572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}