{"id":63404,"date":"2023-11-14T16:18:14","date_gmt":"2023-11-14T15:18:14","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/"},"modified":"2023-11-14T16:18:14","modified_gmt":"2023-11-14T15:18:14","slug":"o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/","title":{"rendered":"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis"},"content":{"rendered":"<h5>A Associa\u00e7\u00e3o Europeia de Cons\u00f3rcio de Transportadores Internacionais (ELVIS) apoia uma descarboniza\u00e7\u00e3o segura do setor de transporte. Uma recomenda\u00e7\u00e3o central que o cons\u00f3rcio de transporte extrai do mais recente estudo da Global Energy Solutions (GES) e.V. \u00e9 que a transi\u00e7\u00e3o da mobilidade s\u00f3 pode ser realizada globalmente e n\u00e3o de forma isolada pela Alemanha. Al\u00e9m disso, n\u00e3o existe um \u00fanico combust\u00edvel como solu\u00e7\u00e3o abrangente para reduzir os gases de efeito estufa no transporte.<\/h5>\n<p>(Alzenau) Com base nisso, a ELVIS aconselha o setor a testar diferentes solu\u00e7\u00f5es de combust\u00edvel, a n\u00e3o agir precipitadamente e exige ao governo o apoio a combust\u00edveis alternativos. O estudo avalia informa\u00e7\u00f5es de pol\u00edtica, ci\u00eancia e economia para fornecer abordagens concretas para empresas de transporte e log\u00edstica \u2013 especialmente no transporte pesado.<\/p>\n<p>&#8220;A descarboniza\u00e7\u00e3o no transporte \u00e9 uma preocupa\u00e7\u00e3o global, uma vez que as cadeias de suprimento atuais neste setor est\u00e3o interconectadas em todo o mundo. Que a Alemanha n\u00e3o pode desenvolver uma solu\u00e7\u00e3o sozinha \u00e9 uma das descobertas decisivas do atual estudo da GES&#8221;, diz Nikolja Grabowski, membro do conselho da ELVIS AG. A Global Energy Solutions e.V. enfatiza em seu estudo intitulado &#8220;Considera\u00e7\u00e3o de diferentes formas de propuls\u00e3o para caminh\u00f5es pesados&#8221; que uma interpreta\u00e7\u00e3o e sistemas regulat\u00f3rios puramente nacionais, sem uma perspectiva global, promovem inadequadamente a prote\u00e7\u00e3o clim\u00e1tica mundial. Isso pode ser economicamente prejudicial se as medidas implementadas n\u00e3o forem aplic\u00e1veis internacionalmente. O transporte de cargas pesadas \u00e9 respons\u00e1vel por cerca de 30% de todos os gases de efeito estufa do transporte rodovi\u00e1rio na UE. &#8220;O setor est\u00e1 ciente disso e trabalha continuamente para reduzir as emiss\u00f5es sempre que poss\u00edvel, mas mantendo a viabilidade econ\u00f4mica&#8221;, afirma Grabowski.<\/p>\n<h5>Combust\u00edveis de metanol como solu\u00e7\u00e3o promissora<\/h5>\n<p>O estudo subjacente considera combust\u00edveis sint\u00e9ticos, especialmente metanol-diesel e metanol-gasolina, como uma solu\u00e7\u00e3o promissora para a neutralidade clim\u00e1tica no setor de caminh\u00f5es pesados. O Prof. Dr. Dr. Dr. h.c. Franz Josef Radermacher, l\u00edder do estudo e vice-presidente da Global Energy Solutions e.V., enfatiza: &#8220;Com combust\u00edveis sint\u00e9ticos, toda a frota mundial de cerca de 1,3 bilh\u00f5es de ve\u00edculos \u2013 incluindo cerca de 300 milh\u00f5es de caminh\u00f5es \u2013 pode ser progressivamente levada em dire\u00e7\u00e3o \u00e0 neutralidade clim\u00e1tica atrav\u00e9s da mistura&#8230;&#8221; Isso permite o uso sustent\u00e1vel da infraestrutura e dos ve\u00edculos existentes. Os combust\u00edveis renov\u00e1veis HVO devem oferecer a solu\u00e7\u00e3o mais r\u00e1pida para a redu\u00e7\u00e3o das emiss\u00f5es de CO2, uma vez que, entre outras coisas, j\u00e1 existe um n\u00famero crescente de postos de abastecimento HVO na Europa. Os sistemas de propuls\u00e3o por bateria s\u00e3o adequados para ve\u00edculos menores e mais leves e para dist\u00e2ncias mais curtas, enquanto g\u00e1s, c\u00e9lulas de combust\u00edvel, hidrog\u00eanio e combust\u00edveis sint\u00e9ticos devem desempenhar um papel central no transporte pesado. &#8220;N\u00e3o existe uma solu\u00e7\u00e3o universal. No futuro, todos esses tipos de propuls\u00e3o ser\u00e3o necess\u00e1rios para garantir competitividade e, ao mesmo tempo, redu\u00e7\u00e3o de CO2&#8221;, diz Radermacher.<\/p>\n<p><a href=\"https:\/\/www.elvis-ag.com\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-24786 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ELVIS_14.11.23_2.jpg\" alt=\"\" width=\"1632\" height=\"805\" \/><\/a>Por isso, a ELVIS recomenda \u00e0s pequenas e m\u00e9dias empresas que n\u00e3o tomem decis\u00f5es precipitadas e que, ao renovar a frota, permane\u00e7am inicialmente com combust\u00edveis estabelecidos. Grabowski enfatiza: &#8220;O desenvolvimento de diferentes caminhos tecnol\u00f3gicos no mercado deve ser inicialmente continuado e, sem falta, tamb\u00e9m testado dentro das possibilidades dispon\u00edveis para acumular experi\u00eancias pr\u00e1ticas. \u00c9 importante n\u00e3o apostar apenas em uma tecnologia de propuls\u00e3o.&#8221; Assim, a op\u00e7\u00e3o mais eficiente e amplamente implement\u00e1vel que o mercado tem a oferecer nas condi\u00e7\u00f5es atuais pode ser escolhida. Como solu\u00e7\u00e3o de transi\u00e7\u00e3o, combust\u00edveis renov\u00e1veis de baixo carbono devem ser os mais adequados para reduzir os gases de efeito estufa a curto prazo.<\/p>\n<h5>Apoiar os parceiros do cons\u00f3rcio na descarboniza\u00e7\u00e3o<\/h5>\n<p>Com a participa\u00e7\u00e3o no estudo da Global Energy Solutions, o cons\u00f3rcio de transporte contribui ativamente para a promo\u00e7\u00e3o de solu\u00e7\u00f5es sustent\u00e1veis no setor de transporte. &#8220;Estamos ao lado de nossos mais de 250 parceiros do cons\u00f3rcio, oferecendo consultoria na descarboniza\u00e7\u00e3o&#8221;, diz Grabowski.<\/p>\n<p>Foto: \u00a9 ELVIS<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Associa\u00e7\u00e3o Europeia de Cons\u00f3rcio de Transportadores Internacionais (ELVIS) apoia uma descarboniza\u00e7\u00e3o segura do setor de transporte. Uma recomenda\u00e7\u00e3o central que o cons\u00f3rcio de transporte extrai<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":7291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1556,1561],"tags":[],"class_list":["post-63404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A Associa\u00e7\u00e3o Europeia de Cons\u00f3rcio de Transportadores Internacionais (ELVIS) apoia uma descarboniza\u00e7\u00e3o segura do setor de transporte. Uma recomenda\u00e7\u00e3o central que o cons\u00f3rcio de transporte extrai [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-14T15:18:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ELVIS_14.11.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1347\" \/>\n\t<meta property=\"og:image:height\" content=\"737\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis\",\"datePublished\":\"2023-11-14T15:18:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/\"},\"wordCount\":732,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ELVIS_14.11.23.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/\",\"name\":\"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ELVIS_14.11.23.jpg\",\"datePublished\":\"2023-11-14T15:18:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ELVIS_14.11.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ELVIS_14.11.23.jpg\",\"width\":1347,\"height\":737},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/11\\\/14\\\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/","og_locale":"pt_PT","og_type":"article","og_title":"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis - Loginfo24","og_description":"A Associa\u00e7\u00e3o Europeia de Cons\u00f3rcio de Transportadores Internacionais (ELVIS) apoia uma descarboniza\u00e7\u00e3o segura do setor de transporte. Uma recomenda\u00e7\u00e3o central que o cons\u00f3rcio de transporte extrai [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-11-14T15:18:14+00:00","og_image":[{"width":1347,"height":737,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ELVIS_14.11.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/"},"author":{"name":"","@id":""},"headline":"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis","datePublished":"2023-11-14T15:18:14+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/"},"wordCount":732,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ELVIS_14.11.23.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/","url":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/","name":"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ELVIS_14.11.23.jpg","datePublished":"2023-11-14T15:18:14+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ELVIS_14.11.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ELVIS_14.11.23.jpg","width":1347,"height":737},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/11\/14\/o-consorcio-de-carga-elvis-exige-diversidade-nos-combustiveis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"O Cons\u00f3rcio de Carga ELVIS exige diversidade nos combust\u00edveis"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=63404"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/63404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/7291"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=63404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=63404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=63404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}