{"id":61475,"date":"2023-05-19T18:59:03","date_gmt":"2023-05-19T16:59:03","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/"},"modified":"2023-05-19T18:59:03","modified_gmt":"2023-05-19T16:59:03","slug":"logistica-mader-confere-a-jurgen-behr-procura-geral","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/","title":{"rendered":"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral"},"content":{"rendered":"<h5>A log\u00edstica Mader nomeou J\u00fcrgen Behr (49) como procurador para todas as empresas do grupo, ampliando assim sua capacidade de a\u00e7\u00e3o e decis\u00e3o em diferentes locais. J\u00fcrgen Behr possui quase 30 anos de experi\u00eancia profissional em empresas de log\u00edstica contratual, tanto nacionais quanto internacionais. Ele tem um amplo conhecimento do mercado e contatos na regi\u00e3o DACH.<\/h5>\n<p>(Ansbach) Na empresa familiar Mader, o especialista em transporte J\u00fcrgen Behr \u00e9 desde 2021 o gerente da filial de Heidelberg e respons\u00e1vel pelo desenvolvimento de neg\u00f3cios. Al\u00e9m do desenvolvimento de neg\u00f3cios externo, ele tamb\u00e9m \u00e9 respons\u00e1vel pelo desenvolvimento interno e pela melhoria cont\u00ednua da qualidade do grupo de log\u00edstica, que opera atualmente em dez locais diferentes, oferecendo im\u00f3veis log\u00edsticos de uso \u00fanico e m\u00faltiplo, principalmente para a ind\u00fastria automotiva e para o com\u00e9rcio eletr\u00f4nico.<\/p>\n<p>&#8220;Para desenvolver a Mader de forma consistente e adaptar as estruturas ao crescimento, confiamos a J\u00fcrgen Behr mais responsabilidades e fun\u00e7\u00f5es de lideran\u00e7a. Com ele, temos ao nosso lado um experiente especialista em log\u00edstica que continuar\u00e1 a expandir o curso bem-sucedido do grupo Mader e proporcionar\u00e1 um valor agregado para nossa empresa e nossos clientes&#8221;, explica Matthias Irion, s\u00f3cio-gerente do grupo Mader.<\/p>\n<p>&#8220;Com a nomea\u00e7\u00e3o de procurador para todas as empresas do grupo Mader, sublinhamos a confian\u00e7a depositada em J\u00fcrgen Behr e, com seus impulsos para projetos internos e externos, continuaremos a trajet\u00f3ria de crescimento&#8221;, acrescenta Philipp Thiele, s\u00f3cio-gerente do grupo Mader.<\/p>\n<h5>Empresa familiar com funcion\u00e1rios leais<\/h5>\n<p>Sobre sua nomea\u00e7\u00e3o, J\u00fcrgen Behr diz: &#8220;O grupo Mader, com seu pensamento de PME, clientes de longa data, valores vividos de uma empresa familiar e funcion\u00e1rios leais, tem um grande potencial. Esses valores s\u00e3o valorizados, como mostram os relacionamentos de longa data com os clientes e os novos contratos conquistados, como com a TE Connectivity.&#8221;<\/p>\n<p>Foto: \u00a9 Mader \/ <em><strong>Legenda da imagem:<\/strong> J\u00fcrgen Behr<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A log\u00edstica Mader nomeou J\u00fcrgen Behr (49) como procurador para todas as empresas do grupo, ampliando assim sua capacidade de a\u00e7\u00e3o e decis\u00e3o em diferentes locais.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8136,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-61475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A log\u00edstica Mader nomeou J\u00fcrgen Behr (49) como procurador para todas as empresas do grupo, ampliando assim sua capacidade de a\u00e7\u00e3o e decis\u00e3o em diferentes locais. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-19T16:59:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mader_19.5.23.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1257\" \/>\n\t<meta property=\"og:image:height\" content=\"932\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral\",\"datePublished\":\"2023-05-19T16:59:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/\"},\"wordCount\":343,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mader_19.5.23.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/\",\"name\":\"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mader_19.5.23.jpg\",\"datePublished\":\"2023-05-19T16:59:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mader_19.5.23.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mader_19.5.23.jpg\",\"width\":1257,\"height\":932},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/05\\\/19\\\/logistica-mader-confere-a-jurgen-behr-procura-geral\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/","og_locale":"pt_PT","og_type":"article","og_title":"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral - Loginfo24","og_description":"A log\u00edstica Mader nomeou J\u00fcrgen Behr (49) como procurador para todas as empresas do grupo, ampliando assim sua capacidade de a\u00e7\u00e3o e decis\u00e3o em diferentes locais. [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-05-19T16:59:03+00:00","og_image":[{"width":1257,"height":932,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mader_19.5.23.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/"},"author":{"name":"","@id":""},"headline":"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral","datePublished":"2023-05-19T16:59:03+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/"},"wordCount":343,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mader_19.5.23.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/","url":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/","name":"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mader_19.5.23.jpg","datePublished":"2023-05-19T16:59:03+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mader_19.5.23.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mader_19.5.23.jpg","width":1257,"height":932},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/05\/19\/logistica-mader-confere-a-jurgen-behr-procura-geral\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Log\u00edstica Mader confere a J\u00fcrgen Behr procura geral"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/61475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=61475"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/61475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/8136"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=61475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=61475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=61475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}