{"id":60572,"date":"2023-02-14T16:40:05","date_gmt":"2023-02-14T15:40:05","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/"},"modified":"2023-02-14T16:40:05","modified_gmt":"2023-02-14T15:40:05","slug":"dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/","title":{"rendered":"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades"},"content":{"rendered":"<h5><strong>O conceito &#8220;DACHSER Emission-Free Delivery&#8221;, iniciado como um projeto de pesquisa e inova\u00e7\u00e3o, provou ser um sucesso total na entrega em \u00e1reas urbanas. Atualmente, j\u00e1 existem doze \u00e1reas de entrega urbanas localmente sem emiss\u00f5es para mercadorias n\u00e3o refrigeradas na rede Dachser. Mais crescimento est\u00e1 planejado: at\u00e9 2025, pelo menos dez grandes cidades europeias devem se juntar a essa iniciativa.<\/strong><\/h5>\n<p>(Kempten) &#8220;Com o DACHSER Emission-Free Delivery, provamos que podemos entregar a \u00faltima milha sem emiss\u00f5es com carga fracionada. O projeto de pesquisa deu o passo para a pr\u00e1tica e aponta o caminho para uma log\u00edstica urbana mais sustent\u00e1vel&#8221;, diz Stefan Hohm, Chief Development Officer (CDO) da Dachser.<\/p>\n<p>A entrega sem emiss\u00f5es de pacotes e cargas fracionadas n\u00e3o refrigeradas ocorre at\u00e9 agora em \u00e1reas de entrega definidas em Berlim, Freiburg, Stuttgart, Munique, Dortmund, Copenhague, Oslo, Praga, Estrasburgo, Paris, Madrid e Porto. Ve\u00edculos de zero emiss\u00f5es s\u00e3o utilizados: com base em um sistema modular e adaptados \u00e0s exig\u00eancias locais, s\u00e3o utilizados furg\u00f5es e caminh\u00f5es el\u00e9tricos a bateria, bem como bicicletas de carga eletricamente assistidas. Estas \u00faltimas s\u00e3o especialmente projetadas para cargas fracionadas e mercadorias paletizadas de at\u00e9 250 quilos. As bicicletas de carga come\u00e7am seu percurso em um centro de transbordo pr\u00f3ximo ao centro da cidade \u2013 chamado de &#8220;Microhub&#8221; \u2013 e se dirigem \u00e0s movimentadas zonas de pedestres. Os caminh\u00f5es el\u00e9tricos, por sua vez, abastecem os Microhubs com mercadorias ou entregam diretamente aos destinat\u00e1rios, quando os pacotes e paletes n\u00e3o s\u00e3o adequados para transporte por bicicleta devido ao seu peso ou dimens\u00f5es.<\/p>\n<h5><strong>Expans\u00e3o planejada em outras metr\u00f3poles<\/strong><\/h5>\n<p>A disponibilidade de ve\u00edculos de zero emiss\u00f5es e de uma infraestrutura de carregamento correspondente \u00e9 um fator decisivo para a implementa\u00e7\u00e3o do conceito de log\u00edstica urbana.<\/p>\n<p>&#8220;As capacidades de produ\u00e7\u00e3o dos fabricantes de ve\u00edculos foram significativamente aumentadas, de modo que podemos esperar uma melhor disponibilidade de caminh\u00f5es el\u00e9tricos no futuro&#8221;, diz Alexander Tonn, Chief Operations Officer Road Logistics da Dachser. &#8220;Portanto, planejamos com pelo menos mais dez cidades at\u00e9 2025, atendendo assim ao desejo de muitos clientes.&#8221;<\/p>\n<p>O foco est\u00e1 principalmente em regi\u00f5es metropolitanas europeias com pelo menos um milh\u00e3o de habitantes, onde a Dachser est\u00e1 representada com suas pr\u00f3prias filiais da Unidade de Neg\u00f3cios European Logistics.<\/p>\n<h5><strong>Efeitos positivos para o meio ambiente e para os motoristas<\/strong><\/h5>\n<p>Com a entrega urbana localmente sem emiss\u00f5es, a Dachser contribui para os esfor\u00e7os das administra\u00e7\u00f5es municipais em busca de uma melhor qualidade do ar e menos ru\u00eddo causado pelo tr\u00e1fego. Gra\u00e7as aos caminh\u00f5es e bicicletas de carga el\u00e9tricos a bateria, n\u00e3o h\u00e1 emiss\u00f5es de poluentes atmosf\u00e9ricos no local, o que representa uma contribui\u00e7\u00e3o significativa para a purifica\u00e7\u00e3o do ar. Em conjunto com o uso exclusivo de eletricidade gerada de forma regenerativa pela Dachser, as emiss\u00f5es de gases de efeito estufa relacionadas \u00e0s opera\u00e7\u00f5es para a \u00faltima milha, desde a filial at\u00e9 o destinat\u00e1rio, s\u00e3o reduzidas a zero. Al\u00e9m disso, as emiss\u00f5es de ru\u00eddo causadas por motores a diesel s\u00e3o significativamente reduzidas e a carga de tr\u00e1fego causada por caminh\u00f5es \u00e9 diminu\u00edda pelo uso de bicicletas de carga. Os motoristas de caminh\u00e3o tamb\u00e9m se beneficiam dos ve\u00edculos el\u00e9tricos a bateria, pois as vibra\u00e7\u00f5es do motor, que normalmente s\u00e3o sentidas na cabine, est\u00e3o ausentes.<\/p>\n<h5><strong>Parte da estrat\u00e9gia de prote\u00e7\u00e3o clim\u00e1tica de longo prazo<\/strong><\/h5>\n<p>O DACHSER Emission-Free Delivery foi desenvolvido em conjunto com a filial de Kornwestheim e foi introduzido pela primeira vez na cidade de Stuttgart. A Dachser ganhou o pr\u00eamio de Log\u00edstica Urbana Sustent\u00e1vel do Minist\u00e9rio Federal do Meio Ambiente da Alemanha e da Ag\u00eancia Federal do Meio Ambiente em dezembro de 2018 pelo conceito e pela implementa\u00e7\u00e3o piloto.<\/p>\n<p>O conceito \u00e9, gra\u00e7as ao sistema modular, fundamentalmente adequado para todas as cidades europeias. Assim, a Dachser est\u00e1 bem preparada para as proibi\u00e7\u00f5es de entrada j\u00e1 existentes ou planejadas para ve\u00edculos a combust\u00e3o nas grandes metr\u00f3poles. No total, o DACHSER Emission-Free Delivery contribui para a estrat\u00e9gia de prote\u00e7\u00e3o clim\u00e1tica de longo prazo da empresa com sede em Kempten\/Allg\u00e4u. Com foco em um desenvolvimento empresarial sustent\u00e1vel e com \u00eanfase em efici\u00eancia, inova\u00e7\u00e3o e responsabilidade integrativa, a empresa familiar avan\u00e7a, junto com clientes e parceiros, na transforma\u00e7\u00e3o para uma log\u00edstica mais sustent\u00e1vel.<\/p>\n<p>Foto: \u00a9 Dachser<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O conceito &#8220;DACHSER Emission-Free Delivery&#8221;, iniciado como um projeto de pesquisa e inova\u00e7\u00e3o, provou ser um sucesso total na entrega em \u00e1reas urbanas. Atualmente, j\u00e1 existem<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":8505,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-60572","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"O conceito &#8220;DACHSER Emission-Free Delivery&#8221;, iniciado como um projeto de pesquisa e inova\u00e7\u00e3o, provou ser um sucesso total na entrega em \u00e1reas urbanas. Atualmente, j\u00e1 existem [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-14T15:40:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_14.02.2023.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1516\" \/>\n\t<meta property=\"og:image:height\" content=\"901\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades\",\"datePublished\":\"2023-02-14T15:40:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/\"},\"wordCount\":781,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_14.02.2023.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/\",\"name\":\"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_14.02.2023.jpg\",\"datePublished\":\"2023-02-14T15:40:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_14.02.2023.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_14.02.2023.jpg\",\"width\":1516,\"height\":901},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2023\\\/02\\\/14\\\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/","og_locale":"pt_PT","og_type":"article","og_title":"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades - Loginfo24","og_description":"O conceito &#8220;DACHSER Emission-Free Delivery&#8221;, iniciado como um projeto de pesquisa e inova\u00e7\u00e3o, provou ser um sucesso total na entrega em \u00e1reas urbanas. Atualmente, j\u00e1 existem [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2023-02-14T15:40:05+00:00","og_image":[{"width":1516,"height":901,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_14.02.2023.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/"},"author":{"name":"","@id":""},"headline":"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades","datePublished":"2023-02-14T15:40:05+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/"},"wordCount":781,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_14.02.2023.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/","url":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/","name":"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_14.02.2023.jpg","datePublished":"2023-02-14T15:40:05+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_14.02.2023.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_14.02.2023.jpg","width":1516,"height":901},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2023\/02\/14\/dachser-plane-areas-de-entrega-sem-emissoes-em-10-outras-cidades\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Dachser plane \u00e1reas de entrega sem emiss\u00f5es em 10 outras cidades"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/60572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=60572"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/60572\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/8505"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=60572"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=60572"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=60572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}