{"id":58855,"date":"2022-10-05T18:55:35","date_gmt":"2022-10-05T16:55:35","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/"},"modified":"2022-10-05T18:55:35","modified_gmt":"2022-10-05T16:55:35","slug":"a-correios-suicos-adquire-a-empresa-de-ti-eoscop","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/","title":{"rendered":"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop"},"content":{"rendered":"<h5><strong>A Correios Su\u00ed\u00e7os adquiriu, a partir de 4 de outubro de 2022, a empresa de software log\u00edstico Eoscop, localizada em Balsthal (SO). Com a Eoscop, ela assume uma parceira de TI de longa data, que estava \u00e0 procura de um comprador devido a uma sucess\u00e3o. Com a Eoscop, os Correios podem padronizar e desenvolver ainda mais seu software de planejamento para processos log\u00edsticos espec\u00edficos.<\/strong><\/h5>\n<p>(Berna\/Balsthal) A log\u00edstica de mercadorias \u00e9 um mercado em crescimento, especialmente considerando a crescente import\u00e2ncia do com\u00e9rcio online. Portanto, os Correios assumem a log\u00edstica completa de A a Z para muitos clientes comerciais \u2013 desde fabricantes de m\u00e1quinas at\u00e9 lojas online. Eles n\u00e3o s\u00e3o apenas respons\u00e1veis pela entrega de mercadorias, mas tamb\u00e9m oferecem, por exemplo, servi\u00e7os de desembara\u00e7o aduaneiro ou servi\u00e7os de montagem para lojas de m\u00f3veis. Para esses servi\u00e7os, os Correios precisam de profissionais e know-how, entre outras coisas, para o planejamento das diversas opera\u00e7\u00f5es. Para melhorar ainda mais nesse aspecto, os Correios adquiriram 100% da empresa de TI Eoscop a partir de 4 de outubro de 2022. A Eoscop desenvolve aplica\u00e7\u00f5es digitais espec\u00edficas que s\u00e3o necess\u00e1rias para uma log\u00edstica moderna. A empresa emprega 20 colaboradores em Balsthal (SO), que ser\u00e3o integrados.<\/p>\n<h5><strong>Software para transporte<\/strong><\/h5>\n<p>Software para o processamento de desembara\u00e7os aduaneiros, ferramentas para a organiza\u00e7\u00e3o de transportes internacionais ou para a entrega de pe\u00e7as de reposi\u00e7\u00e3o a empresas de tecnologia: por tr\u00e1s de cada servi\u00e7o que os Correios oferecem a seus clientes comerciais, existe um planejamento robusto. A empresa Eoscop desenvolveu, nos \u00faltimos anos, in\u00fameras e muito espec\u00edficas aplica\u00e7\u00f5es com e para a log\u00edstica de mercadorias dos Correios.<\/p>\n<h5><strong>Os Correios como maior cliente<\/strong><\/h5>\n<p>Os Correios j\u00e1 s\u00e3o hoje o maior cliente da Eoscop. Johannes Cramer, chefe de Servi\u00e7os Log\u00edsticos dos Correios, est\u00e1 satisfeito que o especialista em software log\u00edstico agora tamb\u00e9m pertence completamente aos Correios: &#8220;A Eoscop entende perfeitamente o que precisamos. Temos uma colabora\u00e7\u00e3o de longa data. Com a aquisi\u00e7\u00e3o, obtemos uma ferramenta importante para padronizar nosso software de planejamento em toda a log\u00edstica de mercadorias. Ao ter os especialistas da Eoscop sob um mesmo teto, podemos tamb\u00e9m responder ainda mais rapidamente \u00e0s necessidades espec\u00edficas de nossos clientes comerciais.&#8221;<\/p>\n<p>Foto: \u00a9 Eoscop<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Correios Su\u00ed\u00e7os adquiriu, a partir de 4 de outubro de 2022, a empresa de software log\u00edstico Eoscop, localizada em Balsthal (SO). Com a Eoscop, ela<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":9224,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-58855","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A Correios Su\u00ed\u00e7os adquiriu, a partir de 4 de outubro de 2022, a empresa de software log\u00edstico Eoscop, localizada em Balsthal (SO). Com a Eoscop, ela [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-05T16:55:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_5.10.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1289\" \/>\n\t<meta property=\"og:image:height\" content=\"712\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop\",\"datePublished\":\"2022-10-05T16:55:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/\"},\"wordCount\":406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_5.10.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/\",\"name\":\"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_5.10.22.jpg\",\"datePublished\":\"2022-10-05T16:55:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_5.10.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_CH_5.10.22.jpg\",\"width\":1289,\"height\":712},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/10\\\/05\\\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/","og_locale":"pt_PT","og_type":"article","og_title":"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop - Loginfo24","og_description":"A Correios Su\u00ed\u00e7os adquiriu, a partir de 4 de outubro de 2022, a empresa de software log\u00edstico Eoscop, localizada em Balsthal (SO). Com a Eoscop, ela [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-10-05T16:55:35+00:00","og_image":[{"width":1289,"height":712,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_5.10.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/"},"author":{"name":"","@id":""},"headline":"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop","datePublished":"2022-10-05T16:55:35+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/"},"wordCount":406,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_5.10.22.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/","url":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/","name":"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_5.10.22.jpg","datePublished":"2022-10-05T16:55:35+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_5.10.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_CH_5.10.22.jpg","width":1289,"height":712},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/10\/05\/a-correios-suicos-adquire-a-empresa-de-ti-eoscop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"A Correios Su\u00ed\u00e7os adquire a empresa de TI Eoscop"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/58855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=58855"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/58855\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/9224"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=58855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=58855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=58855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}