{"id":55020,"date":"2022-03-07T19:48:06","date_gmt":"2022-03-07T18:48:06","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/"},"modified":"2022-03-07T19:48:06","modified_gmt":"2022-03-07T18:48:06","slug":"transporeon-fecha-parceria-com-a-blue-yonder","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/","title":{"rendered":"Transporeon fecha parceria com a Blue Yonder"},"content":{"rendered":"<h5><strong>A solu\u00e7\u00e3o de visibilidade em tempo real da Transporeon \u2013 Sixfold by Transporeon \u2013 proporcionar\u00e1 um valor adicional aos clientes de solu\u00e7\u00f5es de gest\u00e3o de transporte (TMS) da Blue Yonder. Os clientes TMS da Blue Yonder poder\u00e3o utilizar o Sixfold by Transporeon em todo o mundo, sem restri\u00e7\u00f5es regionais, e para todos os modos de transporte: a\u00e9reo, mar\u00edtimo, rodovi\u00e1rio e multimodal.<\/strong><\/h5>\n<p>(Ulm) A Transporeon, a maior plataforma de gest\u00e3o de transporte da Europa, anunciou hoje uma parceria com a Blue Yonder, uma empresa l\u00edder mundial em cadeias de suprimento digitais e cumprimento de com\u00e9rcio omnicanal. O objetivo \u00e9 fornecer aos seus clientes em comum visibilidade em tempo real (RTV). No \u00e2mbito da parceria, a solu\u00e7\u00e3o RTV da Transporeon \u2013 Sixfold by Transporeon \u2013 permitir\u00e1 que os clientes TMS da Blue Yonder tenham acesso necess\u00e1rio a dados em tempo real, al\u00e9m de fornecer informa\u00e7\u00f5es precisas sobre os Tempos Estimados de Chegada (ETAs) para seus transportes a carregadores, transportadoras e clientes finais.<\/p>\n<p>A capacidade de rastrear mercadorias e\/ou produtos durante o transporte e, assim, obter uma vis\u00e3o clara sobre o pr\u00f3prio invent\u00e1rio e atividades atuais, continua a ser uma prioridade para os l\u00edderes da cadeia de suprimentos. Melhorar o atendimento ao cliente e o controle de custos por meio da gest\u00e3o de invent\u00e1rio em movimento, fornecer atualiza\u00e7\u00f5es proativas de status, limitar interrup\u00e7\u00f5es e mitigar riscos s\u00e3o essenciais para uma cadeia de suprimentos forte e flex\u00edvel.<\/p>\n<h5><strong>Benef\u00edcios para os clientes<\/strong><\/h5>\n<ul>\n<li>Abordagem hol\u00edstica na gest\u00e3o de ponta a ponta, execu\u00e7\u00e3o e visibilidade dentro das cadeias de suprimento.<\/li>\n<li>Acesso \u00e0 maior rede global de mais de 130.000 transportadoras.<\/li>\n<li>Melhoria na conectividade atrav\u00e9s de ofertas expandidas de prestadores de servi\u00e7os log\u00edsticos.<\/li>\n<li>Aumento do Net Promoter Score (NPS) dos clientes e melhor colabora\u00e7\u00e3o com transportadoras.<\/li>\n<li>Menos disputas e penalidades contratuais atrav\u00e9s da vis\u00e3o dos reais indicadores OTIF.<\/li>\n<\/ul>\n<p>&#8220;Esta parceria representa um passo importante para ambas as empresas. O Sixfold by Transporeon \u00e9 um servi\u00e7o de visibilidade em tempo real de primeira linha, pronto para uso, que oferece rastreamento de transportes a\u00e9reos, mar\u00edtimos, rodovi\u00e1rios e multimodais. Os servi\u00e7os de rede da Transporeon equipam os clientes TMS da Blue Yonder com funcionalidades de ponta&#8221;, diz Stephan Sieber, CEO da Transporeon.<\/p>\n<h5><strong>Premiado com o Pr\u00eamio Telem\u00e1tica<\/strong><\/h5>\n<p>O Sixfold by Transporeon, premiado com o Pr\u00eamio Telem\u00e1tica Alem\u00e3o 2022, oferece a uma ampla rede de prestadores de servi\u00e7os log\u00edsticos ferramentas e servi\u00e7os para colabora\u00e7\u00e3o. Esta \u00e9 a plataforma mais utilizada entre os milhares de transportadoras que se beneficiam de seus servi\u00e7os.<\/p>\n<p>A poderosa intelig\u00eancia artificial (IA) da plataforma pode prever atrasos e alertar proativamente os clientes sobre problemas, reunindo dados ao vivo de cadeias de suprimento em toda a Europa em sua rede robusta. A tecnologia do Sixfold by Transporeon integra TMS com telem\u00e1tica de caminh\u00f5es, dados de mapas e an\u00e1lises preditivas em uma solu\u00e7\u00e3o de ponta.<\/p>\n<p>Foto: \u00a9 Transporeon<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A solu\u00e7\u00e3o de visibilidade em tempo real da Transporeon \u2013 Sixfold by Transporeon \u2013 proporcionar\u00e1 um valor adicional aos clientes de solu\u00e7\u00f5es de gest\u00e3o de transporte<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10822,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-55020","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Transporeon fecha parceria com a Blue Yonder - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transporeon fecha parceria com a Blue Yonder - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A solu\u00e7\u00e3o de visibilidade em tempo real da Transporeon \u2013 Sixfold by Transporeon \u2013 proporcionar\u00e1 um valor adicional aos clientes de solu\u00e7\u00f5es de gest\u00e3o de transporte [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-07T18:48:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_7.3.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1201\" \/>\n\t<meta property=\"og:image:height\" content=\"690\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Transporeon fecha parceria com a Blue Yonder\",\"datePublished\":\"2022-03-07T18:48:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/\"},\"wordCount\":520,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_7.3.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/\",\"name\":\"Transporeon fecha parceria com a Blue Yonder - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_7.3.22.jpg\",\"datePublished\":\"2022-03-07T18:48:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_7.3.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Transporeon_7.3.22.jpg\",\"width\":1201,\"height\":690},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/03\\\/07\\\/transporeon-fecha-parceria-com-a-blue-yonder\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transporeon fecha parceria com a Blue Yonder\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Transporeon fecha parceria com a Blue Yonder - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/","og_locale":"pt_PT","og_type":"article","og_title":"Transporeon fecha parceria com a Blue Yonder - Loginfo24","og_description":"A solu\u00e7\u00e3o de visibilidade em tempo real da Transporeon \u2013 Sixfold by Transporeon \u2013 proporcionar\u00e1 um valor adicional aos clientes de solu\u00e7\u00f5es de gest\u00e3o de transporte [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-03-07T18:48:06+00:00","og_image":[{"width":1201,"height":690,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_7.3.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/"},"author":{"name":"","@id":""},"headline":"Transporeon fecha parceria com a Blue Yonder","datePublished":"2022-03-07T18:48:06+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/"},"wordCount":520,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_7.3.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/","url":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/","name":"Transporeon fecha parceria com a Blue Yonder - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_7.3.22.jpg","datePublished":"2022-03-07T18:48:06+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_7.3.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Transporeon_7.3.22.jpg","width":1201,"height":690},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/03\/07\/transporeon-fecha-parceria-com-a-blue-yonder\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Transporeon fecha parceria com a Blue Yonder"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/55020","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=55020"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/55020\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/10822"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=55020"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=55020"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=55020"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}