{"id":53060,"date":"2021-10-28T12:09:38","date_gmt":"2021-10-28T10:09:38","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/"},"modified":"2021-10-28T12:09:38","modified_gmt":"2021-10-28T10:09:38","slug":"astag-garante-o-fornecimento-na-suica","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/","title":{"rendered":"ASTAG garante o fornecimento na Su\u00ed\u00e7a"},"content":{"rendered":"<h5><strong>Diferentemente do Reino Unido, o fornecimento e a elimina\u00e7\u00e3o na Su\u00ed\u00e7a est\u00e3o sempre garantidos \u2013 gra\u00e7as ao alto e confi\u00e1vel compromisso do setor de transporte rodovi\u00e1rio. No entanto, a necessidade de motoristas adicionais \u00e9 grande. A Associa\u00e7\u00e3o Su\u00ed\u00e7a de Ve\u00edculos Comerciais ASTAG, portanto, continua a apostar na promo\u00e7\u00e3o direcionada de jovens talentos. A parceria social existente com Les Routiers Suisses tamb\u00e9m \u00e9 importante. As reivindica\u00e7\u00f5es salariais, como as que foram divulgadas nos \u00faltimos dias, s\u00e3o normais no outono.<\/strong><\/h5>\n<p>(Berna) A Associa\u00e7\u00e3o Su\u00ed\u00e7a de Ve\u00edculos Comerciais ASTAG est\u00e1 satisfeita com a grande presen\u00e7a do setor de transporte rodovi\u00e1rio na m\u00eddia nos \u00faltimos dias. Com a situa\u00e7\u00e3o tensa no Reino Unido em mente, a quest\u00e3o que mais interessou foi se tamb\u00e9m na Su\u00ed\u00e7a devemos esperar por escassez de fornecimento. A necessidade de motoristas profissionais adicionais, que a ASTAG tem destacado h\u00e1 anos, de repente se tornou o foco. O tema foi como a promo\u00e7\u00e3o de jovens talentos poderia ser incentivada. Les Routiers Suisses, a associa\u00e7\u00e3o respons\u00e1vel pelos trabalhadores do transporte rodovi\u00e1rio, posicionou-se afirmando que as empresas de transporte su\u00ed\u00e7as recrutam pessoal demais no exterior. Tamb\u00e9m foi levantada a exig\u00eancia de que s\u00e3o necess\u00e1rias &#8220;melhores condi\u00e7\u00f5es de trabalho&#8221;.<\/p>\n<h5>Para a ASTAG, est\u00e1 claro:<\/h5>\n<ul>\n<li>O fornecimento e a elimina\u00e7\u00e3o na Su\u00ed\u00e7a est\u00e3o sempre garantidos \u2013 gra\u00e7as aos servi\u00e7os confi\u00e1veis, seguros e ambientalmente amig\u00e1veis do setor de transporte rodovi\u00e1rio, incluindo os motoristas.<\/li>\n<li>Com o apoio de muitas empresas associadas, a ASTAG \u2013 como a \u00fanica organiza\u00e7\u00e3o \u2013 tem se empenhado intensamente h\u00e1 anos por mais jovens talentos e profissionais de outras \u00e1reas.<\/li>\n<li>Entre outras coisas, \u00e9 importante mencionar a colabora\u00e7\u00e3o muito pr\u00f3xima e boa com o ex\u00e9rcito (motoristas RS), feiras de emprego, visitas escolares ou a campanha &#8220;Profissionais em Turn\u00ea&#8221;.<\/li>\n<li>A principal raz\u00e3o para a escassez de motoristas \u00e9 a demanda crescente por parte da economia e dos consumidores por servi\u00e7os de transporte.<\/li>\n<li>Al\u00e9m disso, a problem\u00e1tica do tr\u00e1fego pesado afeta fortemente a atratividade da profiss\u00e3o.<\/li>\n<li>A necessidade de motoristas n\u00e3o pode ser totalmente atendida no pa\u00eds, apesar de todos os esfor\u00e7os, assim como no transporte p\u00fablico (estrada, ferrovia).<\/li>\n<li>Para garantir a seguran\u00e7a do fornecimento, s\u00e3o necess\u00e1rios, al\u00e9m dos profissionais qualificados da Su\u00ed\u00e7a, motoristas do exterior.<\/li>\n<li>No entanto, a situa\u00e7\u00e3o \u00e9 melhor do que em outros pa\u00edses. A raz\u00e3o \u00e9 o empenho ativo das empresas de transporte su\u00ed\u00e7as por &#8220;seus&#8221; motoristas e a promo\u00e7\u00e3o de jovens talentos.<\/li>\n<\/ul>\n<p>Para a ASTAG, a promo\u00e7\u00e3o direcionada de jovens talentos continua a ser a principal prioridade. Como mostram o desenvolvimento e as previs\u00f5es, a necessidade de motoristas qualificados e motivados tende a aumentar. A profiss\u00e3o de motorista tem futuro \u2013 assim como todas as profiss\u00f5es no transporte e na log\u00edstica.<\/p>\n<p>Al\u00e9m disso, a ASTAG aposta na continuidade da parceria social de longa data com Les Routiers Suisses. O outono \u00e9 \u2013 como em outros setores \u2013 o per\u00edodo normal para reivindica\u00e7\u00f5es salariais ou negocia\u00e7\u00f5es entre os parceiros sociais. A ASTAG estar\u00e1 disposta a dialogar com Les Routiers Suisses. No entanto, a defini\u00e7\u00e3o efetiva dos sal\u00e1rios \u00e9 de compet\u00eancia exclusiva das empresas de transporte individuais.<\/p>\n<p>Foto: \u00a9 Loginfo24\/Adobe Stock<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diferentemente do Reino Unido, o fornecimento e a elimina\u00e7\u00e3o na Su\u00ed\u00e7a est\u00e3o sempre garantidos \u2013 gra\u00e7as ao alto e confi\u00e1vel compromisso do setor de transporte rodovi\u00e1rio.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11950,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-53060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ASTAG garante o fornecimento na Su\u00ed\u00e7a - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ASTAG garante o fornecimento na Su\u00ed\u00e7a - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Diferentemente do Reino Unido, o fornecimento e a elimina\u00e7\u00e3o na Su\u00ed\u00e7a est\u00e3o sempre garantidos \u2013 gra\u00e7as ao alto e confi\u00e1vel compromisso do setor de transporte rodovi\u00e1rio. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-28T10:09:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_28.10.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1387\" \/>\n\t<meta property=\"og:image:height\" content=\"697\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"ASTAG garante o fornecimento na Su\u00ed\u00e7a\",\"datePublished\":\"2021-10-28T10:09:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/\"},\"wordCount\":579,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_28.10.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/\",\"name\":\"ASTAG garante o fornecimento na Su\u00ed\u00e7a - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_28.10.21.jpg\",\"datePublished\":\"2021-10-28T10:09:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_28.10.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ASTAG_28.10.21.jpg\",\"width\":1387,\"height\":697},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/28\\\/astag-garante-o-fornecimento-na-suica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ASTAG garante o fornecimento na Su\u00ed\u00e7a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ASTAG garante o fornecimento na Su\u00ed\u00e7a - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/","og_locale":"pt_PT","og_type":"article","og_title":"ASTAG garante o fornecimento na Su\u00ed\u00e7a - Loginfo24","og_description":"Diferentemente do Reino Unido, o fornecimento e a elimina\u00e7\u00e3o na Su\u00ed\u00e7a est\u00e3o sempre garantidos \u2013 gra\u00e7as ao alto e confi\u00e1vel compromisso do setor de transporte rodovi\u00e1rio. [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-10-28T10:09:38+00:00","og_image":[{"width":1387,"height":697,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_28.10.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/"},"author":{"name":"","@id":""},"headline":"ASTAG garante o fornecimento na Su\u00ed\u00e7a","datePublished":"2021-10-28T10:09:38+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/"},"wordCount":579,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_28.10.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/","name":"ASTAG garante o fornecimento na Su\u00ed\u00e7a - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_28.10.21.jpg","datePublished":"2021-10-28T10:09:38+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_28.10.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ASTAG_28.10.21.jpg","width":1387,"height":697},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/28\/astag-garante-o-fornecimento-na-suica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"ASTAG garante o fornecimento na Su\u00ed\u00e7a"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/53060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=53060"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/53060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/11950"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=53060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=53060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=53060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}