{"id":52694,"date":"2021-10-14T20:50:47","date_gmt":"2021-10-14T18:50:47","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/"},"modified":"2021-10-14T20:50:47","modified_gmt":"2021-10-14T18:50:47","slug":"a-onomotion-participa-no-programa-de-trainees-mobilidade-verde","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/","title":{"rendered":"A ONOMOTION participa no programa de trainees &#8220;Mobilidade Verde&#8221;"},"content":{"rendered":"<h5><strong>A ONOMOTION GmbH, Daimler Truck, DB Schenker, Lufthansa Cargo, Lufthansa Innovation Hub e time:matters oferecem a partir de abril a oportunidade para mestrandos e mestrandas de trabalharem em solu\u00e7\u00f5es para uma a\u00e7\u00e3o mais sustent\u00e1vel e orientada para o futuro na ind\u00fastria de log\u00edstica e mobilidade. O novo programa come\u00e7a com o t\u00edtulo &#8220;Trainee de Mobilidade Verde&#8221;.<\/strong><\/h5>\n<p>(Berlim) Este \u00e9 o primeiro programa de trainees em que os trainees obt\u00eam uma vis\u00e3o de diferentes empresas e que coloca uma ind\u00fastria sustent\u00e1vel no centro das aten\u00e7\u00f5es.<\/p>\n<p>Durante o per\u00edodo do programa de dois anos, os participantes trabalham em quatro projetos em diferentes empresas parceiras \u2013 desde startups at\u00e9 empresas de atua\u00e7\u00e3o internacional. Eles mergulham profundamente nas mais recentes tend\u00eancias de sustentabilidade e conhecem os desafios da ind\u00fastria de mobilidade e log\u00edstica. Atrav\u00e9s da colabora\u00e7\u00e3o de diversas empresas dentro das cadeias de transporte, surge uma ampla gama de temas \u2013 desde uma melhor interconex\u00e3o entre si at\u00e9 rotas de transporte mais eficientes e projetos sobre combust\u00edveis sustent\u00e1veis para avia\u00e7\u00e3o (Sustainable Aviation Fuel). Assim, os trainees adquirem as ferramentas necess\u00e1rias para impulsionar solu\u00e7\u00f5es para uma transi\u00e7\u00e3o sustent\u00e1vel em dire\u00e7\u00e3o a uma economia mais ecol\u00f3gica.<\/p>\n<h5><strong>O Lufthansa Innovation Hub coordena o programa<\/strong><\/h5>\n<p>A ideia para o programa \u00e9 da Deutsche Lufthansa AG. A coordena\u00e7\u00e3o e a elabora\u00e7\u00e3o do conte\u00fado do programa s\u00e3o de responsabilidade do Lufthansa Innovation Hub. O programa oferece muitos benef\u00edcios tanto para os trainees quanto para as empresas envolvidas. Al\u00e9m dos desafios individuais das empresas, os trainees conhecem diferentes formas de trabalho, abordagens de solu\u00e7\u00e3o e culturas empresariais. Al\u00e9m disso, eles t\u00eam a grande oportunidade de contribuir para o desenvolvimento de uma &#8220;ind\u00fastria de mobilidade mais verde&#8221;.<\/p>\n<h5><strong>As empresas selecionam os trainees em conjunto<\/strong><\/h5>\n<p>Neste programa, pela primeira vez, a ideia da economia compartilhada \u00e9 aplicada \u00e0 gest\u00e3o de talentos. As empresas selecionam os trainees em conjunto e s\u00e3o respons\u00e1veis pela estrutura\u00e7\u00e3o do programa. Elas, por sua vez, beneficiam-se de talentos que desenvolvem uma compreens\u00e3o da ind\u00fastria de mobilidade como um todo e de diferentes modelos de neg\u00f3cios, pensando em solu\u00e7\u00f5es integradas.<\/p>\n<h5><strong>As empresas parceiras assumem a sua responsabilidade<\/strong><\/h5>\n<p>As empresas parceiras sublinham com a sua participa\u00e7\u00e3o no programa o seu compromisso com uma ind\u00fastria orientada para o futuro e mais sustent\u00e1vel, e assumem a responsabilidade de minimizar os impactos das suas atividades empresariais no meio ambiente. Cada empresa enfrenta desafios diferentes, mas o que une todas elas \u00e9 a tarefa de desenvolver solu\u00e7\u00f5es para uma a\u00e7\u00e3o sustent\u00e1vel e orientada para o futuro. Colabora\u00e7\u00e3o, interc\u00e2mbio, aprender umas com as outras: esta mentalidade \u00e9 implementada de forma consistente neste conceito de forma\u00e7\u00e3o de novos talentos.<\/p>\n<p>De sexta-feira, 15 de outubro a segunda-feira, 15 de novembro, mestrandos e mestrandas interessados podem se inscrever atrav\u00e9s da p\u00e1gina inicial <a href=\"https:\/\/www.greenmobilitytrainee.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.greenmobilitytrainee.de<\/a>.<\/p>\n<p>O programa de trainees come\u00e7a em 1 de abril de 2022.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ONOMOTION GmbH, Daimler Truck, DB Schenker, Lufthansa Cargo, Lufthansa Innovation Hub e time:matters oferecem a partir de abril a oportunidade para mestrandos e mestrandas de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":12103,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-52694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A ONOMOTION participa no programa de trainees &quot;Mobilidade Verde&quot; - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A ONOMOTION participa no programa de trainees &quot;Mobilidade Verde&quot; - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A ONOMOTION GmbH, Daimler Truck, DB Schenker, Lufthansa Cargo, Lufthansa Innovation Hub e time:matters oferecem a partir de abril a oportunidade para mestrandos e mestrandas de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-14T18:50:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ONOMOTION_14.10.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"869\" \/>\n\t<meta property=\"og:image:height\" content=\"451\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"A ONOMOTION participa no programa de trainees &#8220;Mobilidade Verde&#8221;\",\"datePublished\":\"2021-10-14T18:50:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/\"},\"wordCount\":525,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ONOMOTION_14.10.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/\",\"name\":\"A ONOMOTION participa no programa de trainees \\\"Mobilidade Verde\\\" - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ONOMOTION_14.10.21.jpg\",\"datePublished\":\"2021-10-14T18:50:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ONOMOTION_14.10.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/ONOMOTION_14.10.21.jpg\",\"width\":869,\"height\":451},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/10\\\/14\\\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A ONOMOTION participa no programa de trainees &#8220;Mobilidade Verde&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A ONOMOTION participa no programa de trainees \"Mobilidade Verde\" - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/","og_locale":"pt_PT","og_type":"article","og_title":"A ONOMOTION participa no programa de trainees \"Mobilidade Verde\" - Loginfo24","og_description":"A ONOMOTION GmbH, Daimler Truck, DB Schenker, Lufthansa Cargo, Lufthansa Innovation Hub e time:matters oferecem a partir de abril a oportunidade para mestrandos e mestrandas de [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-10-14T18:50:47+00:00","og_image":[{"width":869,"height":451,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ONOMOTION_14.10.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/"},"author":{"name":"","@id":""},"headline":"A ONOMOTION participa no programa de trainees &#8220;Mobilidade Verde&#8221;","datePublished":"2021-10-14T18:50:47+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/"},"wordCount":525,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ONOMOTION_14.10.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/","name":"A ONOMOTION participa no programa de trainees \"Mobilidade Verde\" - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ONOMOTION_14.10.21.jpg","datePublished":"2021-10-14T18:50:47+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ONOMOTION_14.10.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/ONOMOTION_14.10.21.jpg","width":869,"height":451},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/10\/14\/a-onomotion-participa-no-programa-de-trainees-mobilidade-verde\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"A ONOMOTION participa no programa de trainees &#8220;Mobilidade Verde&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/52694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=52694"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/52694\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/12103"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=52694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=52694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=52694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}