{"id":27287,"date":"2021-06-28T17:16:56","date_gmt":"2021-06-28T15:16:56","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/"},"modified":"2025-12-15T13:09:09","modified_gmt":"2025-12-15T12:09:09","slug":"erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/","title":{"rendered":"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics"},"content":{"rendered":"<p>Ao longo de sua longa carreira na pfenning logistics, h\u00e1 poucas cargas que Erwin He\u00df n\u00e3o tenha transportado. Como motorista de caminh\u00e3o, ele acompanhou a empresa em sua trajet\u00f3ria de transportadora para prestadora de servi\u00e7os de log\u00edstica contratual de full-service, contribuindo com sua experi\u00eancia de forma valiosa. Durante uma celebra\u00e7\u00e3o, a empresa agradeceu a ele e refletiu sobre sua carreira merit\u00f3ria.<\/p>\n<p>(Heddesheim) Desde crian\u00e7a, Erwin He\u00df sabia que queria trabalhar como motorista. A for\u00e7a e o tamanho dos ve\u00edculos o impressionavam, e n\u00e3o havia vis\u00e3o mais bonita para ele do que dirigir um caminh\u00e3o. Ele obteve sua licen\u00e7a de motorista de caminh\u00e3o no ex\u00e9rcito. Com 21 anos \u2013 n\u00e3o poderia ser antes \u2013 ele realizou seu sonho profissional e se candidatou a um an\u00fancio de jornal na pfenning logistics em Heddesheim. Desde 1981, Erwin He\u00df \u00e9 motorista profissional para o prestador de servi\u00e7os de log\u00edstica contratual. Seu in\u00edcio profissional est\u00e1 totalmente alinhado com a tradi\u00e7\u00e3o da empresa: a pfenning logistics foi fundada na d\u00e9cada de 1930 como uma empresa de transporte de leite, e Erwin He\u00df tamb\u00e9m transportou regularmente leite na regi\u00e3o nos primeiros anos.<\/p>\n<h5><strong>Treinamento para motorista de produtos perigosos<\/strong><\/h5>\n<p>Ap\u00f3s uma semana em que passou no banco do passageiro para aprender as rotas de cor, ele p\u00f4de assumir o volante. Em sua carreira, ele esteve na estrada para v\u00e1rios clientes da pfenning logistics na regi\u00e3o. Ele transportou cargas diversas, incluindo produtos perigosos para um dos maiores e mais antigos clientes da pfenning logistics. Para que pudesse executar esses trabalhos corretamente e sempre estivesse ciente das regulamenta\u00e7\u00f5es e diretrizes atuais, ele participou de v\u00e1rios semin\u00e1rios de forma\u00e7\u00e3o e atualiza\u00e7\u00e3o, incluindo um treinamento para motorista de produtos perigosos, um treinamento para motoristas profissionais, um semin\u00e1rio sobre seguran\u00e7a de carga e um semin\u00e1rio pr\u00e1tico sobre o tema do tac\u00f3grafo digital. Sua confiabilidade e flexibilidade foram, e ainda s\u00e3o, especialmente valorizadas na log\u00edstica.<br \/><div id=\"attachment_12361\" style=\"width: 1439px\" class=\"wp-caption alignnone\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-12361\" class=\"wp-image-12361 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_28.6.21_2.jpg\" alt=\"\" width=\"1429\" height=\"919\" \/><p id=\"caption-attachment-12361\" class=\"wp-caption-text\">Foto: \u00a9 pfenning logistics \/ Legenda da imagem: da esquerda para a direita: Katharina Kumpf, diretora de recursos humanos do grupo pfenning logistics, Erwin He\u00df, homenageado, Manuel Pfenning, Rana Matthias Nag, ambos diretores do grupo pfenning logistics<\/p><\/div>Como motorista, Erwin He\u00df testemunhou os desenvolvimentos empresariais e marcos dos \u00faltimos anos e d\u00e9cadas em primeira m\u00e3o. Tamb\u00e9m houve mudan\u00e7as em seu dia a dia, e ele cita o maior avan\u00e7o em sua profiss\u00e3o como o desenvolvimento t\u00e9cnico dos ve\u00edculos. Onde antes ele conhecia a rota de cor ou usava um mapa na sem\u00e1foro, agora ele tem um sistema de navega\u00e7\u00e3o \u00e0 sua disposi\u00e7\u00e3o. O conforto tamb\u00e9m melhorou significativamente; quem passa at\u00e9 dez horas por dia na cabine do motorista \u00e9 grato pelo ar-condicionado que agora \u00e9 padr\u00e3o e pela ergonomia aprimorada. Ele espera que essas vantagens, que facilitam o dia a dia como motorista profissional, tamb\u00e9m atraiam jovens mulheres e homens no futuro e os inspirem para esse trabalho emocionante.<\/p>\n<h5><strong>Aposentadoria em tr\u00eas anos<\/strong><\/h5>\n<p>Rana Matthias Nag, que entregou a Erwin He\u00df um certificado, uma bolsa surpresa da pfenning e \u2013 de acordo com a prefer\u00eancia de He\u00df por festivais de vinho regionais \u2013 um pacote de vinho da Pfalz em sua homenagem, destacou em um discurso os m\u00e9ritos do motorista: &#8220;Em nome de todo o grupo pfenning logistics, meu mais sincero agradecimento a Erwin He\u00df, que ao longo de seus 40 anos na localiza\u00e7\u00e3o de Heddesheim e arredores conheceu a empresa melhor do que muitos outros. Ele acompanhou nosso caminho de crescimento e mudan\u00e7a de transportadora para prestadora de servi\u00e7os de log\u00edstica contratual. Sua confiabilidade e flexibilidade se mostraram inestim\u00e1veis e indispens\u00e1veis em muitas ocasi\u00f5es.&#8221;Em seu tempo livre, Erwin He\u00df tamb\u00e9m gosta de estar em movimento, seja de bicicleta ou visitando festivais de vinho na regi\u00e3o. Ele gostaria de exercer sua profiss\u00e3o dos sonhos por mais tr\u00eas anos, depois se aposentar\u00e1. No entanto, ele quer continuar em movimento: com um pequeno motorhome, ele pretende viajar. A pfenning logistics j\u00e1 lhe deseja tudo de bom e um vento favor\u00e1vel para suas viagens.<br \/>Foto de capa: \u00a9 pfenning logistics \/ <em><strong>Legenda da imagem:<\/strong> Homenageado Erwin He\u00df diante de seu ve\u00edculo de trabalho<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ao longo de sua longa carreira na pfenning logistics, h\u00e1 poucas cargas que Erwin He\u00df n\u00e3o tenha transportado. Como motorista de caminh\u00e3o, ele acompanhou a empresa<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-27287","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Ao longo de sua longa carreira na pfenning logistics, h\u00e1 poucas cargas que Erwin He\u00df n\u00e3o tenha transportado. Como motorista de caminh\u00e3o, ele acompanhou a empresa [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-28T15:16:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:09:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_28.6.21_2.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics\",\"datePublished\":\"2021-06-28T15:16:56+00:00\",\"dateModified\":\"2025-12-15T12:09:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/\"},\"wordCount\":745,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_28.6.21_2.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/\",\"name\":\"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_28.6.21_2.jpg\",\"datePublished\":\"2021-06-28T15:16:56+00:00\",\"dateModified\":\"2025-12-15T12:09:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_28.6.21_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/pfenning_28.6.21_2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/28\\\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/","og_locale":"pt_PT","og_type":"article","og_title":"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics - Loginfo24","og_description":"Ao longo de sua longa carreira na pfenning logistics, h\u00e1 poucas cargas que Erwin He\u00df n\u00e3o tenha transportado. Como motorista de caminh\u00e3o, ele acompanhou a empresa [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-28T15:16:56+00:00","article_modified_time":"2025-12-15T12:09:09+00:00","og_image":[{"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_28.6.21_2.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/"},"author":{"name":"","@id":""},"headline":"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics","datePublished":"2021-06-28T15:16:56+00:00","dateModified":"2025-12-15T12:09:09+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/"},"wordCount":745,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_28.6.21_2.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/","name":"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_28.6.21_2.jpg","datePublished":"2021-06-28T15:16:56+00:00","dateModified":"2025-12-15T12:09:09+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_28.6.21_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/pfenning_28.6.21_2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/28\/erwin-hes-ha-40-anos-a-trabalhar-para-a-pfenning-logistics\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Erwin He\u00df h\u00e1 40 anos a trabalhar para a pfenning logistics"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/27287","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=27287"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/27287\/revisions"}],"predecessor-version":[{"id":48840,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/27287\/revisions\/48840"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=27287"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=27287"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=27287"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}