{"id":27194,"date":"2021-06-23T17:47:20","date_gmt":"2021-06-23T15:47:20","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/"},"modified":"2025-12-15T13:08:43","modified_gmt":"2025-12-15T12:08:43","slug":"logimat-homenageia-vencedores-do-premio-melhor-produto-2021","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/","title":{"rendered":"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021"},"content":{"rendered":"<p>Os tr\u00eas l\u00edderes que foram premiados este ano no LogiMAT.digital Summer Summit com o renomado pr\u00eamio &#8216;MELHOR PRODUTO&#8217; s\u00e3o Grenzebach, inotec e KNAPP. A cerim\u00f4nia de premia\u00e7\u00e3o foi transmitida ao vivo na noite de 22 de junho de 2021 pela plataforma da comunidade de intralog\u00edstica LogiMAT.digital.<\/p>\n<p>(Munique) Um j\u00fari independente de cientistas e jornalistas selecionou, entre mais de 100 inscri\u00e7\u00f5es recebidas, tr\u00eas dignos vencedores que fazem jus ao nome &#8216;MELHOR PRODUTO&#8217;. Eles atendem de forma excepcional aos crit\u00e9rios de competi\u00e7\u00e3o: aumento de produtividade, economia de custos e racionaliza\u00e7\u00e3o na log\u00edstica.<\/p>\n<p>Os tr\u00eas pr\u00eamios foram entregues durante o &#8216;LogiMAT.digital Summer Summit&#8217; diante das c\u00e2meras aos felizes vencedores Grenzebach Maschinenbau GmbH, inotec Barcode Security e KNAPP AG. O evento do setor ocorreu no centro de exposi\u00e7\u00f5es de Stuttgart e foi transmitido online simultaneamente. Milhares de participantes internacionais da comunidade de intralog\u00edstica LogiMAT.digital tiveram, assim, a oportunidade de acompanhar ao vivo.<\/p>\n<p>Em seu discurso, o Prof. Dr.-Ing. Robert Schulz, chefe do Instituto de Tecnologia de Transporte e Log\u00edstica (IFT) da Universidade de Stuttgart, elogiou n\u00e3o apenas os vencedores, mas tamb\u00e9m todos os candidatos que se inscreveram para o pr\u00eamio este ano, apesar da aus\u00eancia de eventos presenciais, e destacou a capacidade de inova\u00e7\u00e3o do setor.<\/p>\n<h5><strong>Categoria &#8216;Tecnologia de Comissionamento, Transporte, Eleva\u00e7\u00e3o e Armazenagem&#8217; para Grenzebach Maschinenbau GmbH<\/strong><\/h5>\n<p>O OL1200S estabelece a conex\u00e3o entre a opera\u00e7\u00e3o omnidirecional e a localiza\u00e7\u00e3o aut\u00f4noma de transportadores, enquanto monitora a \u00e1rea de opera\u00e7\u00e3o em 360\u00b0. A alta manobrabilidade, combinada com a localiza\u00e7\u00e3o de transportadores, permite que transportadores deslocados sejam coletados de forma aut\u00f4noma em espa\u00e7os reduzidos. N\u00e3o s\u00e3o necess\u00e1rios sensores adicionais no ve\u00edculo, nem dispositivos nos recipientes. Esta\u00e7\u00f5es de transfer\u00eancia e pontos de entrega s\u00e3o completamente dispens\u00e1veis. Os usu\u00e1rios se beneficiam da economia de espa\u00e7o, baixos custos de investimento e uma r\u00e1pida implementa\u00e7\u00e3o. Ajustes em instala\u00e7\u00f5es existentes podem ser feitos de forma r\u00e1pida e descomplicada. Em combina\u00e7\u00e3o com a supervis\u00e3o adicional da \u00e1rea de opera\u00e7\u00e3o em tr\u00eas dimens\u00f5es, o OL1200S tamb\u00e9m detecta obst\u00e1culos no caminho, dependendo da velocidade, de todas as dire\u00e7\u00f5es de movimento e da carga. Isso ajuda os usu\u00e1rios a evitar danos durante o transporte. Dados de imagem esquematizados armazenados permitem uma an\u00e1lise de falhas e uma otimiza\u00e7\u00e3o direcionada dos processos. Com este pacote completo de servi\u00e7os, o OL1200S torna o transporte aut\u00f4nomo de pe\u00e7as, especialmente o transporte de longos transportadores, particularmente eficiente.<\/p>\n<h5><strong>Categoria &#8216;Identifica\u00e7\u00e3o, Tecnologia de Embalagem e Carregamento, Seguran\u00e7a de Carga&#8217; para inotec Barcode Security GmbH<\/strong><\/h5>\n<p>Com o inotec RFID Inmould Label, \u00e9 poss\u00edvel uma marca\u00e7\u00e3o permanente de paletes de pl\u00e1stico, recipientes e bandejas, como a nova GS1-Smart-Box. As etiquetas Inmould s\u00e3o resistentes ao desgaste, luz UV, produtos de limpeza, \u00e1cidos fracos e outros produtos qu\u00edmicos. Al\u00e9m disso, elas est\u00e3o permanentemente unidas ao recipiente e s\u00e3o absolutamente higi\u00eanicas. Assim, atendem tamb\u00e9m aos altos requisitos de higiene da ind\u00fastria aliment\u00edcia e farmac\u00eautica e s\u00e3o certificadas GS1 para a marca\u00e7\u00e3o de recipientes de carne em toda a ind\u00fastria. A etiqueta de camada \u00fanica, com c\u00f3digo de barras integrado, antena RFID impressa e chip RFID montado, \u00e9 unida de forma indissoci\u00e1vel ao transportador no processo de moldagem por inje\u00e7\u00e3o. Assim, o tag RFID se torna uma parte integral do transportador e, portanto, \u00e0 prova de manipula\u00e7\u00e3o. As solu\u00e7\u00f5es RFID Inmould tamb\u00e9m s\u00e3o perfeitas para ler dados \u00e0 dist\u00e2ncia ou sem contato visual.<\/p>\n<h5><strong>Categoria &#8216;Software, Comunica\u00e7\u00e3o, TI&#8217; para KNAPP AG<\/strong><\/h5>\n<p>O ivii.smartdesk \u00e9 uma esta\u00e7\u00e3o de montagem equipada com um sistema de reconhecimento e processamento de imagens. Assim, os trabalhos de montagem s\u00e3o 100% suportados por software. O sistema de feedback em tempo real do ivii.smartdesk monitora cada etapa do trabalho, o que possibilita uma estrat\u00e9gia de zero erros e rastreabilidade cont\u00ednua no processo de montagem \u2013 por exemplo, na produ\u00e7\u00e3o. O sistema de reconhecimento e processamento de imagens captura todos os componentes necess\u00e1rios para a montagem. Cada etapa do trabalho \u00e9 verificada e validada. A pr\u00f3xima etapa s\u00f3 pode seguir quando a anterior for reconhecida como &#8216;ok&#8217; pelo sistema de processamento de imagens.<\/p>\n<p>Dessa forma, \u00e9 garantido que todos os componentes sejam montados na ordem e qualidade corretas. O funcion\u00e1rio recebe, gra\u00e7as ao sistema de feedback em tempo real, um retorno imediato sobre a qualidade de sua execu\u00e7\u00e3o. Uma abordagem l\u00fadica das etapas de trabalho \u2013 a gamifica\u00e7\u00e3o \u2013 \u00e9 motivadora para os funcion\u00e1rios e contribui para uma organiza\u00e7\u00e3o que aprende e para uma alta satisfa\u00e7\u00e3o dos colaboradores. O ivii.smartdesk tamb\u00e9m pode ser utilizado na recep\u00e7\u00e3o de mercadorias, para verificar se todos os produtos foram entregues na quantidade e qualidade correspondentes. A entrega \u00e9 documentada e armazenada, facilitando a obriga\u00e7\u00e3o de prova posterior. Isso n\u00e3o apenas economiza tempo, mas tamb\u00e9m reduz os custos de reclama\u00e7\u00f5es.<\/p>\n<p>Foto: \u00a9 LogiMAT<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os tr\u00eas l\u00edderes que foram premiados este ano no LogiMAT.digital Summer Summit com o renomado pr\u00eamio &#8216;MELHOR PRODUTO&#8217; s\u00e3o Grenzebach, inotec e KNAPP. A cerim\u00f4nia de<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-27194","post","type-post","status-publish","format-standard","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Os tr\u00eas l\u00edderes que foram premiados este ano no LogiMAT.digital Summer Summit com o renomado pr\u00eamio &#8216;MELHOR PRODUTO&#8217; s\u00e3o Grenzebach, inotec e KNAPP. A cerim\u00f4nia de [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-23T15:47:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:08:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021\",\"datePublished\":\"2021-06-23T15:47:20+00:00\",\"dateModified\":\"2025-12-15T12:08:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/\"},\"wordCount\":883,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/\",\"name\":\"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2021-06-23T15:47:20+00:00\",\"dateModified\":\"2025-12-15T12:08:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/23\\\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/","og_locale":"pt_PT","og_type":"article","og_title":"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021 - Loginfo24","og_description":"Os tr\u00eas l\u00edderes que foram premiados este ano no LogiMAT.digital Summer Summit com o renomado pr\u00eamio &#8216;MELHOR PRODUTO&#8217; s\u00e3o Grenzebach, inotec e KNAPP. A cerim\u00f4nia de [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-23T15:47:20+00:00","article_modified_time":"2025-12-15T12:08:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/"},"author":{"name":"","@id":""},"headline":"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021","datePublished":"2021-06-23T15:47:20+00:00","dateModified":"2025-12-15T12:08:43+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/"},"wordCount":883,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/","name":"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2021-06-23T15:47:20+00:00","dateModified":"2025-12-15T12:08:43+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/23\/logimat-homenageia-vencedores-do-premio-melhor-produto-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"LogiMAT homenageia vencedores do PR\u00caMIO MELHOR PRODUTO 2021"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/27194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=27194"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/27194\/revisions"}],"predecessor-version":[{"id":48654,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/27194\/revisions\/48654"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=27194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=27194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=27194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}