{"id":26878,"date":"2021-06-10T18:05:35","date_gmt":"2021-06-10T16:05:35","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/"},"modified":"2025-12-15T13:07:17","modified_gmt":"2025-12-15T12:07:17","slug":"tres-dias-de-programacao-completa-no-logimat-digital-summer-summit","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/","title":{"rendered":"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit"},"content":{"rendered":"<p>Tr\u00eas dias de programa\u00e7\u00e3o completa com a qualidade habitual da LogiMAT. \u00c9 tradi\u00e7\u00e3o e fator de sucesso da marca LogiMAT \u2013 o programa desafiador em n\u00edvel de congresso. Destaques do programa, como a entrega do pr\u00eamio MELHOR PRODUTO, o dia IFT e s\u00e9ries de palestras que oferecem recomenda\u00e7\u00f5es pr\u00e1ticas imediatas sobre temas desafiadores, ser\u00e3o transmitidos online de Stuttgart atrav\u00e9s do<\/p>\n<p>(Stuttgart) Embora a feira especializada em intralog\u00edstica LogiMAT, Stuttgart, tenha sido adiada para mar\u00e7o de 2022, a comunidade internacional de intralog\u00edstica poder\u00e1 participar digitalmente de destaques populares do programa de eventos de 22 a 24 de junho. Estes ser\u00e3o transmitidos ao vivo na plataforma www.logimat.digital. Qualquer interessado pode se registrar facilmente, sem compromisso e gratuitamente como participante e, como de costume, aproveitar o valor agregado com a qualidade comprovada da LogiMAT para si e para sua empresa.<\/p>\n<h5><strong>Vencedores do MELHOR PRODUTO 2020 ser\u00e3o homenageados posteriormente<\/strong><\/h5>\n<p>O &#8220;LogiMAT.digital Summer Summit&#8221; ser\u00e1 inaugurado no dia 22 de junho \u00e0s 10:00. O primeiro dia oferece um talk show di\u00e1rio da LogiMAT, uma s\u00e9rie de palestras empolgantes com foco em FTS e estar\u00e1 totalmente voltado para a entrega do pr\u00eamio MELHOR PRODUTO. A jornalista especializada Anja Seemann conduzir\u00e1 o programa durante os tr\u00eas dias e receber\u00e1 os vencedores de 2020 \u2013 incluindo duas startups \u2013 para entregar-lhes o pr\u00eamio, o que n\u00e3o foi poss\u00edvel no ano passado. Eles abordar\u00e3o a ambi\u00e7\u00e3o inovadora de suas solu\u00e7\u00f5es \u2013 especialmente \u00e0 luz dos desafios atuais, onde transpar\u00eancia e efici\u00eancia est\u00e3o sendo testadas. Os vencedores apresentar\u00e3o as solu\u00e7\u00f5es premiadas: a Kern AG da Su\u00ed\u00e7a estar\u00e1 representada com o produto: &#8220;PackOnTime 2box&#8221; na categoria &#8220;Identifica\u00e7\u00e3o, tecnologia de embalagem e carregamento, seguran\u00e7a de carga&#8221;, a Wiferion GmbH com o produto &#8220;etaLINK 12000&#8221; na categoria &#8220;Tecnologia de coleta, transporte, eleva\u00e7\u00e3o e armazenamento&#8221; e, por \u00faltimo, mas n\u00e3o menos importante, a MotionMiners GmbH com o produto: &#8220;Manual Process Intelligence&#8221; na categoria &#8220;Software, comunica\u00e7\u00e3o, TI&#8221;.<\/p>\n<h5><strong>Esp\u00edrito inovador do setor inabal\u00e1vel<\/strong><\/h5>\n<p>No dia 22 de junho, \u00e0s 19:00 (CEST), ocorrer\u00e1 a cerim\u00f4nia de entrega do pr\u00eamio MELHOR PRODUTO 2021 com os vencedores deste ano. Tamb\u00e9m neste ano, os expositores da LogiMAT foram convidados a se inscrever com seus produtos e solu\u00e7\u00f5es inovadoras que contribuem para a racionaliza\u00e7\u00e3o, economia de custos e aumento da produtividade na log\u00edstica interna. Mais de cem empresas atenderam ao convite do organizador da feira. Uma tarefa desafiadora para o j\u00fari, que teve que examinar cuidadosamente e avaliar criticamente as inscri\u00e7\u00f5es apresentadas. &#8220;Foi uma grande alegria ver que, especialmente ou talvez ainda mais nestes tempos, o esp\u00edrito inovador do setor est\u00e1 inabal\u00e1vel. Quem identifica fatores de perturba\u00e7\u00e3o decisivos como pontos fracos e tem uma solu\u00e7\u00e3o para isso, avan\u00e7a o setor. Isso encoraja a olhar para o futuro&#8221;, disse o Prof. Dr.-Ing. Johannes Fottner, titular da c\u00e1tedra de Tecnologia de Transporte e Log\u00edstica da Universidade T\u00e9cnica de Munique e presidente do j\u00fari. As empresas premiadas contribuem com seus produtos para processos seguros, para uma adapta\u00e7\u00e3o mais f\u00e1cil \u00e0s mudan\u00e7as, para a melhoria da efici\u00eancia e, portanto, em \u00faltima an\u00e1lise, para o aumento da produtividade na intralog\u00edstica.<\/p>\n<h5><strong>Mix de talk shows e s\u00e9ries de palestras com especialistas<\/strong><\/h5>\n<p>Nos dois dias seguintes, 23 e 24 de junho, tamb\u00e9m ser\u00e1 oferecido um mix de talk shows de alto n\u00edvel e s\u00e9ries de palestras com os principais especialistas do setor e da academia. A gama de temas varia desde a &#8220;apresenta\u00e7\u00e3o do novo guia VDI para planejamento de FTS&#8221; at\u00e9 &#8220;Sele\u00e7\u00e3o e implementa\u00e7\u00e3o \u00e1gil de sistemas WMS&#8221; e &#8220;G\u00eameos digitais na comissionamento&#8221; ou &#8220;Log\u00edstica de produ\u00e7\u00e3o orientada ao fluxo de valor&#8221; at\u00e9 o tema &#8220;Otimiza\u00e7\u00e3o da cadeia de suprimentos digital atrav\u00e9s de tecnologias AutoID&#8221;. N\u00e3o podem faltar as sequ\u00eancias do dia IFT sob o conhecido lema: &#8220;Intralog\u00edstica \u2013 Futuro \u2013 Tecnologia&#8221;. Este evento \u00e9 tradicionalmente realizado todos os anos pelo Instituto de Tecnologia de Transporte e Log\u00edstica (IFT) da Universidade de Stuttgart na LogiMAT e relata abordagens de solu\u00e7\u00f5es industriais e orientadas \u00e0 pesquisa. No evento digital na quarta-feira, 23 de junho, haver\u00e1 uma s\u00e9rie de palestras de uma hora sobre &#8220;T\u00e9cnicas inovadoras para fornecimento descentralizado de materiais&#8221; ou, no \u00e2mbito de uma discuss\u00e3o em painel, sobre o tema &#8220;Plug &amp; Supply na intralog\u00edstica \u2013 vis\u00e3o do futuro ou realidade vivida?&#8221;. A maioria dos eventos do LogiMAT.digital Summer Summit ser\u00e1 traduzida simultaneamente para o ingl\u00eas.<br \/>&#8220;Mesmo que n\u00e3o possamos receber visitantes profissionais no local nesta data, transmitiremos ao vivo do centro de exposi\u00e7\u00f5es de Stuttgart nesses dias. Com isso, queremos transmitir a sensa\u00e7\u00e3o LogiMAT \u00e0queles que se conectarem durante os tr\u00eas dias. Isso estabelece a ponte digital para a LogiMAT de Bangkok em novembro de 2021 at\u00e9 Stuttgart em mar\u00e7o de 2022, que estamos preparando paralelamente com total empenho como eventos presenciais&#8221;, disse Peter Kazander, diretor-geral da EUROEXPO Messe- und Kongress-GmbH.<br \/>Foto: \u00a9 Loginfo24\/Adobe Stock<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tr\u00eas dias de programa\u00e7\u00e3o completa com a qualidade habitual da LogiMAT. \u00c9 tradi\u00e7\u00e3o e fator de sucesso da marca LogiMAT \u2013 o programa desafiador em n\u00edvel<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-26878","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Tr\u00eas dias de programa\u00e7\u00e3o completa com a qualidade habitual da LogiMAT. \u00c9 tradi\u00e7\u00e3o e fator de sucesso da marca LogiMAT \u2013 o programa desafiador em n\u00edvel [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-10T16:05:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:07:17+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit\",\"datePublished\":\"2021-06-10T16:05:35+00:00\",\"dateModified\":\"2025-12-15T12:07:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/\"},\"wordCount\":875,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/\",\"name\":\"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2021-06-10T16:05:35+00:00\",\"dateModified\":\"2025-12-15T12:07:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/06\\\/10\\\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/","og_locale":"pt_PT","og_type":"article","og_title":"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit - Loginfo24","og_description":"Tr\u00eas dias de programa\u00e7\u00e3o completa com a qualidade habitual da LogiMAT. \u00c9 tradi\u00e7\u00e3o e fator de sucesso da marca LogiMAT \u2013 o programa desafiador em n\u00edvel [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-06-10T16:05:35+00:00","article_modified_time":"2025-12-15T12:07:17+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/"},"author":{"name":"","@id":""},"headline":"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit","datePublished":"2021-06-10T16:05:35+00:00","dateModified":"2025-12-15T12:07:17+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/"},"wordCount":875,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/","name":"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2021-06-10T16:05:35+00:00","dateModified":"2025-12-15T12:07:17+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/06\/10\/tres-dias-de-programacao-completa-no-logimat-digital-summer-summit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Tr\u00eas dias de programa\u00e7\u00e3o completa no LogiMAT.digital Summer Summit"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26878","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=26878"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26878\/revisions"}],"predecessor-version":[{"id":48030,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26878\/revisions\/48030"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=26878"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=26878"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=26878"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}