{"id":26632,"date":"2022-01-19T17:15:02","date_gmt":"2022-01-19T16:15:02","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/"},"modified":"2022-01-19T17:15:02","modified_gmt":"2022-01-19T16:15:02","slug":"correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/","title":{"rendered":"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021"},"content":{"rendered":"<h5><strong>2021 trouxe \u00e0 Correios da \u00c1ustria n\u00e3o apenas um novo recorde de pacotes transportados no pa\u00eds. No total, a empresa movimentou quase meia bilh\u00e3o de pacotes no ano passado \u2013 o que representa um aumento de nove por cento. No entanto, a maioria das remessas n\u00e3o foi transportada no mercado dom\u00e9stico da \u00c1ustria, mas atrav\u00e9s da sua subsidi\u00e1ria de pacotes Aras Kargo na Turquia: ou seja, 217 milh\u00f5es de pacotes. Para compara\u00e7\u00e3o: na \u00c1ustria, no ano anterior, foram transportados 184 milh\u00f5es de pacotes \u2013 um aumento de onze por cento.<\/strong><\/h5>\n<p>(Wien) A Correios da \u00c1ustria transporta pacotes e paletes em um total de nove pa\u00edses. E isso inclui a B\u00f3snia e Herzegovina, Bulg\u00e1ria, Cro\u00e1cia, Montenegro, \u00c1ustria, S\u00e9rvia, Eslov\u00e1quia, Hungria e Turquia. &#8220;Em todas as subsidi\u00e1rias, o volume de pacotes em 2021 totalizou 452 milh\u00f5es de unidades. A maior parte disso na \u00c1ustria e na Turquia. Mas nossas subsidi\u00e1rias na Europa Central e Oriental tamb\u00e9m registraram um aumento significativo de 16 por cento. L\u00e1, transportamos quase 52 milh\u00f5es de pacotes no ano passado&#8221;, disse DI Peter Umundum, membro do conselho de pacotes e log\u00edstica da Correios da \u00c1ustria AG, que enfatiza que o crescimento nos mercados estrangeiros, assim como na \u00c1ustria, deve-se principalmente \u00e0 crescente tend\u00eancia do com\u00e9rcio eletr\u00f4nico.<\/p>\n<h5><strong>Os volumes de vendas das subsidi\u00e1rias individuais:<\/strong><br \/>\n<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-16833\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_19.1.22.jpg\" alt=\"\" width=\"1024\" height=\"531\" \/><\/h5>\n<p>Peter Umundum continuou: &#8220;Este novo recorde de pacotes nos deixa muito satisfeitos, tamb\u00e9m investimos massivamente em nossa rede internacional para estarmos preparados para aumentos de volume no futuro. Al\u00e9m disso, focamos fortemente na orienta\u00e7\u00e3o ao cliente e em solu\u00e7\u00f5es de entrega convenientes, para sermos sempre a primeira escolha tanto para remetentes quanto para destinat\u00e1rios.&#8221;<\/p>\n<h5><strong>Investimentos em infraestrutura<\/strong><\/h5>\n<p>No ano passado, por exemplo, a Aras Kargo na Turquia automatizou sete centros de log\u00edstica em todo o pa\u00eds, aumentando a capacidade de triagem em 30 por cento. A rede existente de Out of Home foi mais que dobrada para cerca de 2.400 locais. Em todas as subsidi\u00e1rias, as op\u00e7\u00f5es de recebimento de pacotes foram ampliadas e a orienta\u00e7\u00e3o ao cliente foi refor\u00e7ada. No total, em 2021, 1.845 novos locais para recebimento de pacotes foram inaugurados no Sudeste da Europa.<\/p>\n<p>2022 tamb\u00e9m ser\u00e1 marcado por investimentos direcionados. A Express One na Hungria colocar\u00e1 novas instala\u00e7\u00f5es de triagem em opera\u00e7\u00e3o, na Eslov\u00e1quia a tecnologia de transporte nos centros de log\u00edstica ser\u00e1 expandida e os terminais de pacotes tamb\u00e9m ser\u00e3o ampliados em toda a CEE. Na Aras Kargo, a capacidade de triagem nos centros de log\u00edstica ser\u00e1 aumentada em mais 30 por cento, al\u00e9m de expandir e renovar a frota de entrega.<\/p>\n<p>Foto\/Grafik: \u00a9 Correios da \u00c1ustria<\/p>\n","protected":false},"excerpt":{"rendered":"<p>2021 trouxe \u00e0 Correios da \u00c1ustria n\u00e3o apenas um novo recorde de pacotes transportados no pa\u00eds. No total, a empresa movimentou quase meia bilh\u00e3o de pacotes<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11241,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-26632","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021 - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021 - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"2021 trouxe \u00e0 Correios da \u00c1ustria n\u00e3o apenas um novo recorde de pacotes transportados no pa\u00eds. No total, a empresa movimentou quase meia bilh\u00e3o de pacotes [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-19T16:15:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_19.1.22_Titel.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1283\" \/>\n\t<meta property=\"og:image:height\" content=\"725\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021\",\"datePublished\":\"2022-01-19T16:15:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_19.1.22_Titel.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/\",\"name\":\"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021 - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_19.1.22_Titel.jpg\",\"datePublished\":\"2022-01-19T16:15:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_19.1.22_Titel.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_19.1.22_Titel.jpg\",\"width\":1283,\"height\":725},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/19\\\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021 - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/","og_locale":"pt_PT","og_type":"article","og_title":"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021 - Loginfo24","og_description":"2021 trouxe \u00e0 Correios da \u00c1ustria n\u00e3o apenas um novo recorde de pacotes transportados no pa\u00eds. No total, a empresa movimentou quase meia bilh\u00e3o de pacotes [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-01-19T16:15:02+00:00","og_image":[{"width":1283,"height":725,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_19.1.22_Titel.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/"},"author":{"name":"","@id":""},"headline":"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021","datePublished":"2022-01-19T16:15:02+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_19.1.22_Titel.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/","url":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/","name":"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021 - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_19.1.22_Titel.jpg","datePublished":"2022-01-19T16:15:02+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_19.1.22_Titel.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_19.1.22_Titel.jpg","width":1283,"height":725},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/19\/correios-da-austria-transportam-cerca-de-500-milhoes-de-pacotes-em-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Correios da \u00c1ustria transportam cerca de 500 milh\u00f5es de pacotes em 2021"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26632","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=26632"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26632\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/11241"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=26632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=26632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=26632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}