{"id":26478,"date":"2022-01-13T18:54:27","date_gmt":"2022-01-13T17:54:27","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/"},"modified":"2022-01-13T18:54:27","modified_gmt":"2022-01-13T17:54:27","slug":"a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/","title":{"rendered":"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI"},"content":{"rendered":"<h5><strong>Como uma associa\u00e7\u00e3o registrada para a promo\u00e7\u00e3o da ind\u00fastria de log\u00edstica de transporte, a Pro Fahrer-Image, sob a tutela do Minist\u00e9rio Federal de Digitaliza\u00e7\u00e3o e Transporte (BMDV), se dedica especialmente a aumentar a valoriza\u00e7\u00e3o da profiss\u00e3o de motorista e a melhorar as condi\u00e7\u00f5es de trabalho para os motoristas.<\/strong><\/h5>\n<p>(Berlim) Al\u00e9m disso, a associa\u00e7\u00e3o tem como objetivo promover a forma\u00e7\u00e3o e qualifica\u00e7\u00e3o de motoristas profissionais no transporte de mercadorias e de passageiros, contribuindo assim para a elimina\u00e7\u00e3o da escassez de motoristas.<\/p>\n<p>&#8220;N\u00e3o h\u00e1 d\u00favida: a competitividade e a capacidade futura da ind\u00fastria de transporte e log\u00edstica alem\u00e3 dependem, entre outras coisas, de qu\u00e3o bem conseguimos conquistar a nova gera\u00e7\u00e3o de amanh\u00e3. Todos n\u00f3s devemos juntos mostrar a essa nova gera\u00e7\u00e3o essas oportunidades futuras e contribuir para que a ind\u00fastria de transporte receba mais reconhecimento&#8221;, explica Andreas Marquardt, presidente da Ag\u00eancia Federal de Transporte de Mercadorias. A Ag\u00eancia Federal pretende, no futuro, disponibilizar sua expertise ao clube em todas as quest\u00f5es relacionadas ao transporte de mercadorias e log\u00edstica \u2013 especialmente quando se trata da atra\u00e7\u00e3o de novos talentos.<\/p>\n<h5><strong>\u00c9 a primeira vez que uma entidade estatal se compromete com a imagem do setor<\/strong><\/h5>\n<p>Prof. Dr. Dirk Engelhardt, presidente da associa\u00e7\u00e3o de apoio PROFI e porta-voz do Bundesverband G\u00fcterkraftverkehr Logistik und Entsorgung (BGL) e.V.: &#8220;Estamos especialmente felizes que a Ag\u00eancia Federal de Transporte de Mercadorias, com sua compet\u00eancia, apoie o PROFI na implementa\u00e7\u00e3o de seus objetivos. \u00c9 a primeira vez que uma entidade estatal se compromete ativamente por uma melhor imagem do setor e mais valoriza\u00e7\u00e3o para nossos motoristas.&#8221; <\/p>\n<p>Mais informa\u00e7\u00f5es sobre a associa\u00e7\u00e3o PROFI \u2013 Pro Fahrer-Image e.V. podem ser encontradas aqui:<\/p>\n<p><a href=\"https:\/\/www.pro-fahrer-image.de\" target=\"_blank\" rel=\"noopener\">www.pro-fahrer-image.de<\/a><\/p>\n<p>Foto: \u00a9 PROFI<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como uma associa\u00e7\u00e3o registrada para a promo\u00e7\u00e3o da ind\u00fastria de log\u00edstica de transporte, a Pro Fahrer-Image, sob a tutela do Minist\u00e9rio Federal de Digitaliza\u00e7\u00e3o e Transporte<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11317,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-26478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Como uma associa\u00e7\u00e3o registrada para a promo\u00e7\u00e3o da ind\u00fastria de log\u00edstica de transporte, a Pro Fahrer-Image, sob a tutela do Minist\u00e9rio Federal de Digitaliza\u00e7\u00e3o e Transporte [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-13T17:54:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGL_13.1.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1218\" \/>\n\t<meta property=\"og:image:height\" content=\"669\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI\",\"datePublished\":\"2022-01-13T17:54:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/\"},\"wordCount\":322,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGL_13.1.22.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/\",\"name\":\"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGL_13.1.22.jpg\",\"datePublished\":\"2022-01-13T17:54:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGL_13.1.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BGL_13.1.22.jpg\",\"width\":1218,\"height\":669},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2022\\\/01\\\/13\\\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/","og_locale":"pt_PT","og_type":"article","og_title":"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI - Loginfo24","og_description":"Como uma associa\u00e7\u00e3o registrada para a promo\u00e7\u00e3o da ind\u00fastria de log\u00edstica de transporte, a Pro Fahrer-Image, sob a tutela do Minist\u00e9rio Federal de Digitaliza\u00e7\u00e3o e Transporte [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-01-13T17:54:27+00:00","og_image":[{"width":1218,"height":669,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGL_13.1.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/"},"author":{"name":"","@id":""},"headline":"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI","datePublished":"2022-01-13T17:54:27+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/"},"wordCount":322,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGL_13.1.22.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/","url":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/","name":"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGL_13.1.22.jpg","datePublished":"2022-01-13T17:54:27+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGL_13.1.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BGL_13.1.22.jpg","width":1218,"height":669},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2022\/01\/13\/a-agencia-federal-de-transporte-de-mercadorias-torna-se-membro-do-profi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"A Ag\u00eancia Federal de Transporte de Mercadorias torna-se membro do PROFI"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=26478"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26478\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/11317"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=26478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=26478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=26478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}