{"id":26267,"date":"2021-12-21T19:24:16","date_gmt":"2021-12-21T18:24:16","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/"},"modified":"2021-12-21T19:24:16","modified_gmt":"2021-12-21T18:24:16","slug":"riege-com-software-de-zoll-scope-preparado-para-atlas-impost","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/","title":{"rendered":"Riege com software de Zoll Scope preparado para ATLAS-IMPOST"},"content":{"rendered":"<h5><strong>A partida para o procedimento ATLAS-IMPOST ocorreu j\u00e1 em 01.07.2021 com a decis\u00e3o do <\/strong><strong>pacote digital de IVA<\/strong><strong>. A elimina\u00e7\u00e3o da isen\u00e7\u00e3o de IVA para a importa\u00e7\u00e3o de pequenas remessas abriu caminho para o novo procedimento de declara\u00e7\u00e3o aduaneira. Ao mesmo tempo, entraram em vigor altera\u00e7\u00f5es na legisla\u00e7\u00e3o aduaneira europeia. Consequentemente, a partir de janeiro de 2022, tamb\u00e9m ser\u00e1 necess\u00e1rio declarar mercadorias de baixo valor na alf\u00e2ndega, o que at\u00e9 agora era incomum, especialmente na \u00e1rea do com\u00e9rcio eletr\u00f4nico.<\/strong><\/h5>\n<p> ATLAS-IMPOST dever\u00e1 entrar em opera\u00e7\u00e3o em 15 de janeiro de 2022. A aplica\u00e7\u00e3o destina-se \u00e0 declara\u00e7\u00e3o de &#8220;remessas de baixo valor&#8221; at\u00e9 o limite de 150 euros. Anteriormente, o limite inferior para o valor das mercadorias em bens importados era de 22 euros. Todas as mercadorias cujo valor esteja abaixo desse limite estavam isentas de IVA. A crescente taxa de aumento nas remessas da \u00e1rea de com\u00e9rcio eletr\u00f4nico (lojas online) e a sobrecarga resultante do sistema automatizado de tarifa\u00e7\u00e3o e processamento aduaneiro da alf\u00e2ndega alem\u00e3 (ATLAS) tornaram a introdu\u00e7\u00e3o de uma aplica\u00e7\u00e3o adicional indispens\u00e1vel. ATLAS-IMPOST deve agora garantir um tratamento eficiente em termos de direitos aduaneiros e de IVA de importa\u00e7\u00e3o para remessas de baixo valor, aliviando assim permanentemente a importa\u00e7\u00e3o atrav\u00e9s do ATLAS. <\/p>\n<h5><strong>Os principais fatos sobre ATLAS-IMPOST<\/strong><\/h5>\n<ul>\n<li>O pacote digital de IVA entrou em vigor em 1 de julho de 2021<\/li>\n<li>ATLAS-IMPOST dever\u00e1 entrar em opera\u00e7\u00e3o em 15 de janeiro de 2022<\/li>\n<li>Declara\u00e7\u00f5es aduaneiras eletr\u00f4nicas agora tamb\u00e9m s\u00e3o necess\u00e1rias para pequenas mercadorias<\/li>\n<li>ATLAS-IMPOST regula a importa\u00e7\u00e3o de pequenas remessas com um valor at\u00e9 150 euros<\/li>\n<\/ul>\n<h5><strong>Requisitos t\u00e9cnicos para ATLAS-IMPOST<\/strong><\/h5>\n<p> Ao contr\u00e1rio do procedimento de declara\u00e7\u00e3o ATLAS anterior, a transmiss\u00e3o eletr\u00f4nica de informa\u00e7\u00f5es no IMPOST \u00e9 realizada atrav\u00e9s de um servi\u00e7o web. O conhecido gateway FTAM n\u00e3o deve ser utilizado para isso. Ao mesmo tempo, a BIN conhecida n\u00e3o ser\u00e1 mais utilizada como assinatura eletr\u00f4nica no IMPOST. Portanto, ser\u00e3o necess\u00e1rios outros crit\u00e9rios de autentica\u00e7\u00e3o. Quem quiser declarar mercadorias de baixo valor atrav\u00e9s da aplica\u00e7\u00e3o web IMPOST a partir de 15 de janeiro de 2022 deve primeiro solicitar o chamado IOSS-ID na alf\u00e2ndega. O n\u00famero de identifica\u00e7\u00e3o do &#8220;Import One-Stop-Shop&#8221; (IOSS) tornou-se especialmente obrigat\u00f3rio para comerciantes online com armaz\u00e9ns ou sede fora da UE com a decis\u00e3o do pacote digital de IVA. Para obter um n\u00famero IOSS, cada empresa deve se registrar uma vez na autoridade fiscal competente. Na Alemanha, o Escrit\u00f3rio Federal de Impostos (BZSt) \u00e9 respons\u00e1vel pelo registro. Mais informa\u00e7\u00f5es sobre a implementa\u00e7\u00e3o t\u00e9cnica est\u00e3o dispon\u00edveis nas p\u00e1ginas da alf\u00e2ndega. <\/p>\n<h5><strong>Utilizar Scope para declara\u00e7\u00f5es ATLAS-IMPOST<\/strong><\/h5>\n<p> Para os usu\u00e1rios do software de Zoll <a href=\"https:\/\/www.riege.com\/de\/scope\/zoll\/\">Scope<\/a>, nada muda no procedimento de importa\u00e7\u00e3o ATLAS, apesar do pacote digital de IVA. Atrav\u00e9s do m\u00f3dulo ATLAS integrado, as declara\u00e7\u00f5es aduaneiras podem continuar a ser feitas como SumA com base em modelos armazenados ou como procedimentos individuais. Al\u00e9m disso, o Scope verifica se os documentos necess\u00e1rios para a declara\u00e7\u00e3o na alf\u00e2ndega est\u00e3o faltando e informa automaticamente sobre altera\u00e7\u00f5es relacionadas ao n\u00famero tarif\u00e1rio no procedimento de declara\u00e7\u00e3o aduaneira. &#8220;ATLAS-IMPOST traz algumas inova\u00e7\u00f5es significativas na aplica\u00e7\u00e3o aduaneira alem\u00e3. Por exemplo, a transmiss\u00e3o FTAM, que agora est\u00e1 obsoleta, ser\u00e1 modernizada atrav\u00e9s da transmiss\u00e3o via WebService. Espera-se que todos os outros procedimentos aduaneiros sejam gradualmente migrados para a tecnologia WebService, pelo menos quando esses procedimentos forem atualizados no contexto da implementa\u00e7\u00e3o adicional do UZK,&#8221; afirma Dirk Heidenfelder, Gerente de Produto de Aduanas, Riege Software. <br \/> Foto: \u00a9 Riege<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partida para o procedimento ATLAS-IMPOST ocorreu j\u00e1 em 01.07.2021 com a decis\u00e3o do pacote digital de IVA. A elimina\u00e7\u00e3o da isen\u00e7\u00e3o de IVA para a<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11403,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-26267","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Riege com software de Zoll Scope preparado para ATLAS-IMPOST - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Riege com software de Zoll Scope preparado para ATLAS-IMPOST - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A partida para o procedimento ATLAS-IMPOST ocorreu j\u00e1 em 01.07.2021 com a decis\u00e3o do pacote digital de IVA. A elimina\u00e7\u00e3o da isen\u00e7\u00e3o de IVA para a [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-21T18:24:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Riege_21.12.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1410\" \/>\n\t<meta property=\"og:image:height\" content=\"794\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Riege com software de Zoll Scope preparado para ATLAS-IMPOST\",\"datePublished\":\"2021-12-21T18:24:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/\"},\"wordCount\":635,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Riege_21.12.21.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/\",\"name\":\"Riege com software de Zoll Scope preparado para ATLAS-IMPOST - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Riege_21.12.21.jpg\",\"datePublished\":\"2021-12-21T18:24:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Riege_21.12.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Riege_21.12.21.jpg\",\"width\":1410,\"height\":794},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/21\\\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Riege com software de Zoll Scope preparado para ATLAS-IMPOST\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Riege com software de Zoll Scope preparado para ATLAS-IMPOST - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/","og_locale":"pt_PT","og_type":"article","og_title":"Riege com software de Zoll Scope preparado para ATLAS-IMPOST - Loginfo24","og_description":"A partida para o procedimento ATLAS-IMPOST ocorreu j\u00e1 em 01.07.2021 com a decis\u00e3o do pacote digital de IVA. A elimina\u00e7\u00e3o da isen\u00e7\u00e3o de IVA para a [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-12-21T18:24:16+00:00","og_image":[{"width":1410,"height":794,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Riege_21.12.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/"},"author":{"name":"","@id":""},"headline":"Riege com software de Zoll Scope preparado para ATLAS-IMPOST","datePublished":"2021-12-21T18:24:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/"},"wordCount":635,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Riege_21.12.21.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/","name":"Riege com software de Zoll Scope preparado para ATLAS-IMPOST - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Riege_21.12.21.jpg","datePublished":"2021-12-21T18:24:16+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Riege_21.12.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Riege_21.12.21.jpg","width":1410,"height":794},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/21\/riege-com-software-de-zoll-scope-preparado-para-atlas-impost\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Riege com software de Zoll Scope preparado para ATLAS-IMPOST"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26267","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=26267"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26267\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/11403"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=26267"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=26267"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=26267"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}