{"id":26260,"date":"2021-12-20T18:20:51","date_gmt":"2021-12-20T17:20:51","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/"},"modified":"2021-12-20T18:20:51","modified_gmt":"2021-12-20T17:20:51","slug":"gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/","title":{"rendered":"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia"},"content":{"rendered":"<h5><strong>O prestador de servi\u00e7os de transporte e log\u00edstica Gebr\u00fcder Weiss e o fabricante de bens de consumo Henkel expandiram sua parceria log\u00edstica de longa data com um conceito inovador de transporte ferrovi\u00e1rio. Produtos de lavagem e limpeza, que a Henkel produz em Kru\u0161evac, na S\u00e9rvia, chegam aos mercados europeus na rota Viena \u2013 D\u00fcsseldorf desde maio deste ano por via ferrovi\u00e1ria.<\/strong><\/h5>\n<p>(D\u00fcsseldorf\/Viena\/Kru\u0161evac\/Lauterach) Para cerca de 750 cargas anuais, a Gebr\u00fcder Weiss, juntamente com a log\u00edstica de localiza\u00e7\u00e3o da Henkel em D\u00fcsseldorf, desenvolveu e implementou um projeto de transfer\u00eancia do qual ambos os parceiros se beneficiam. &#8220;Estamos contornando a atual escassez de espa\u00e7o de carga em caminh\u00f5es, podemos reduzir as emiss\u00f5es clim\u00e1ticas na rota Viena \u2013 D\u00fcsseldorf em at\u00e9 70% e oferecemos o mesmo tempo de tr\u00e2nsito que o transporte rodovi\u00e1rio&#8221;, enfatiza Roland Raith, gerente regional da S\u00e9rvia na Gebr\u00fcder Weiss. Com a solu\u00e7\u00e3o ferrovi\u00e1ria, cerca de 500 toneladas de CO2 s\u00e3o economizadas por ano.<\/p>\n<p>Os produtos anteriormente transportados por caminh\u00e3o ao longo de toda a rota do setor de Lavagem e Cuidados para o Lar da Henkel agora s\u00e3o carregados em Viena nos reboques horizontais da Helrom. A Gebr\u00fcder Weiss pode assim usar os mesmos reboques que foram utilizados anteriormente no transporte rodovi\u00e1rio. &#8220;O princ\u00edpio de carregamento \u00e9 acess\u00edvel&#8221;, explica Roland Raith. &#8220;Estamos com a Helrom independentes de terminais ferrovi\u00e1rios cl\u00e1ssicos e n\u00e3o precisamos de reboques especiais que possam ser i\u00e7ados e guindastes. Os reboques s\u00e3o simplesmente empurrados para os vag\u00f5es de carga atrav\u00e9s de plataformas de carga que se projetam lateralmente e, no destino, s\u00e3o puxados para baixo por outra m\u00e1quina de tra\u00e7\u00e3o.&#8221;<\/p>\n<h5><strong>Desenvolvimento conjunto do conceito de transporte<\/strong><\/h5>\n<p>O conceito de transporte foi desenvolvido e realizado pela Gebr\u00fcder Weiss em conjunto com a Henkel e a Helrom. Uma vantagem especial \u00e9 que o trem est\u00e1 diretamente conectado ao tr\u00e1fego da f\u00e1brica da Henkel. &#8220;O terminal de reboques est\u00e1 localizado muito perto da nossa localiza\u00e7\u00e3o da Henkel em D\u00fcsseldorf. Assim, podemos descarregar os produtos diretamente dos vag\u00f5es e lev\u00e1-los para nossos armaz\u00e9ns em uma curta dist\u00e2ncia. Com a solu\u00e7\u00e3o ferrovi\u00e1ria, evitamos rotas de transporte com caminh\u00f5es e, assim, podemos economizar emiss\u00f5es de CO2 e tornar nossos processos mais sustent\u00e1veis&#8221;, explica Patrick Csar, gerente de log\u00edstica e exporta\u00e7\u00e3o da cadeia de suprimentos de Lavagem e Cuidados para o Lar na Henkel.<\/p>\n<h5><strong>Parceria log\u00edstica de longa data<\/strong><\/h5>\n<p>A Gebr\u00fcder Weiss tem uma parceria de mais de 25 anos com a Henkel. O prestador de servi\u00e7os log\u00edsticos gerencia transportes terrestres, a\u00e9reos e mar\u00edtimos entre v\u00e1rias instala\u00e7\u00f5es de produ\u00e7\u00e3o e armaz\u00e9ns de distribui\u00e7\u00e3o da Henkel na Europa, \u00c1sia e EUA. No transporte terrestre europeu, a Gebr\u00fcder Weiss j\u00e1 utiliza v\u00e1rios caminh\u00f5es a g\u00e1s de baixa emiss\u00e3o para a Henkel.<\/p>\n<p>Foto: \u00a9 Gebr. Weiss<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prestador de servi\u00e7os de transporte e log\u00edstica Gebr\u00fcder Weiss e o fabricante de bens de consumo Henkel expandiram sua parceria log\u00edstica de longa data com<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":11405,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-26260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"O prestador de servi\u00e7os de transporte e log\u00edstica Gebr\u00fcder Weiss e o fabricante de bens de consumo Henkel expandiram sua parceria log\u00edstica de longa data com [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-20T17:20:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Gebr_Weiss_20.12.21.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1237\" \/>\n\t<meta property=\"og:image:height\" content=\"825\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia\",\"datePublished\":\"2021-12-20T17:20:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/\"},\"wordCount\":530,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Gebr_Weiss_20.12.21.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/\",\"name\":\"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Gebr_Weiss_20.12.21.jpg\",\"datePublished\":\"2021-12-20T17:20:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Gebr_Weiss_20.12.21.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Gebr_Weiss_20.12.21.jpg\",\"width\":1237,\"height\":825},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/12\\\/20\\\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/","og_locale":"pt_PT","og_type":"article","og_title":"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia - Loginfo24","og_description":"O prestador de servi\u00e7os de transporte e log\u00edstica Gebr\u00fcder Weiss e o fabricante de bens de consumo Henkel expandiram sua parceria log\u00edstica de longa data com [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-12-20T17:20:51+00:00","og_image":[{"width":1237,"height":825,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Gebr_Weiss_20.12.21.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/"},"author":{"name":"","@id":""},"headline":"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia","datePublished":"2021-12-20T17:20:51+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/"},"wordCount":530,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Gebr_Weiss_20.12.21.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/","name":"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Gebr_Weiss_20.12.21.jpg","datePublished":"2021-12-20T17:20:51+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Gebr_Weiss_20.12.21.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Gebr_Weiss_20.12.21.jpg","width":1237,"height":825},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/12\/20\/gebruder-weiss-e-henkel-transferem-transportes-para-a-ferrovia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Gebr\u00fcder Weiss e Henkel transferem transportes para a ferrovia"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=26260"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/26260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media\/11405"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=26260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=26260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=26260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}