{"id":25716,"date":"2021-05-26T15:11:42","date_gmt":"2021-05-26T13:11:42","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/"},"modified":"2025-12-15T13:03:47","modified_gmt":"2025-12-15T12:03:47","slug":"tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/","title":{"rendered":"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca"},"content":{"rendered":"<p>Abena, o fabricante dinamarqu\u00eas de produtos de sa\u00fade e medicina, aposta na tecnologia de transporte energeticamente eficiente da TGW para a expans\u00e3o do seu centro log\u00edstico, que ir\u00e1 transportar caixas, bandejas e sacos pl\u00e1sticos. A expans\u00e3o servir\u00e1 como base para o crescimento futuro. Um pacote de manuten\u00e7\u00e3o e pe\u00e7as de reposi\u00e7\u00e3o garante a m\u00e1xima disponibilidade.<\/p>\n<p>(Marchtrenk\/Aabenraa) A Abena aposta no know-how da TGW para a expans\u00e3o do seu centro log\u00edstico. Na sede do fabricante de produtos de sa\u00fade e medicina, no sul da Dinamarca, est\u00e1 a ser desenvolvido, at\u00e9 ao ver\u00e3o de 2021, um sistema de transporte energeticamente eficiente para caixas, bandejas e embalagens suaves (sacos pl\u00e1sticos).<\/p>\n<h5><strong>Conceito personalizado<\/strong><\/h5>\n<p>Para estabelecer a base para o crescimento futuro, a Abena est\u00e1 a expandir o seu centro de distribui\u00e7\u00e3o existente com uma rede de transporte energeticamente eficiente. O TGW KingDrive\u00ae conecta as diferentes \u00e1reas funcionais e transporta caixas, bandejas e embalagens suaves \u2013 de forma r\u00e1pida, eficiente e fi\u00e1vel. A tecnologia inovadora utiliza rolos motorizados sem engrenagens e sem manuten\u00e7\u00e3o, combinando alto desempenho com longa durabilidade e baixos custos totais de propriedade. Em conjunto com a Abena, a TGW desenvolveu um conceito personalizado para otimizar a utiliza\u00e7\u00e3o do espa\u00e7o dispon\u00edvel. &#8220;Estamos muito satisfeitos por poder apoiar o cliente com a nossa compet\u00eancia em intralog\u00edstica e a nossa experi\u00eancia, trabalhando em estreita colabora\u00e7\u00e3o com Ole Cordes, Chefe de Opera\u00e7\u00f5es T\u00e9cnicas e Suporte da Abena&#8221;, sublinha Hans Gjers, Gerente de Desenvolvimento de Neg\u00f3cios da TGW Escandin\u00e1via. Al\u00e9m disso, a Abena tamb\u00e9m conta com a compet\u00eancia de servi\u00e7o da TGW. O contrato de Servi\u00e7os Vital\u00edcios inclui um pacote de manuten\u00e7\u00e3o e pe\u00e7as de reposi\u00e7\u00e3o, garantindo a m\u00e1xima disponibilidade do sistema em opera\u00e7\u00e3o. Foto: \u00a9 TGW<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abena, o fabricante dinamarqu\u00eas de produtos de sa\u00fade e medicina, aposta na tecnologia de transporte energeticamente eficiente da TGW para a expans\u00e3o do seu centro log\u00edstico,<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1560,1561],"tags":[],"class_list":["post-25716","post","type-post","status-publish","format-standard","hentry","category-categories","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Abena, o fabricante dinamarqu\u00eas de produtos de sa\u00fade e medicina, aposta na tecnologia de transporte energeticamente eficiente da TGW para a expans\u00e3o do seu centro log\u00edstico, [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-26T13:11:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca\",\"datePublished\":\"2021-05-26T13:11:42+00:00\",\"dateModified\":\"2025-12-15T12:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/\"},\"wordCount\":330,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Categories\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/\",\"name\":\"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2021-05-26T13:11:42+00:00\",\"dateModified\":\"2025-12-15T12:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/05\\\/26\\\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/","og_locale":"pt_PT","og_type":"article","og_title":"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca - Loginfo24","og_description":"Abena, o fabricante dinamarqu\u00eas de produtos de sa\u00fade e medicina, aposta na tecnologia de transporte energeticamente eficiente da TGW para a expans\u00e3o do seu centro log\u00edstico, [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-05-26T13:11:42+00:00","article_modified_time":"2025-12-15T12:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/"},"author":{"name":"","@id":""},"headline":"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca","datePublished":"2021-05-26T13:11:42+00:00","dateModified":"2025-12-15T12:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/"},"wordCount":330,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Categories","Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/","name":"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2021-05-26T13:11:42+00:00","dateModified":"2025-12-15T12:03:47+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/05\/26\/tgw-expande-o-centro-logistico-da-abena-em-aabenraa-dinamarca\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"TGW expande o centro log\u00edstico da Abena em Aabenraa, Dinamarca"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/25716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=25716"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/25716\/revisions"}],"predecessor-version":[{"id":47134,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/25716\/revisions\/47134"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=25716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=25716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=25716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}