{"id":24955,"date":"2021-04-23T20:14:12","date_gmt":"2021-04-23T18:14:12","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/"},"modified":"2025-12-15T13:00:03","modified_gmt":"2025-12-15T12:00:03","slug":"stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/","title":{"rendered":"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia"},"content":{"rendered":"<p>A L\u00fcbecker Hafen-Gesellschaft (LHG) d\u00e1 as boas-vindas a um novo navio nos seus cais. A companhia sueca Stena Line come\u00e7ou recentemente a operar o<\/p>\n<p>(L\u00fcbeck) O navio RoPax junta-se no terminal LHG Skandinavienkai aos navios &#8220;Urd&#8221; e &#8220;Stena Gothica&#8221;. Com isso, a companhia aumenta o n\u00famero de viagens, podendo agora oferecer sete partidas por semana em cada dire\u00e7\u00e3o; anteriormente eram cinco. O &#8220;Vinga&#8221; oferece, al\u00e9m de 1500 metros de carga, espa\u00e7o para at\u00e9 400 passageiros. Neste momento, est\u00e1 reservado para motoristas de caminh\u00e3o. O navio atraca no cais 5.<\/p>\n<p>A maior capacidade \u00e9 um reflexo do aumento das quantidades entre a Alemanha e os Estados B\u00e1lticos, bem como a R\u00fassia. O transporte de ve\u00edculos novos tamb\u00e9m se beneficia disso: para abril e maio, est\u00e3o previstas at\u00e9 500 ve\u00edculos por semana no Skandinavienkai, destinados aos Estados B\u00e1lticos.<\/p>\n<p><strong>Coopera\u00e7\u00e3o estreita com o porto de Liep\u0101ja<\/strong><\/p>\n<p>A LHG mant\u00e9m uma estreita coopera\u00e7\u00e3o com o porto de Liep\u0101ja h\u00e1 anos. Janis Lapins, chefe da Zona Econ\u00f3mica Especial de Liep\u0101ja (LSEZ), comenta: \u201cAumentar o n\u00famero de partidas para sete por semana d\u00e1 um novo impulso ao tr\u00e1fego de ferry entre os nossos locais portu\u00e1rios. No primeiro trimestre, o volume de carga, incluindo ve\u00edculos novos, entre Liep\u0101ja e L\u00fcbeck aumentou em mais de 40 por cento. Vemos este desenvolvimento tamb\u00e9m como resultado da nossa expans\u00e3o de infraestrutura no local.\u201d Mais travessias ajudariam a fortalecer ainda mais a coopera\u00e7\u00e3o entre o porto de Liep\u0101ja e a LHG.<\/p>\n<p>O diretor-geral da LHG, Sebastian J\u00fcrgens, acrescenta: \u201cUm passo l\u00f3gico, que naturalmente acolhemos com grande satisfa\u00e7\u00e3o. Estamos a seguir esta tend\u00eancia e queremos expandir ainda mais a colabora\u00e7\u00e3o com os nossos parceiros let\u00f5es, conectando-nos ainda melhor. Para isso, queremos lan\u00e7ar um &#8220;Dia do Porto Alem\u00e3o-Let\u00e3o&#8221; ap\u00f3s o fim da pandemia.\u201d Para a Finl\u00e2ndia, j\u00e1 existe h\u00e1 anos um evento semelhante no outono, que desfrutou de crescente popularidade at\u00e9 ao lockdown.<\/p>\n<p>&nbsp;<\/p>\n<p>Foto: \u00a9 LHG \/ Tim Becker<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A L\u00fcbecker Hafen-Gesellschaft (LHG) d\u00e1 as boas-vindas a um novo navio nos seus cais. A companhia sueca Stena Line come\u00e7ou recentemente a operar o (L\u00fcbeck) O<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1561,1559],"tags":[],"class_list":["post-24955","post","type-post","status-publish","format-standard","hentry","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A L\u00fcbecker Hafen-Gesellschaft (LHG) d\u00e1 as boas-vindas a um novo navio nos seus cais. A companhia sueca Stena Line come\u00e7ou recentemente a operar o (L\u00fcbeck) O [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-04-23T18:14:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T12:00:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia\",\"datePublished\":\"2021-04-23T18:14:12+00:00\",\"dateModified\":\"2025-12-15T12:00:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/\"},\"wordCount\":368,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/\",\"name\":\"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2021-04-23T18:14:12+00:00\",\"dateModified\":\"2025-12-15T12:00:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/04\\\/23\\\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/","og_locale":"pt_PT","og_type":"article","og_title":"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia - Loginfo24","og_description":"A L\u00fcbecker Hafen-Gesellschaft (LHG) d\u00e1 as boas-vindas a um novo navio nos seus cais. A companhia sueca Stena Line come\u00e7ou recentemente a operar o (L\u00fcbeck) O [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-04-23T18:14:12+00:00","article_modified_time":"2025-12-15T12:00:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/"},"author":{"name":"","@id":""},"headline":"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia","datePublished":"2021-04-23T18:14:12+00:00","dateModified":"2025-12-15T12:00:03+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/"},"wordCount":368,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Regions","Shipping &amp; Ports"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/","name":"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2021-04-23T18:14:12+00:00","dateModified":"2025-12-15T12:00:03+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/04\/23\/stena-line-fortalece-a-ligacao-entre-o-porto-de-lubeck-e-a-letonia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Stena Line fortalece a liga\u00e7\u00e3o entre o porto de L\u00fcbeck e a Let\u00f3nia"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/24955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=24955"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/24955\/revisions"}],"predecessor-version":[{"id":45618,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/24955\/revisions\/45618"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=24955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=24955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=24955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}