{"id":23979,"date":"2021-03-16T17:34:33","date_gmt":"2021-03-16T16:34:33","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/"},"modified":"2025-12-15T12:55:32","modified_gmt":"2025-12-15T11:55:32","slug":"dhl-express-inicia-construcao-no-novo-local-em-neu-ulm","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/","title":{"rendered":"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm"},"content":{"rendered":"<p>A DHL Express deu in\u00edcio \u00e0 constru\u00e7\u00e3o do mais recente local em Neu-Ulm. O volume de investimento para a instala\u00e7\u00e3o totaliza 17 milh\u00f5es de euros. No total, a DHL Express investir\u00e1 160 milh\u00f5es de euros em cinco novos projetos de constru\u00e7\u00e3o at\u00e9 2033, permitindo aumentos de capacidade e crescimento operacional.<\/p>\n<p>(Bonn\/Neu-Ulm) A DHL Express continua a investir de forma consistente em seus locais na Alemanha. O programa de infraestrutura da rede expressa alem\u00e3 inclui um volume de investimento total de 160 milh\u00f5es de euros apenas para cinco novos projetos de constru\u00e7\u00e3o no per\u00edodo de 2020 a 2023.<\/p>\n<p>Para o mais recente projeto em Neu-Ulm, o in\u00edcio oficial da constru\u00e7\u00e3o come\u00e7a hoje. Na Albrecht-Berblinger-Stra\u00dfe, ser\u00e1 criado um espa\u00e7o operacional e de escrit\u00f3rio de mais de 3.500 m\u00b2 em uma \u00e1rea total de 13.500 m\u00b2. O desenvolvedor do projeto \u00e9 a empresa Europastra\u00dfe NU Projekt GmbH de Lenggries. Atualmente, est\u00e3o sendo realizadas as obras preparat\u00f3rias para a constru\u00e7\u00e3o do novo edif\u00edcio. O volume de investimento para o novo local da DHL Express totaliza 17 milh\u00f5es de euros. A mudan\u00e7a e a opera\u00e7\u00e3o est\u00e3o previstas para a primavera de 2022.<\/p>\n<h5><strong>Tecnologia de ponta dobra as capacidades<\/strong><\/h5>\n<p>&#8220;Continuamos a investir de forma consistente em nossa rede na Alemanha&#8221;, diz Markus Reckling, Diretor Geral da DHL Express Alemanha. &#8220;Com a utiliza\u00e7\u00e3o de tecnologia de ponta, dobramos com a nova constru\u00e7\u00e3o as capacidades do nosso local atual. Os efeitos crescentes da globaliza\u00e7\u00e3o e digitaliza\u00e7\u00e3o aumentaram significativamente a demanda dos clientes por servi\u00e7os expressos internacionais e receberam um impulso adicional devido aos efeitos dos lockdowns em todo o pa\u00eds. Os novos investimentos nos permitem um crescimento org\u00e2nico, para que possamos conectar nossos clientes na regi\u00e3o ainda melhor com nossa rede global.&#8221; A DHL Express se v\u00ea bem preparada com a nova constru\u00e7\u00e3o para o crescimento previsto na regi\u00e3o nos pr\u00f3ximos anos.<\/p>\n<p>A nova instala\u00e7\u00e3o contar\u00e1 com dois chamados dedos PUD (&#8220;Pick-up e Delivery&#8221;) com possibilidades diretas de carga e descarga para 72 ve\u00edculos de entrega simultaneamente. Al\u00e9m disso, ter\u00e1 uma moderna instala\u00e7\u00e3o de triagem, projetada para um volume de remessas de 3.000 pacotes por hora, atrav\u00e9s da qual todas as remessas nacionais e internacionais da DHL Express ser\u00e3o processadas de forma r\u00e1pida e eficiente. &#8220;Atrav\u00e9s das inova\u00e7\u00f5es operacionais, alcan\u00e7amos janelas de tempo de processamento mais curtas no manuseio das remessas, bem como processos significativamente melhorados&#8221;, continua Reckling.<\/p>\n<h5><strong>Funcion\u00e1rios se beneficiam de infraestrutura moderna<\/strong><\/h5>\n<p>Al\u00e9m disso, os funcion\u00e1rios no novo local, que fica a apenas tr\u00eas quil\u00f4metros do local anterior, se beneficiar\u00e3o de locais de trabalho ergon\u00f4micos no escrit\u00f3rio e no armaz\u00e9m, bem como de \u00e1reas sociais modernamente equipadas. Al\u00e9m disso, ser\u00e1 dada aten\u00e7\u00e3o ao uso de materiais economizadores de energia e, por exemplo, a ilumina\u00e7\u00e3o de todo o armaz\u00e9m ser\u00e1 equipada com a mais moderna tecnologia LED. Al\u00e9m disso, o local ser\u00e1 em breve equipado com um sistema de energia fotovoltaica para a opera\u00e7\u00e3o di\u00e1ria da esta\u00e7\u00e3o. A nova esta\u00e7\u00e3o da DHL Express tamb\u00e9m atender\u00e1 aos requisitos de seguran\u00e7a da Transported Asset Protection Association (TAPA) e, assim, receber\u00e1 a certifica\u00e7\u00e3o TAPA Classe A, reconhecida mundialmente, como o mais alto n\u00edvel de seguran\u00e7a no transporte a\u00e9reo.<\/p>\n<p>No ano passado, a DHL Express Alemanha anunciou um projeto de constru\u00e7\u00e3o muito especial com a nova constru\u00e7\u00e3o no aeroporto de Munique. O novo local da DHL Express, com acesso direto ao lado da pista, ser\u00e1 seis vezes maior que o anterior. O volume de investimento \u00e9 de 70 milh\u00f5es de euros. Apesar da pandemia, em 2020, as novas constru\u00e7\u00f5es em Bielefeld (17 milh\u00f5es de euros) e em Berlim (31 milh\u00f5es de euros) foram conclu\u00eddas pontualmente. A inaugura\u00e7\u00e3o do novo local em Dortmund, cujo volume de investimento \u00e9 de 25 milh\u00f5es de euros, est\u00e1 prevista para o outono de 2021.<\/p>\n<p>Foto: \u00a9 DPDHL<\/p>\n<p><a href=\"https:\/\/www.dpdhl.com\" target=\"_blank\" rel=\"noopener noreferrer\">www.dpdhl.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A DHL Express deu in\u00edcio \u00e0 constru\u00e7\u00e3o do mais recente local em Neu-Ulm. O volume de investimento para a instala\u00e7\u00e3o totaliza 17 milh\u00f5es de euros. No<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1560,1561],"tags":[],"class_list":["post-23979","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intermodal-road","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"A DHL Express deu in\u00edcio \u00e0 constru\u00e7\u00e3o do mais recente local em Neu-Ulm. O volume de investimento para a instala\u00e7\u00e3o totaliza 17 milh\u00f5es de euros. No [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-16T16:34:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:55:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm\",\"datePublished\":\"2021-03-16T16:34:33+00:00\",\"dateModified\":\"2025-12-15T11:55:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/\"},\"wordCount\":690,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/\",\"name\":\"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2021-03-16T16:34:33+00:00\",\"dateModified\":\"2025-12-15T11:55:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2021\\\/03\\\/16\\\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/","og_locale":"pt_PT","og_type":"article","og_title":"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm - Loginfo24","og_description":"A DHL Express deu in\u00edcio \u00e0 constru\u00e7\u00e3o do mais recente local em Neu-Ulm. O volume de investimento para a instala\u00e7\u00e3o totaliza 17 milh\u00f5es de euros. No [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2021-03-16T16:34:33+00:00","article_modified_time":"2025-12-15T11:55:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/"},"author":{"name":"","@id":""},"headline":"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm","datePublished":"2021-03-16T16:34:33+00:00","dateModified":"2025-12-15T11:55:32+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/"},"wordCount":690,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/","url":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/","name":"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2021-03-16T16:34:33+00:00","dateModified":"2025-12-15T11:55:32+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2021\/03\/16\/dhl-express-inicia-construcao-no-novo-local-em-neu-ulm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"DHL Express inicia constru\u00e7\u00e3o no novo local em Neu-Ulm"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/23979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=23979"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/23979\/revisions"}],"predecessor-version":[{"id":43682,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/23979\/revisions\/43682"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=23979"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=23979"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=23979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}