{"id":21916,"date":"2020-12-06T16:06:55","date_gmt":"2020-12-06T15:06:55","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/"},"modified":"2025-12-15T12:46:14","modified_gmt":"2025-12-15T11:46:14","slug":"omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/","title":{"rendered":"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH"},"content":{"rendered":"<p>O especialista em Fulfillment Full-Stack Omnipack sp. z o.o. da Pol\u00f4nia investe em crescimento e internacionaliza\u00e7\u00e3o. Para isso, tr\u00eas novos investidores foram trazidos a bordo. Os fundos adicionais tamb\u00e9m devem ser direcionados para a tecnologia do armaz\u00e9m e para a expans\u00e3o da regi\u00e3o DACH.<\/p>\n<p>(Vars\u00f3via) O especialista em Fulfillment Full-Stack Omnipack concluiu em 18 de novembro de 2020 uma rodada de financiamento de cerca de 2,5 milh\u00f5es de euros. Com isso, os investimentos totais atingiram cerca de cinco milh\u00f5es de euros. Al\u00e9m dos investidores j\u00e1 existentes, foram adicionados, entre outros, os seguintes: Dr. Cornelius Walter, que se concentra em empresas que seguem modelos de neg\u00f3cios sustent\u00e1veis e se comprometem com os objetivos de Environmental, Social and Governance (ESG), Dr. Dr. Florian Drabeck, Conselheiro Executivo S\u00eanior, Investidor e ex-Chief Financial Officer Global da Westwing Group AG, e Nunatak Capital, um fundo de capital de risco com foco na Europa Central e Oriental.<\/p>\n<h5><strong>Expans\u00e3o do mercado DACH<\/strong><\/h5>\n<p> &#8220;Apesar dos graves impactos da pandemia de Corona, conseguimos implementar nossos planos de expans\u00e3o e a capta\u00e7\u00e3o de recursos no valor de cerca de cinco milh\u00f5es de euros para os pr\u00f3ximos passos de desenvolvimento&#8221;, diz o CEO da Omnipack, Tomek Kasperski. O capital adicional ser\u00e1 principalmente investido no crescimento cont\u00ednuo, na expans\u00e3o internacional e no desenvolvimento da tecnologia interna e do armaz\u00e9m. &#8220;Com isso, temos a oportunidade de mais crescimento e maior rentabilidade no pr\u00f3ximo ano. Al\u00e9m disso, podemos realizar mais passos para expandir o mercado DACH. Esta rodada de financiamento mostra o qu\u00e3o grande \u00e9 a confian\u00e7a dos investidores em nossa empresa, tanto dos investidores existentes quanto dos novos. O interesse superou nossas expectativas em muito.&#8221; Kasperski acrescenta: &#8220;Estamos orgulhosos de ter trazido Dr. Cornelius Walter, Dr. Dr. Florian Drabeck e Nunatak Capital como novos investidores. Seu conhecimento do setor e ampla experi\u00eancia nos apoiar\u00e3o significativamente na continuidade de nossa estrat\u00e9gia de internacionaliza\u00e7\u00e3o e na expans\u00e3o para mais pa\u00edses nos pr\u00f3ximos anos.&#8221;<\/p>\n<h5><strong>Especialista em solu\u00e7\u00f5es de Fulfillment<\/strong><\/h5>\n<p> H\u00e1 mais de tr\u00eas anos, a Omnipack oferece aos seus clientes um Fulfillment abrangente: desde a recep\u00e7\u00e3o de mercadorias e armazenamento at\u00e9 a separa\u00e7\u00e3o, embalagem e envio, bem como a gest\u00e3o de devolu\u00e7\u00f5es e reclama\u00e7\u00f5es. Assim, a Omnipack n\u00e3o \u00e9 apenas especialista em servi\u00e7os de Fulfillment, mas tamb\u00e9m possui uma tecnologia de TI propriet\u00e1ria, que \u00e9 continuamente aprimorada por desenvolvedores Full-Stack internos. Isso proporciona aos clientes controle sobre seus processos log\u00edsticos e a gest\u00e3o de suas plataformas de e-commerce. A empresa colabora com todas as principais plataformas de e-commerce e prestadores de servi\u00e7os de courier. Hoje, a Omnipack possui dois armaz\u00e9ns modernos em locais estrategicamente situados, que possibilitam servi\u00e7os como entrega de Fulfillment no mesmo dia ou no dia seguinte em toda a Europa. Cerca da metade de todos os clientes existentes v\u00eam de pa\u00edses europeus fora da sede da empresa na Pol\u00f4nia, com foco na Alemanha, \u00c1ustria e Su\u00ed\u00e7a. J\u00e1 durante a funda\u00e7\u00e3o da empresa, estava claro que o objetivo era seguir um curso internacional a longo prazo e apoiar clientes em toda a Europa em seus neg\u00f3cios.<\/p>\n<h5><strong>Tend\u00eancias de amanh\u00e3 em vista<\/strong><\/h5>\n<p> Dr. Cornelius Walter resume: &#8220;Os motivos decisivos para o investimento foram, para mim, dois fatores: por um lado, o desenvolvimento cont\u00ednuo da Europa Oriental como um hub log\u00edstico digital cada vez mais significativo, promovido pela localiza\u00e7\u00e3o geogr\u00e1fica e pela cont\u00ednua expans\u00e3o de inova\u00e7\u00f5es. Por outro lado, a colabora\u00e7\u00e3o com a equipe talentosa e experiente da Omnipack, que j\u00e1 tem um olhar voltado para as tend\u00eancias de amanh\u00e3 e desempenhar\u00e1 um papel crucial no mercado de e-commerce em expans\u00e3o na Europa.&#8221;<\/p>\n<h5><strong>Passos de desenvolvimento conjunto<\/strong><\/h5>\n<p> Dr. Dr. Florian Drabeck acrescenta: &#8220;Com a Omnipack, tenho uma longa colabora\u00e7\u00e3o com Tomek Kasperski. Como Co-CEO da Westwing Home &amp; Living CEE, ele construiu uma das maiores plataformas de e-commerce na Pol\u00f4nia e nos ajudou a implementar nossa estrat\u00e9gia de internacionaliza\u00e7\u00e3o. Investi na Omnipack porque acreditamos tanto na equipe experiente quanto nas for\u00e7as da empresa como prestadora de servi\u00e7os log\u00edsticos internacional, que j\u00e1 conhecemos na pr\u00e1tica. Estamos ansiosos para implementar os pr\u00f3ximos passos de desenvolvimento juntos com a Omnipack.&#8221;<\/p>\n<h5><strong>Ansiosos pela colabora\u00e7\u00e3o futura<\/strong><\/h5>\n<p> Piotr Ci\u017ckowicz, s\u00f3cio-gerente da Nunatak Capital, acrescenta: &#8220;Gra\u00e7as ao uso de solu\u00e7\u00f5es avan\u00e7adas de Data Science, \u00e9, por exemplo, poss\u00edvel adaptar automaticamente o tipo de embalagem ou o tamanho de acordo com as exig\u00eancias dos clientes para um determinado produto. A Nunatak Capital, que atua como um fundo de VC operacional, n\u00e3o apenas investe em startups que utilizam Data Science para cria\u00e7\u00e3o de valor, mas tamb\u00e9m as apoia no desenvolvimento. &#8220;O investimento e o apoio de longo prazo da Omnipack se encaixam perfeitamente em nosso modelo operacional. Estamos ansiosos pela colabora\u00e7\u00e3o futura e pelos sucessos conjuntos.&#8221;<\/p>\n<h5><strong>Sobre a Omnipack<\/strong><\/h5>\n<p> A Omnipack \u00e9 uma plataforma de Fulfillment que se dirige especificamente a pequenas e m\u00e9dias empresas europeias que atuam no e-commerce. A empresa de tecnologia \u00e9 especialista em Fulfillment Full-Stack: desde a gest\u00e3o do armaz\u00e9m e seu controle at\u00e9 a recep\u00e7\u00e3o e armazenamento de mercadorias, bem como a montagem dos produtos at\u00e9 o envio. Para isso, a Omnipack conta com uma extensa rede de parceiros log\u00edsticos internacionais, que entregam as mercadorias ao cliente via entrega no dia seguinte. A Omnipack tamb\u00e9m apoia seus clientes na integra\u00e7\u00e3o de sistemas e oferece uma gest\u00e3o de devolu\u00e7\u00f5es abrangente, al\u00e9m de servi\u00e7os personalizados. Anualmente, a empresa com sede em Vars\u00f3via, Pol\u00f4nia, envia cerca de 1,2 milh\u00f5es de pacotes em toda a Europa e utiliza mais de 16.500 metros quadrados de espa\u00e7o de armazenamento para seus clientes.<\/p>\n<p>Foto: \u00a9 Omnipack\/Adobe Stock<br \/><a href=\"https:\/\/www.omnipack.io\/de\" target=\"_blank\" rel=\"noopener noreferrer\">www.omnipack.io\/de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O especialista em Fulfillment Full-Stack Omnipack sp. z o.o. da Pol\u00f4nia investe em crescimento e internacionaliza\u00e7\u00e3o. Para isso, tr\u00eas novos investidores foram trazidos a bordo. Os<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-21916","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"O especialista em Fulfillment Full-Stack Omnipack sp. z o.o. da Pol\u00f4nia investe em crescimento e internacionaliza\u00e7\u00e3o. Para isso, tr\u00eas novos investidores foram trazidos a bordo. Os [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-06T15:06:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:46:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH\",\"datePublished\":\"2020-12-06T15:06:55+00:00\",\"dateModified\":\"2025-12-15T11:46:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/\"},\"wordCount\":1017,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/\",\"name\":\"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2020-12-06T15:06:55+00:00\",\"dateModified\":\"2025-12-15T11:46:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/12\\\/06\\\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/","og_locale":"pt_PT","og_type":"article","og_title":"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH - Loginfo24","og_description":"O especialista em Fulfillment Full-Stack Omnipack sp. z o.o. da Pol\u00f4nia investe em crescimento e internacionaliza\u00e7\u00e3o. Para isso, tr\u00eas novos investidores foram trazidos a bordo. Os [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-12-06T15:06:55+00:00","article_modified_time":"2025-12-15T11:46:14+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/"},"author":{"name":"","@id":""},"headline":"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH","datePublished":"2020-12-06T15:06:55+00:00","dateModified":"2025-12-15T11:46:14+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/"},"wordCount":1017,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/","url":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/","name":"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2020-12-06T15:06:55+00:00","dateModified":"2025-12-15T11:46:14+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/12\/06\/omnipack-com-rodada-de-financiamento-e-expansao-do-mercado-dach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Omnipack com rodada de financiamento e expans\u00e3o do mercado DACH"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/21916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=21916"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/21916\/revisions"}],"predecessor-version":[{"id":40022,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/21916\/revisions\/40022"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=21916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=21916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=21916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}