{"id":21532,"date":"2020-11-24T16:35:21","date_gmt":"2020-11-24T15:35:21","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/"},"modified":"2025-12-15T12:44:29","modified_gmt":"2025-12-15T11:44:29","slug":"intersport-wohlleben-cresce-no-e-commerce-com-logcontrol","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/","title":{"rendered":"Intersport Wohlleben cresce no E-Commerce com LogControl"},"content":{"rendered":"<p>O comerciante de artigos esportivos franconiano Intersport Wohlleben otimiza seus processos de separa\u00e7\u00e3o no crescente com\u00e9rcio online com o software de gerenciamento de armaz\u00e9m modular da LogControl e hardware da Panda Products. Ambos fazem parte do MHP Solution Group, um fornecedor de software de log\u00edstica e hardware na regi\u00e3o DACH.<\/p>\n<p>(Neustadt am R\u00fcbenberge) A Intersport Wohlleben envia at\u00e9 300 pacotes por dia, que s\u00e3o principalmente separados na localiza\u00e7\u00e3o de D\u00f6rfles-Esbach, mas tamb\u00e9m na filial de Lichtenfels. Para substituir a solu\u00e7\u00e3o de separa\u00e7\u00e3o anterior com listas em papel, a empresa procurou fornecedores adequados de software e hardware. &#8220;Para n\u00f3s, como uma empresa de m\u00e9dio porte, a LogControl e a Panda Products s\u00e3o os parceiros ideais, com os quais podemos nos comunicar de forma r\u00e1pida, sem problemas e competente em p\u00e9 de igualdade&#8221;, explica Michael Dorst, Diretor T\u00e9cnico da Intersport Wohlleben. Com a nova solu\u00e7\u00e3o, a separa\u00e7\u00e3o ser\u00e1 &#8220;sem documentos e sem erros&#8221;.<\/p>\n<h5><strong>Interfaces para o sistema ERP<\/strong><\/h5>\n<p>O LogControl WHM ser\u00e1 conectado \u00e0 Intersport Wohlleben atrav\u00e9s das interfaces padr\u00e3o existentes ao sistema ERP Advarics e ao software de gerenciamento de E-Commerce multicanal Globalsys. Os pedidos gerados atrav\u00e9s da Amazon, Check24, eBay, Zalando e da pr\u00f3pria loja online s\u00e3o encaminhados do Globalsys para o Advarics e para o LogControl WHM. O WHM, por sua vez, envia os pedidos de separa\u00e7\u00e3o gerados diretamente para os scanners m\u00f3veis do tipo Zebra MC3300. At\u00e9 cinco separadores s\u00e3o guiados de forma otimizada para o respectivo local de prateleira e escaneiam os c\u00f3digos de barras no local de armazenamento e no artigo a cada retirada de mercadoria. Os separadores pesam os pacotes e os fotografam em seguida com a c\u00e2mera integrada no scanner. &#8220;Com esse procedimento, podemos quase eliminar erros, o que reduz significativamente o n\u00famero de devolu\u00e7\u00f5es&#8221;, espera Dorst. Para a impress\u00e3o das etiquetas de envio, a Panda Products fornece uma impressora t\u00e9rmica direta do tipo Zebra Zt411.<\/p>\n<h5><strong>Sobre a Intersport Wohlleben<\/strong><\/h5>\n<p>A Intersport Wohlleben \u00e9 um comerciante de artigos esportivos de m\u00e9dio porte com duas filiais em D\u00f6rfles-Esbach e Lichtenfels. Fundada em 1926, a empresa emprega cerca de 80 funcion\u00e1rios e atualmente \u00e9 administrada pela quarta gera\u00e7\u00e3o. 15.000 dos 85.000 artigos do amplo sortimento j\u00e1 podem ser encomendados online, com novos artigos sendo constantemente adicionados ao sistema. A Sporthaus Wohlleben GmbH \u00e9 membro da Intersport Deutschland eG desde 1993, a associa\u00e7\u00e3o mais bem-sucedida de comerciantes de artigos esportivos independentes.<\/p>\n<h5><strong>Sobre o MHP Solution Group \u2013 Doing Logistics<\/strong><\/h5>\n<p>A MHP Solution Group GmbH, fundada em 1999 e localizada em Neustadt am R\u00fcbenberge, perto de Hannover, \u00e9 um fornecedor total de solu\u00e7\u00f5es de software inteligentes, hardware, consultoria e Business Intelligence na log\u00edstica. O grupo empresarial combina mais de 250 anos de compet\u00eancia em log\u00edstica com conhecimento log\u00edstico intersetorial e solu\u00e7\u00f5es empresariais inovadoras para a otimiza\u00e7\u00e3o dos processos log\u00edsticos. Em 12 locais na Europa, as 10 empresas do MHP Solution Group empregam cerca de 300 funcion\u00e1rios, organizados em quatro \u00e1reas de produtos: Customs (TIA innovations GmbH B\u00f6bingen, AZ Au\u00dfenwirtschafts- und Zollberatungsgesellschaft mbH Albstadt), Warehouse (aisys Advanced Information Systems GmbH W\u00fcrzburg, KDL Logistiksysteme GmbH Hamburg, LogControl GmbH Pforzheim, PANDA PRODUCTS Barcode-Systeme GmbH Norderstedt), Shipping (MHP Software GmbH Neustadt, MHP Software S.L. Espanha) &amp; Transport (BNS GmbH D\u00fcsseldorf, TRANSDATA Software GmbH &amp; Co. KG Bielefeld) e o centro de desenvolvimento MHP Solution Center na Espanha.<br \/>Foto: \u00a9 Adobe Stock<br \/><a href=\"https:\/\/www.intersport-wohlleben.de\">www.intersport-wohlleben.de<\/a>\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.mhp-solution-group.com\">www.mhp-solution-group.com<\/a>\u00a0\u00a0\u00a0 <a href=\"https:\/\/www.doing-logistics.com\">www.doing-logistics.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O comerciante de artigos esportivos franconiano Intersport Wohlleben otimiza seus processos de separa\u00e7\u00e3o no crescente com\u00e9rcio online com o software de gerenciamento de armaz\u00e9m modular da<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-21532","post","type-post","status-publish","format-standard","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Intersport Wohlleben cresce no E-Commerce com LogControl - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Intersport Wohlleben cresce no E-Commerce com LogControl - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"O comerciante de artigos esportivos franconiano Intersport Wohlleben otimiza seus processos de separa\u00e7\u00e3o no crescente com\u00e9rcio online com o software de gerenciamento de armaz\u00e9m modular da [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-24T15:35:21+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:44:29+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Intersport Wohlleben cresce no E-Commerce com LogControl\",\"datePublished\":\"2020-11-24T15:35:21+00:00\",\"dateModified\":\"2025-12-15T11:44:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/\"},\"wordCount\":600,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/\",\"name\":\"Intersport Wohlleben cresce no E-Commerce com LogControl - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2020-11-24T15:35:21+00:00\",\"dateModified\":\"2025-12-15T11:44:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/11\\\/24\\\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Intersport Wohlleben cresce no E-Commerce com LogControl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Intersport Wohlleben cresce no E-Commerce com LogControl - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/","og_locale":"pt_PT","og_type":"article","og_title":"Intersport Wohlleben cresce no E-Commerce com LogControl - Loginfo24","og_description":"O comerciante de artigos esportivos franconiano Intersport Wohlleben otimiza seus processos de separa\u00e7\u00e3o no crescente com\u00e9rcio online com o software de gerenciamento de armaz\u00e9m modular da [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-11-24T15:35:21+00:00","article_modified_time":"2025-12-15T11:44:29+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/"},"author":{"name":"","@id":""},"headline":"Intersport Wohlleben cresce no E-Commerce com LogControl","datePublished":"2020-11-24T15:35:21+00:00","dateModified":"2025-12-15T11:44:29+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/"},"wordCount":600,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/","url":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/","name":"Intersport Wohlleben cresce no E-Commerce com LogControl - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2020-11-24T15:35:21+00:00","dateModified":"2025-12-15T11:44:29+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/11\/24\/intersport-wohlleben-cresce-no-e-commerce-com-logcontrol\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Intersport Wohlleben cresce no E-Commerce com LogControl"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/21532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=21532"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/21532\/revisions"}],"predecessor-version":[{"id":39258,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/21532\/revisions\/39258"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=21532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=21532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=21532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}