{"id":17174,"date":"2020-03-01T11:47:08","date_gmt":"2020-03-01T10:47:08","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/"},"modified":"2025-12-15T12:26:16","modified_gmt":"2025-12-15T11:26:16","slug":"schnellecke-group-reune-as-areas-de-logistica-e-transporte","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/","title":{"rendered":"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte"},"content":{"rendered":"<p>Schnellecke Group AG &amp; Co. KG re\u00fane a partir de 1 de mar\u00e7o de 2020 as holdings de \u00e1reas de Log\u00edstica e Transporte, que at\u00e9 ent\u00e3o eram amplamente independentes, na nova Schnellecke Logistics SE.<\/p>\n<p>(Wolfsburg, 01.03.2020) Com data de 1 de mar\u00e7o de 2020, as holdings de \u00e1reas de Log\u00edstica e Transporte, que at\u00e9 ent\u00e3o eram amplamente independentes sob a \u00e9gide da Schnellecke Group AG &amp; Co. KG, s\u00e3o reunidas na nova Schnellecke Logistics SE. Elas se integram tanto do ponto de vista jur\u00eddico quanto organizacional na Schnellecke Logistics SE. A Schnellecke Group AG &amp; CO. KG se tornar\u00e1 uma holding pura de participa\u00e7\u00e3o para as \u00e1reas KWD Automotive AG &amp; Co. KG e a rec\u00e9m-formada Schnellecke Logistics SE. Ao mesmo tempo, as estruturas de gest\u00e3o tamb\u00e9m ser\u00e3o reorganizadas. As fun\u00e7\u00f5es do conselho da Schnellecke Group e da holding de \u00e1reas ser\u00e3o separadas, evitando fun\u00e7\u00f5es duplicadas e permitindo uma maior concentra\u00e7\u00e3o no core business da log\u00edstica. Al\u00e9m disso, foi estabelecido um Conselho Executivo composto pelos diretores Nikolaus K\u00fclps (CEO), Dr. Klaus van Marwyk (CFO) e Andreas Wagner (COO), bem como cinco l\u00edderes experientes de longa data: Karsten Keil (TI), Kai Kienast (RH), Lars Otte (BD), Sven Virgens (OpEx) e Volker Vossler (Estrat\u00e9gia), onde todas as fun\u00e7\u00f5es essenciais da Schnellecke Logistics SE est\u00e3o diretamente integradas nos processos de decis\u00e3o pr\u00f3ximos ao cliente e \u00e0s opera\u00e7\u00f5es di\u00e1rias. Com essas medidas, foram implementadas estruturas e processos de neg\u00f3cios mais diretos, al\u00e9m de acelerar e simplificar os caminhos de decis\u00e3o com atribui\u00e7\u00e3o direta de responsabilidades. Com essa nova estrutura, a Schnellecke pode enfrentar melhor os desafios futuros do mercado e da transforma\u00e7\u00e3o tecnol\u00f3gica.<\/p>\n<p><a href=\"https:\/\/www.schnellecke.com\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.schnellecke.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Schnellecke Group AG &amp; Co. KG re\u00fane a partir de 1 de mar\u00e7o de 2020 as holdings de \u00e1reas de Log\u00edstica e Transporte, que at\u00e9 ent\u00e3o<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1560,1561],"tags":[],"class_list":["post-17174","post","type-post","status-publish","format-standard","hentry","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Schnellecke Group AG &amp; Co. KG re\u00fane a partir de 1 de mar\u00e7o de 2020 as holdings de \u00e1reas de Log\u00edstica e Transporte, que at\u00e9 ent\u00e3o [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-01T10:47:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-15T11:26:16+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte\",\"datePublished\":\"2020-03-01T10:47:08+00:00\",\"dateModified\":\"2025-12-15T11:26:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/\"},\"wordCount\":314,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"articleSection\":[\"Intralogistics\",\"Regions\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/\",\"name\":\"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\"},\"datePublished\":\"2020-03-01T10:47:08+00:00\",\"dateModified\":\"2025-12-15T11:26:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/2020\\\/03\\\/01\\\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/pt-pt\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/","og_locale":"pt_PT","og_type":"article","og_title":"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte - Loginfo24","og_description":"Schnellecke Group AG &amp; Co. KG re\u00fane a partir de 1 de mar\u00e7o de 2020 as holdings de \u00e1reas de Log\u00edstica e Transporte, que at\u00e9 ent\u00e3o [\u2026]","og_url":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2020-03-01T10:47:08+00:00","article_modified_time":"2025-12-15T11:26:16+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/"},"author":{"name":"","@id":""},"headline":"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte","datePublished":"2020-03-01T10:47:08+00:00","dateModified":"2025-12-15T11:26:16+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/"},"wordCount":314,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"articleSection":["Intralogistics","Regions"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/","url":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/","name":"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#website"},"datePublished":"2020-03-01T10:47:08+00:00","dateModified":"2025-12-15T11:26:16+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/pt-pt\/2020\/03\/01\/schnellecke-group-reune-as-areas-de-logistica-e-transporte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Schnellecke Group re\u00fane as \u00e1reas de Log\u00edstica e Transporte"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/pt-pt\/#website","url":"https:\/\/loginfo24.com\/pt-pt\/","name":"Loginfo24","description":"Loginfo24 \u00e9 a plataforma dedicada \u00e0 log\u00edstica e \u00e0s cadeias de abastecimento, com informa\u00e7\u00f5es dispon\u00edveis 24 horas por dia.","publisher":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/pt-pt\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/pt-pt\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/pt-pt\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/pt-pt\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=17174"}],"version-history":[{"count":1,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17174\/revisions"}],"predecessor-version":[{"id":30722,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/posts\/17174\/revisions\/30722"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=17174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=17174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=17174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}