{"id":77404,"date":"2026-03-26T09:06:43","date_gmt":"2026-03-26T09:06:43","guid":{"rendered":"https:\/\/loginfo24.com\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/"},"modified":"2026-03-26T09:06:43","modified_gmt":"2026-03-26T09:06:43","slug":"gilgen-logistics-presenteert-verticale-transportsystemen","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/","title":{"rendered":"Gilgen Logistics presenteert verticale transportsystemen"},"content":{"rendered":"<p>De toenemende vraag naar productieoppervlakken in stedelijke gebieden dwingt bedrijven om hun logistieke strategie\u00ebn te heroverwegen, zoals Gilgen Logistics, een aanbieder van intralogistieke systemen met hoofdkantoor in Zwitserland, onlangs heeft meegedeeld. Het bedrijf heeft onlangs op de LogiMAT 2026 oplossingen gepresenteerd waarmee bedrijven effici\u00ebnter kunnen werken door middel van verticale transporttechniek.<\/p>\n<h3>Verticale transportoplossingen van Gilgen Logistics<\/h3>\n<p>Op de LogiMAT 2026 in Hal 1, Stand 05, presenteert Gilgen Logistics twee systemen voor verticale containertransporttechniek. De kleine goederenlift maakt het mogelijk om containers, pakketten en kleine goederen tussen verschillende niveaus te transporteren. Met een modulaire opbouw kan het systeem volgens de fabrikant worden aangepast aan klantvereisten en tilt het lasten tot 50 kg naar hoogtes van maximaal 40 m. De lift kan zowel vrijstaand als in een schacht worden ge\u00efnstalleerd en voldoet aan de geldende brandveiligheidseisen.<\/p>\n<p>Een ander systeem is de circulaire transporteur, ook bekend als Paternoster. Deze oplossing biedt volgens het bedrijf containerstroom en hoge transportcapaciteit op hoogtes tot 80 m. De belading en ontname van de transportcontainers gebeurt automatisch.<\/p>\n<p><a href=\"https:\/\/www.gilgen.com\/de\/index.html\" target=\"_blank\" rel=\"noopener noreferrer\">www.gilgen.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gilgen Logistics presenteert op de LogiMAT 2026 verticale transportsystemen die bedrijven moeten helpen hun intralogistiek aan te passen aan stedelijke uitdagingen en ruimte effici\u00ebnt te benutten.<\/p>\n","protected":false},"author":10,"featured_media":74847,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6679,1593,1596,6660],"tags":[2206,16972,16973,2207,16974,16975,16976,14600,16977,16978,2695,2696,2214,2215,16979,16980,16981,16982,16983,8500,16984,16985,16986,1891,2133,12010,1831,12017,16987,16988,2717,16989,3602,2148,16990,16991,16992,16993,16994,12026,1857,16995,16996,16997,12848,16998,16999,17000,17001,17002,17003,17004,17005],"class_list":["post-77404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-expeditie-logistiek","category-intralogistiek","category-zwitserland","tag-amelioration-de-lefficacite","tag-behaelterfoerdertechnik","tag-brandschutzanforderungen","tag-chaine-dapprovisionnement","tag-circulating-conveyor","tag-container-handling-technology","tag-conteneurs-de-transport","tag-conveyor-technology","tag-convoyeur-circulaire","tag-deutsch-gilgen-logistics","tag-digitalisierung","tag-digitalization","tag-efficiency-improvement","tag-effizienzsteigerung","tag-elevateur-de-petits-colis","tag-espaces-de-production","tag-exigences-de-securite-incendie","tag-fachkraeftemangel-english-gilgen-logistics","tag-fire-safety-requirements","tag-foerdertechnik","tag-intralogistics-systems","tag-intralogistiksysteme","tag-kleingueteraufzug","tag-logimat-2026","tag-logistics-service-providers","tag-logistics-strategies","tag-logistikdienstleister","tag-logistikstrategien","tag-modular-systems","tag-modulare-systeme","tag-numerisation","tag-paternoster","tag-penurie-de-competences","tag-prestataires-de-services-logistiques","tag-production-space","tag-produktionsflaechen","tag-skills-shortage-francais-gilgen-logistics","tag-small-goods-lift","tag-solutions-de-transport-vertical","tag-strategies-logistiques","tag-supply-chain","tag-systemes-dintralogistique","tag-systemes-modulaires","tag-technologie-de-manutention-des-conteneurs","tag-technologie-de-transport","tag-transport-containers","tag-transportbehaelter","tag-umlauffoerderer","tag-urban-areas","tag-urbanen-gebieten","tag-vertical-conveying-solutions","tag-vertikale-foerderloesungen","tag-zones-urbaines"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gilgen Logistics presenteert verticale transportsystemen - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gilgen Logistics presenteert verticale transportsystemen - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Gilgen Logistics presenteert op de LogiMAT 2026 verticale transportsystemen die bedrijven moeten helpen hun intralogistiek aan te passen aan stedelijke uitdagingen en ruimte effici\u00ebnt te benutten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-26T09:06:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/AdobeStock_605908084-1-scaled-1.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1435\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Jeremy Soland\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Jeremy Soland\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/\"},\"author\":{\"name\":\"Jeremy Soland\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\"},\"headline\":\"Gilgen Logistics presenteert verticale transportsystemen\",\"datePublished\":\"2026-03-26T09:06:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/\"},\"wordCount\":173,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/AdobeStock_605908084-1-scaled-1.jpeg\",\"keywords\":[\"am\u00e9lioration de l'efficacit\u00e9\",\"Beh\u00e4lterf\u00f6rdertechnik\",\"Brandschutzanforderungen\",\"cha\u00eene d'approvisionnement\",\"circulating conveyor\",\"container handling technology\",\"conteneurs de transport\",\"conveyor technology\",\"convoyeur circulaire\",\"Deutsch Gilgen Logistics\",\"Digitalisierung\",\"digitalization\",\"efficiency improvement\",\"Effizienzsteigerung\",\"\u00e9l\u00e9vateur de petits colis\",\"espaces de production\",\"exigences de s\u00e9curit\u00e9 incendie\",\"Fachkr\u00e4ftemangel English Gilgen Logistics\",\"fire safety requirements\",\"F\u00f6rdertechnik\",\"intralogistics systems\",\"Intralogistiksysteme\",\"Kleing\u00fcteraufzug\",\"LogiMAT 2026\",\"logistics service providers\",\"logistics strategies\",\"Logistikdienstleister\",\"Logistikstrategien\",\"modular systems\",\"modulare Systeme\",\"num\u00e9risation\",\"Paternoster\",\"p\u00e9nurie de comp\u00e9tences\",\"prestataires de services logistiques\",\"production space\",\"Produktionsfl\u00e4chen\",\"skills shortage Fran\u00e7ais Gilgen Logistics\",\"small goods lift\",\"solutions de transport vertical\",\"strat\u00e9gies logistiques\",\"Supply Chain\",\"syst\u00e8mes d'intralogistique\",\"syst\u00e8mes modulaires\",\"technologie de manutention des conteneurs\",\"technologie de transport\",\"transport containers\",\"Transportbeh\u00e4lter\",\"Umlauff\u00f6rderer\",\"urban areas\",\"urbanen Gebieten\",\"vertical conveying solutions\",\"vertikale F\u00f6rderl\u00f6sungen\",\"zones urbaines\"],\"articleSection\":[\"Europa\",\"Expeditie &amp; Logistiek\",\"Intralogistiek\",\"Zwitserland\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/\",\"name\":\"Gilgen Logistics presenteert verticale transportsystemen - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/AdobeStock_605908084-1-scaled-1.jpeg\",\"datePublished\":\"2026-03-26T09:06:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/AdobeStock_605908084-1-scaled-1.jpeg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/02\\\/AdobeStock_605908084-1-scaled-1.jpeg\",\"width\":2560,\"height\":1435,\"caption\":\"digital warehouse with electronic grids connected to a bar code scanner. Generative Ai\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2026\\\/03\\\/26\\\/gilgen-logistics-presenteert-verticale-transportsystemen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gilgen Logistics presenteert verticale transportsystemen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\",\"name\":\"Logismedia Groep AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Groep AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/person\\\/41d36b5474b623392fa613e97e2363fa\",\"name\":\"Jeremy Soland\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/author\\\/jeremy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gilgen Logistics presenteert verticale transportsystemen - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/","og_locale":"nl_NL","og_type":"article","og_title":"Gilgen Logistics presenteert verticale transportsystemen - Loginfo24","og_description":"Gilgen Logistics presenteert op de LogiMAT 2026 verticale transportsystemen die bedrijven moeten helpen hun intralogistiek aan te passen aan stedelijke uitdagingen en ruimte effici\u00ebnt te benutten.","og_url":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-03-26T09:06:43+00:00","og_image":[{"width":2560,"height":1435,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/AdobeStock_605908084-1-scaled-1.jpeg","type":"image\/jpeg"}],"author":"Jeremy Soland","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Jeremy Soland","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/"},"author":{"name":"Jeremy Soland","@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa"},"headline":"Gilgen Logistics presenteert verticale transportsystemen","datePublished":"2026-03-26T09:06:43+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/"},"wordCount":173,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/AdobeStock_605908084-1-scaled-1.jpeg","keywords":["am\u00e9lioration de l'efficacit\u00e9","Beh\u00e4lterf\u00f6rdertechnik","Brandschutzanforderungen","cha\u00eene d'approvisionnement","circulating conveyor","container handling technology","conteneurs de transport","conveyor technology","convoyeur circulaire","Deutsch Gilgen Logistics","Digitalisierung","digitalization","efficiency improvement","Effizienzsteigerung","\u00e9l\u00e9vateur de petits colis","espaces de production","exigences de s\u00e9curit\u00e9 incendie","Fachkr\u00e4ftemangel English Gilgen Logistics","fire safety requirements","F\u00f6rdertechnik","intralogistics systems","Intralogistiksysteme","Kleing\u00fcteraufzug","LogiMAT 2026","logistics service providers","logistics strategies","Logistikdienstleister","Logistikstrategien","modular systems","modulare Systeme","num\u00e9risation","Paternoster","p\u00e9nurie de comp\u00e9tences","prestataires de services logistiques","production space","Produktionsfl\u00e4chen","skills shortage Fran\u00e7ais Gilgen Logistics","small goods lift","solutions de transport vertical","strat\u00e9gies logistiques","Supply Chain","syst\u00e8mes d'intralogistique","syst\u00e8mes modulaires","technologie de manutention des conteneurs","technologie de transport","transport containers","Transportbeh\u00e4lter","Umlauff\u00f6rderer","urban areas","urbanen Gebieten","vertical conveying solutions","vertikale F\u00f6rderl\u00f6sungen","zones urbaines"],"articleSection":["Europa","Expeditie &amp; Logistiek","Intralogistiek","Zwitserland"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/","url":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/","name":"Gilgen Logistics presenteert verticale transportsystemen - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/AdobeStock_605908084-1-scaled-1.jpeg","datePublished":"2026-03-26T09:06:43+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/AdobeStock_605908084-1-scaled-1.jpeg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/02\/AdobeStock_605908084-1-scaled-1.jpeg","width":2560,"height":1435,"caption":"digital warehouse with electronic grids connected to a bar code scanner. Generative Ai"},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/nl\/2026\/03\/26\/gilgen-logistics-presenteert-verticale-transportsystemen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Gilgen Logistics presenteert verticale transportsystemen"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/nl\/#website","url":"https:\/\/loginfo24.com\/nl\/","name":"Loginfo24","description":"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.","publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/nl\/#organization","name":"Logismedia Groep AG","url":"https:\/\/loginfo24.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Groep AG"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/person\/41d36b5474b623392fa613e97e2363fa","name":"Jeremy Soland","url":"https:\/\/loginfo24.com\/nl\/author\/jeremy\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/77404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/comments?post=77404"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/77404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media\/74847"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media?parent=77404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/categories?post=77404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/tags?post=77404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}