{"id":69122,"date":"2025-05-10T19:11:13","date_gmt":"2025-05-10T17:11:13","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/"},"modified":"2025-05-10T19:11:13","modified_gmt":"2025-05-10T17:11:13","slug":"osterreichse-post-heeft-ambitieuze-plannen","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/","title":{"rendered":"\u00d6sterreichse Post heeft ambitieuze plannen"},"content":{"rendered":"<h5><strong>De \u00d6sterreichse Post AG heeft in een breed opgezet strategieproces een update van haar bedrijfsstrategie ontwikkeld. De visie: Tegen 2030 wil de \u00d6sterreichse Post een van de toonaangevende logistieke en dienstverlenende groepen in Oostenrijk, Centraal- en Oost-Europa, evenals Turkije en daarbuiten zijn \u2013 met meer dan 150 miljoen tevreden klanten en een omzet van vier miljard euro. <\/strong><\/h5>\n<p>(Wenen) Walter Oblin, algemeen directeur, \u00d6sterreichse Post AG: \u201eDe \u00d6sterreichse Post is een modern, internationaal succesvol bedrijf en moet dat ook in de toekomst blijven. Daarom willen we het platform Post in Oostenrijk uitbreiden met aanvullende diensten, in de pakketdienst nog sterker als internationale groep groeien en als ge\u00efntegreerde groep synergiepotentieel over alle gebieden en regio&#8217;s benutten. Met deze strategie willen we tegen 2030 winstgevend groeien naar een omzet van vier miljard euro, een pionier zijn op het gebied van duurzaamheid en een aantrekkelijke werkgever voor onze ongeveer 30.000 betrokken medewerkers nationaal en internationaal zijn.\u201c<\/p>\n<h5><strong>Herziene bedrijfsstrategie is gebaseerd op drie pijlers:<\/strong><\/h5>\n<ol>\n<li>Meer dan Post in Oostenrijk: De Post blijft marktleider in de brief- en pakketdienst met topbezorging. Daarnaast biedt zij met postkantoren, postpartners en digitale kanalen een aantrekkelijk platform voor belangrijke aanvullende diensten zoals bankieren met de eigen bank99. Ook het telecommunicatieaanbod zal verder worden uitgebreid.<\/li>\n<li>Internationaal sterk in de pakketdienst: De Post is internationaal een sterke speler en wil hier verder groeien. Ze zal blijven investeren in bestaande markten en nieuwe markten aanboren. Met dochterondernemingen in Zuidoost- en Oost-Europa, evenals Turkije en daarbuiten, bedient zij meer dan 150 miljoen tevreden klanten met kwalitatief hoogwaardige pakketbezorging.<\/li>\n<li>Een bedrijfsgroep \u2013 operationeel uitstekend: Met ongeveer 30.000 medewerkers in binnen- en buitenland wil de Post als groep de samenwerking verder versterken en synergie\u00ebn benutten - lokaal ondernemend en internationaal verbonden. Daarbij ontwikkelt zij haar processen voortdurend met de ambitie van operationele excellentie en werkt zij aan effici\u00ebntieverbeteringen door automatisering, digitalisering, robotica en kunstmatige intelligentie (AI).<\/li>\n<\/ol>\n<p>Duurzaamheid, klantgerichtheid en bedrijfscultuur vormen centrale strategische richtlijnen voor de gehele bedrijfsorganisatie.<\/p>\n<h5><strong>Post plant eigen mobiele telefoonaanbod<\/strong><\/h5>\n<p>Een eerste concrete maatregel van de herziene bedrijfsstrategie is de geplande uitbreiding van het telecommunicatieaanbod: De \u00d6sterreichse Post en A1 kijken terug op succesvolle jaren van een gezamenlijke verkoop samenwerking. In de toekomst zal de Post nieuwe accenten leggen en als virtuele mobiele aanbieder haar klanten eigen telecommunicatietarieven aanbieden. De bestaande verkoopovereenkomst tussen de Post en A1 loopt eind 2025 af, in het tweede kwartaal van 2026 zal de Post als virtuele mobiele aanbieder met een eigen merk in het netwerk van A1 optreden.<\/p>\n<p>Foto: \u00a9 \u00d6sterreichse Post AG<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De \u00d6sterreichse Post AG heeft in een breed opgezet strategieproces een update van haar bedrijfsstrategie ontwikkeld. De visie: Tegen 2030 wil de \u00d6sterreichse Post een van<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5029,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-69122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00d6sterreichse Post heeft ambitieuze plannen - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00d6sterreichse Post heeft ambitieuze plannen - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"De \u00d6sterreichse Post AG heeft in een breed opgezet strategieproces een update van haar bedrijfsstrategie ontwikkeld. De visie: Tegen 2030 wil de \u00d6sterreichse Post een van [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-10T17:11:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.5.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"760\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00d6sterreichse Post heeft ambitieuze plannen\",\"datePublished\":\"2025-05-10T17:11:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.5.25.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/\",\"name\":\"\u00d6sterreichse Post heeft ambitieuze plannen - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.5.25.jpg\",\"datePublished\":\"2025-05-10T17:11:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.5.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Post_AT_10.5.25.jpg\",\"width\":1365,\"height\":760},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2025\\\/05\\\/10\\\/osterreichse-post-heeft-ambitieuze-plannen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00d6sterreichse Post heeft ambitieuze plannen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\",\"name\":\"Logismedia Groep AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Groep AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d6sterreichse Post heeft ambitieuze plannen - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/","og_locale":"nl_NL","og_type":"article","og_title":"\u00d6sterreichse Post heeft ambitieuze plannen - Loginfo24","og_description":"De \u00d6sterreichse Post AG heeft in een breed opgezet strategieproces een update van haar bedrijfsstrategie ontwikkeld. De visie: Tegen 2030 wil de \u00d6sterreichse Post een van [\u2026]","og_url":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-05-10T17:11:13+00:00","og_image":[{"width":1365,"height":760,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.5.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/"},"author":{"name":"","@id":""},"headline":"\u00d6sterreichse Post heeft ambitieuze plannen","datePublished":"2025-05-10T17:11:13+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.5.25.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/","url":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/","name":"\u00d6sterreichse Post heeft ambitieuze plannen - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.5.25.jpg","datePublished":"2025-05-10T17:11:13+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.5.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Post_AT_10.5.25.jpg","width":1365,"height":760},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/nl\/2025\/05\/10\/osterreichse-post-heeft-ambitieuze-plannen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/nl\/"},{"@type":"ListItem","position":2,"name":"\u00d6sterreichse Post heeft ambitieuze plannen"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/nl\/#website","url":"https:\/\/loginfo24.com\/nl\/","name":"Loginfo24","description":"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.","publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/nl\/#organization","name":"Logismedia Groep AG","url":"https:\/\/loginfo24.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Groep AG"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/69122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/comments?post=69122"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/69122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media\/5029"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media?parent=69122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/categories?post=69122"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/tags?post=69122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}