{"id":65538,"date":"2024-06-06T13:10:20","date_gmt":"2024-06-06T11:10:20","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/"},"modified":"2024-06-06T13:10:20","modified_gmt":"2024-06-06T11:10:20","slug":"gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/","title":{"rendered":"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector"},"content":{"rendered":"<h5><strong>Gemanipuleerde GPS-signalen veroorzaken in de logistieke sector hoge schade en brengen talrijke risico&#8217;s met zich mee. De oplossingen met GPS-Anti-Spam-Technologie (GAJT) van NovAtel uit het huis Hexagon kunnen storingssignalen lokaliseren en onderdrukken om een betrouwbare positionering, tijdmeting en navigatie te waarborgen. Exclusieve distributeur in Duitsland is de ppm precise position management GmbH.<\/strong><\/h5>\n<p>(Penzberg) \u201eEen continue GPS-ontvangst is belangrijk voor een soepele scheepvaart- en vrachtverkeer, maar vooral in de Oostzee en de Middellandse Zee komen steeds vaker signaalstoringen voor\u201c, zegt Michael Singer, directeur van ppm GmbH. \u201eDe GAJT-oplossingen van NovAtel helpen transportbedrijven dure routewijzigingen of stijgende verzekeringspremies te vermijden.\u201c<\/p>\n<p>Aangezien de meeste transportbedrijven gebruikmaken van verschillende globale satellietnavigatiesystemen (GNSS), vormt de storing meestal geen acute bedreiging voor medewerkers en passagiers. Er zijn echter al vluchten geannuleerd, routes gewijzigd en zijn er laadslots in de haven gemist, wat in elk geval zeer hoge kosten met zich meebrengt.<\/p>\n<p>Maar niet alleen jamming, dat wil zeggen het verstoren of onderbreken van satellietsignalen, zorgt in de logistieke sector voor stijgende kosten. Criminelen proberen ook steeds weer met spoofing, het opzettelijk voorwenden van een vals satellietnavigatiesignaal, vrachtwagens met waardevolle lading op een verkeerde route te loodsen om de vracht te stelen.<\/p>\n<h5><strong>Storingssignalen automatisch herkennen<\/strong><\/h5>\n<p>Met de GAJT-oplossingen kunnen deze problemen worden vermeden, want ze beschermen de systemen tegen hoogfrequent storingen (RF) en invloeden. Daartoe is de GAJT-productfamilie uitgerust met een reeks gevoelige sensoren en complexe algoritmen die de storingszender kunnen lokaliseren. Dit gebeurt onder andere door de waarneming van de signaalbeweging: terwijl het GPS-signaal van een satelliet komt die zich met een snelheid van ongeveer vier kilometer per seconde door de ruimte beweegt, is het storingssignaal meestal statisch en op de grond geplaatst. De GAJT-antennes herkennen automatisch een storingssignaal en maken daarvan een digitaal beeld. Het algoritme is in staat om het storingssignaal te elimineren. De GNSS-ontvanger aan boord van een voertuig of vrachtschip ontvangt zo voortdurend correcte satellietgegevens.<\/p>\n<p>Bovendien bieden de GAJT-systemen het voordeel dat gebruikers hun bestaande satellietnavigatiesystemen eenvoudig kunnen blijven gebruiken. Alleen de antenne hoeft te worden vervangen door het GAJT-systeem om beschermd te zijn tegen jamming en spoofing.<\/p>\n<h5><strong>Oplossingen voor vlootbeheer en maritieme toepassingen<\/strong><\/h5>\n<p>De ppm GmbH heeft twee verschillende GAJT-systemen van NovAtel uit het huis Hexagon in het programma. Zowel de GAJT 710-serie als de GAJT 410-serie biedt een betrouwbare verdedigingslaag tegen RF-interferenties en storingsaanvallen. Terwijl de GAJT 410-producten zich onderscheiden door een lager gewicht en formaat, beschikken de GAJT 710-producten over meer antennesegmenten en maken ze daarmee een nog nauwkeurigere lokalisatie van het storingssignaal mogelijk. Bovendien zijn ze uitgerust met een \u201eSilent-Mode-functie\u201c, zodat ze niet zo gemakkelijk te ontdekken zijn. Beide series zijn beschikbaar in een uitvoering voor landvoertuigen, zoals vrachtwagens of waardevolle transporten, evenals in een variant voor maritieme toepassingen, zoals tankers, containerfrachters en cruiseschepen. Ook kustnahe inzetten, zoals bijvoorbeeld hydrografische metingen, scheepsbouw, baggerwerkzaamheden en loodsen, kunnen hiermee worden beschermd.<\/p>\n<p>Foto: \u00a9 NovAtel Inc. \/ <strong><em>Bijschrift:<\/em><\/strong><em> GPS-Anti-Spam-Technologie, kort GAJT, voor veilige GPS-ontvangst<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gemanipuleerde GPS-signalen veroorzaken in de logistieke sector hoge schade en brengen talrijke risico&#8217;s met zich mee. De oplossingen met GPS-Anti-Spam-Technologie (GAJT) van NovAtel uit het huis<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6415,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-65538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Gemanipuleerde GPS-signalen veroorzaken in de logistieke sector hoge schade en brengen talrijke risico&#8217;s met zich mee. De oplossingen met GPS-Anti-Spam-Technologie (GAJT) van NovAtel uit het huis [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T11:10:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hexagon_5.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1272\" \/>\n\t<meta property=\"og:image:height\" content=\"710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector\",\"datePublished\":\"2024-06-06T11:10:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/\"},\"wordCount\":490,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hexagon_5.6.24.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/\",\"name\":\"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hexagon_5.6.24.jpg\",\"datePublished\":\"2024-06-06T11:10:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hexagon_5.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Hexagon_5.6.24.jpg\",\"width\":1272,\"height\":710},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2024\\\/06\\\/06\\\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\",\"name\":\"Logismedia Groep AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Groep AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/","og_locale":"nl_NL","og_type":"article","og_title":"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector - Loginfo24","og_description":"Gemanipuleerde GPS-signalen veroorzaken in de logistieke sector hoge schade en brengen talrijke risico&#8217;s met zich mee. De oplossingen met GPS-Anti-Spam-Technologie (GAJT) van NovAtel uit het huis [\u2026]","og_url":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-06T11:10:20+00:00","og_image":[{"width":1272,"height":710,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hexagon_5.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/"},"author":{"name":"","@id":""},"headline":"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector","datePublished":"2024-06-06T11:10:20+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/"},"wordCount":490,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hexagon_5.6.24.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/","url":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/","name":"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hexagon_5.6.24.jpg","datePublished":"2024-06-06T11:10:20+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hexagon_5.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Hexagon_5.6.24.jpg","width":1272,"height":710},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/nl\/2024\/06\/06\/gemanipuleerde-gps-signalen-veroorzaken-schade-in-de-logistieke-sector\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Gemanipuleerde GPS-signalen veroorzaken schade in de logistieke sector"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/nl\/#website","url":"https:\/\/loginfo24.com\/nl\/","name":"Loginfo24","description":"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.","publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/nl\/#organization","name":"Logismedia Groep AG","url":"https:\/\/loginfo24.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Groep AG"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/65538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/comments?post=65538"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/65538\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media\/6415"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media?parent=65538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/categories?post=65538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/tags?post=65538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}