{"id":56968,"date":"2022-06-15T17:39:15","date_gmt":"2022-06-15T15:39:15","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/"},"modified":"2022-06-15T17:39:15","modified_gmt":"2022-06-15T15:39:15","slug":"rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/","title":{"rendered":"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig"},"content":{"rendered":"<h5><strong>Met zonnepanelen op de transporter het bereik verlengen: Of dit in de praktijk werkt, test Rhenus Home Delivery nu door zonne-energiegegevens te meten met een testvoertuig. De ervaringen uit de metingen kunnen helpen om de vloot op lange termijn duurzamer te maken met toekomstgerichte technologie\u00ebn.<\/strong><\/h5>\n<p>(Holzwickede) De Rhenus Groep, een van de toonaangevende logistieke dienstverleners ter wereld, streeft er voortdurend naar om de eigen vloot duurzamer te maken met alternatieve aandrijvingen. Om te onderzoeken of zonne-energie hiervoor een valide optie is, zet Rhenus Home Delivery nu een testvoertuig met zonne-energie meettechniek in. Hiervoor werkt de specialist in de levering aan eindklanten samen met Sono Motors. Het doel is om te achterhalen in hoeverre zonnepanelen op het voertuigoppervlak het bereik kunnen verlengen \u2013 en welk potentieel de technologie biedt voor grootschalig gebruik in de toekomst.<\/p>\n<h5><strong>Test loopt over vier seizoenen<\/strong><\/h5>\n<p>Van de felle zon in de zomer tot regenachtige winterdagen: Om realistische gemiddelden te verkrijgen, heeft Rhenus de test als een langlopend project over vier seizoenen opgezet. Verlichtingssterktesensoren aan beide zijden en op het dak van de nog conventioneel aangedreven 15-tonner meten continu de intensiteit van de zonnestraling. Een via LTE verbonden datalogger verzendt bovendien het exacte tijdstip van de meting naar Sono Motors, waar alle meetgegevens aan concrete resultaten worden gekoppeld. Vanuit het Brandenburgse Hoppegarten nabij Berlijn is het voertuig tijdens de testfase actief in Berlijn, Brandenburg en Mecklenburg-Voor-Pommeren. Jonas von Frieling, hoofd van het Innovatiecentrum van de bedrijfstakken Rhenus Home Delivery en Rhenus High Tech, legt uit: &#8220;Als twee bedrijven vol innovatiekracht en daadkracht passen Rhenus en Sono Motors perfect bij zo&#8217;n toekomstgericht project.&#8221;<\/p>\n<h5><strong>Zonnepanelen op voertuigen kunnen het elektriciteitsnet ontlasten<\/strong><\/h5>\n<p>Bij de vloot zet Rhenus Home Delivery steeds meer in op alternatieve aandrijvingen. Maar het testproject heeft nog veel meer potentieel: innovatieve technologie\u00ebn zoals zonne-ondersteunde elektrische vrachtwagens zouden in de toekomst een groot deel kunnen bijdragen aan de energietransitie, omdat voor deze vorm van ecologische elektriciteitsopwekking geen extra grond hoeft te worden verhard. &#8220;Als het verkeer op grote schaal overgaat op elektrische aandrijvingen, moet de energievoorziening mee groeien. Zonnepanelen op voertuigen zouden het elektriciteitsnet kunnen ontlasten. Met ons testproject zijn we hier als pionier aan de slag,&#8221; zegt Jonas von Frieling.<\/p>\n<p>Foto: \u00a9 Rhenus Home Delivery<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Met zonnepanelen op de transporter het bereik verlengen: Of dit in de praktijk werkt, test Rhenus Home Delivery nu door zonne-energiegegevens te meten met een testvoertuig.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":10030,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-56968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Met zonnepanelen op de transporter het bereik verlengen: Of dit in de praktijk werkt, test Rhenus Home Delivery nu door zonne-energiegegevens te meten met een testvoertuig. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-06-15T15:39:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_15.6.22.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1457\" \/>\n\t<meta property=\"og:image:height\" content=\"745\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig\",\"datePublished\":\"2022-06-15T15:39:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/\"},\"wordCount\":376,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_15.6.22.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/\",\"name\":\"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_15.6.22.jpg\",\"datePublished\":\"2022-06-15T15:39:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_15.6.22.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Rhenus_15.6.22.jpg\",\"width\":1457,\"height\":745},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/2022\\\/06\\\/15\\\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#organization\",\"name\":\"Logismedia Groep AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Groep AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/","og_locale":"nl_NL","og_type":"article","og_title":"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig - Loginfo24","og_description":"Met zonnepanelen op de transporter het bereik verlengen: Of dit in de praktijk werkt, test Rhenus Home Delivery nu door zonne-energiegegevens te meten met een testvoertuig. [\u2026]","og_url":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2022-06-15T15:39:15+00:00","og_image":[{"width":1457,"height":745,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_15.6.22.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Geschatte leestijd":"2 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/"},"author":{"name":"","@id":""},"headline":"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig","datePublished":"2022-06-15T15:39:15+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/"},"wordCount":376,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_15.6.22.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"nl-NL","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/","url":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/","name":"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/nl\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_15.6.22.jpg","datePublished":"2022-06-15T15:39:15+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_15.6.22.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Rhenus_15.6.22.jpg","width":1457,"height":745},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/nl\/2022\/06\/15\/rhenus-home-delivery-meet-zonne-energiegegevens-met-testvoertuig\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/nl\/"},{"@type":"ListItem","position":2,"name":"Rhenus Home Delivery meet zonne-energiegegevens met testvoertuig"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/nl\/#website","url":"https:\/\/loginfo24.com\/nl\/","name":"Loginfo24","description":"Loginfo24 is het platform voor logistiek en toeleveringsketens en biedt 24 uur per dag informatie.","publisher":{"@id":"https:\/\/loginfo24.com\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/nl\/#organization","name":"Logismedia Groep AG","url":"https:\/\/loginfo24.com\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Groep AG"},"image":{"@id":"https:\/\/loginfo24.com\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/56968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/comments?post=56968"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/posts\/56968\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media\/10030"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/media?parent=56968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/categories?post=56968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/nl\/wp-json\/wp\/v2\/tags?post=56968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}