{"id":78432,"date":"2026-04-15T12:57:25","date_gmt":"2026-04-15T12:57:25","guid":{"rendered":"https:\/\/loginfo24.com\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/"},"modified":"2026-04-15T12:57:25","modified_gmt":"2026-04-15T12:57:25","slug":"progetto-distill-in-lusazia-concluso-con-successo","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/","title":{"rendered":"Progetto DiSTILL in Lusazia concluso con successo"},"content":{"rendered":"<p>Il progetto DiSTILL, che si \u00e8 svolto nell&#8217;arco di circa tre anni, ha raggiunto con successo la sua conclusione. Il 15 aprile 2026 \u00e8 stato presentato, nell&#8217;ambito di un evento di chiusura digitale, lo strumento di pianificazione e simulazione digitale concepito per lo sviluppo del bacino della Lusazia come hub logistico internazionale. Lo strumento \u00e8 ora disponibile in una fase di sviluppo finale ed \u00e8 stato continuamente ottimizzato durante il corso del progetto.<\/p>\n<h3>Piattaforma di analisi completa per i processi logistici<\/h3>\n<p>Lo strumento DiSTILL offre a imprese, pianificatori e decisori regionali una piattaforma completa per l&#8217;analisi dei processi di trasporto e logistica multimodali nella Lusazia. Integra il trasporto su strada, ferrovia e via acqua, consentendo una rappresentazione trasparente dei flussi di trasporto. I colli di bottiglia e i rischi di capacit\u00e0 possono essere identificati in anticipo.<\/p>\n<p>Su questa base, possono essere simulati scenari di sviluppo futuri fino al 2040, variando diversi parametri come il volume di traffico e le capacit\u00e0 infrastrutturali. Dati dettagliati sulle tariffe forniscono una base dati solida per l&#8217;analisi dei flussi di merci reali. Per le aziende logistiche, ci\u00f2 significa che le catene di trasporto possono essere pianificate in modo pi\u00f9 informato e possono essere valutate rotte alternative.<\/p>\n<p>L&#8217;integrazione della rete di trasporto transeuropea (TEN-T) e di corridoi centrali come Mare del Nord-Mare Baltico, Reno-Danubio o Scandinavia-Mediterraneo consente di inquadrare la Lusazia all&#8217;interno di strutture di trasporto europee superiori. Inoltre, sono state integrate informazioni sui luoghi di aeroporti nella piattaforma, consentendo una visione congiunta di tutti i mezzi di trasporto rilevanti: strada, ferrovia, via d&#8217;acqua e trasporto aereo. Questo apre nuove prospettive per lo sviluppo della Lusazia come sede logistica nel contesto internazionale.<\/p>\n<h3>Utilit\u00e0 scientifica e strategica<\/h3>\n<p>Il Prof. Dr.-Ing. Frank Straube, responsabile del settore logistica presso la TU Berlino e project manager di DiSTILL, sottolinea: &#8222;DiSTILL \u00e8 uno strumento che collega scienza, pianificazione strategica e requisiti pratici della logistica. Per le aziende e le autorit\u00e0 pubbliche nella Lusazia, lo strumento offre nuove opportunit\u00e0 per prendere decisioni su trasporti e infrastrutture non solo sulla base di dati passati, ma includendo scenari futuri ben fondati.&#8220; Questo crea sicurezza nella pianificazione e rafforza la competitivit\u00e0 della regione.<\/p>\n<p>Andr\u00e9 Fritsche, direttore generale della Camera di commercio e industria (IHK) di Cottbus, evidenzia che il progetto DiSTILL ha riunito importanti attori del settore e che con lo strumento di simulazione sono state rese visibili potenzialit\u00e0. Questo \u00e8 cruciale per la Lusazia, per posizionarsi chiaramente nella competizione tra sedi logistiche.<\/p>\n<h3>Rilevanza pratica e feedback degli utenti<\/h3>\n<p>La rilevanza pratica dello strumento DiSTILL \u00e8 emersa chiaramente attraverso vari utenti durante l&#8217;evento di chiusura. Ron Fiskal, project manager presso Lobbe Industrieservice GmbH &amp; Co KG, spiega: &#8222;I nodi e le informazioni aggregate nello strumento DiSTILL ci hanno risparmiato molto lavoro di ricerca e ci hanno supportato nello sviluppo di una nuova catena di trasporto dalla Lusazia alla Svizzera.&#8220;<\/p>\n<p>Sven Noatzke, amministratore delegato del Lion Group, sottolinea il valore dell&#8217;accesso gratuito all&#8217;iFrame dello strumento, che consente di avere una visione trasparente dei dati di traffico e posizione della regione. Mario Naumann, responsabile della Supply Chain &amp; Site Logistics presso BASF InfraService &amp; Solutions Lausitz GmbH, evidenzia l&#8217;importanza di dati trasparenti e di alta qualit\u00e0 per lo sviluppo strategico della logistica di sede.<\/p>\n<p>Roland Peine, amministratore delegato tecnico della ASG Spremberg GmbH, descrive lo strumento DiSTILL come un prezioso patrimonio di conoscenze che supporta i colloqui con le aziende locali. Uwe Franz, team leader presso Rhenus Freight East GmbH, aggiunge che i risultati dello strumento forniscono informazioni solide e aiutano nell&#8217;approccio mirato a nuovi clienti.<\/p>\n<h3>Disponibilit\u00e0 a lungo termine dello strumento<\/h3>\n<p>Sebbene il progetto si concluda ufficialmente il 30 aprile 2026, lo strumento DiSTILL rimarr\u00e0 accessibile per almeno dieci anni. I dati e la piattaforma continueranno a essere disponibili, consentendo a imprese, pianificatori e istituzioni di utilizzare le informazioni per decisioni informate su infrastrutture, catene di trasporto e sviluppo di sedi.<\/p>\n<p>Piattaforma DiSTILL: <a href=\"http:\/\/www.distill-lausitz.de\" target=\"_blank\" rel=\"noopener noreferrer\">www.distill-lausitz.de<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il progetto DiSTILL ha sviluppato con successo uno strumento digitale per l&#8217;analisi dei processi logistici in Lusazia, che rimarr\u00e0 disponibile per almeno dieci anni.<\/p>\n","protected":false},"author":7,"featured_media":78428,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6679,6667,1629],"tags":[20169,20170,20171,20172,20173,20174,20175,20176,20177,20178,20179,20180,20181,20182,20183,20184,20185,20186,20187,20188,20189,20190,20191,20192,2525,2526,20193,20194,15659,20195,20196,2479,20197,20198,20199,20200,2869,15666,15333,20201,20202,20203,20204,20205,20206,20207,15340,15341,20208,20209,20210,20211,20212],"class_list":["post-78432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-germania","category-spedizioni-e-logistica","tag-analyse-des-flux-de-transport-de-marchandises","tag-basf-infraservice-lausitz","tag-capacity-risks-identification","tag-chambre-de-commerce-de-cottbus-logistique","tag-cottbus-chamber-of-commerce-logistics","tag-deutsch-distill-projekt","tag-developpement-des-infrastructures-lausitz","tag-digital-planning-and-simulation-tools","tag-digitale-planungs-und-simulations-tools","tag-fachkraeftemangel-logistik-english-distill-project","tag-freight-transport-flow-analysis","tag-future-scenario-simulation","tag-gueterverkehrsstroeme-analyse","tag-identification-des-risques-de-capacite","tag-ihk-cottbus-logistik","tag-infrastructure-development-lausitz","tag-infrastrukturentwicklung-lausitz","tag-international-logistics-hub","tag-internationale-logistikdrehscheibe","tag-kapazitaetsrisiken-identifizieren","tag-lausitz-logistics","tag-lausitz-logistik","tag-lobbe-industrieservice-gmbh","tag-logistics-hub-lausitz","tag-logistics-service-providers-germany","tag-logistikdienstleister-deutschland","tag-logistikstandort-lausitz","tag-logistique-lausitz","tag-multimodal-transport-processes","tag-multimodale-verkehrsprozesse","tag-outils-de-planification-et-de-simulation-numeriques","tag-penurie-de-competences-logistique","tag-planification-des-chaines-de-transport","tag-planification-logistique-strategique","tag-pole-logistique-international","tag-pole-logistique-lausitz","tag-prestataires-de-services-logistiques-allemagne","tag-processus-de-transport-multimodal","tag-reseau-de-transport-ten-t","tag-rhenus-freight-east","tag-road-rail-water-transport","tag-simulation-de-scenarios-futurs","tag-skills-shortage-logistics-francais-projet-distill","tag-strassen-schienen-wasserverkehr","tag-strategic-logistics-planning","tag-strategische-logistikplanung","tag-ten-t-transport-network","tag-ten-t-verkehrsnetz","tag-transport-chain-planning","tag-transport-routier-ferroviaire-fluvial","tag-transportketten-planung","tag-verkehrs-und-standortdaten","tag-zukunftsszenarien-simulation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Progetto DiSTILL in Lusazia concluso con successo - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progetto DiSTILL in Lusazia concluso con successo - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il progetto DiSTILL ha sviluppato con successo uno strumento digitale per l&#039;analisi dei processi logistici in Lusazia, che rimarr\u00e0 disponibile per almeno dieci anni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-15T12:57:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/04\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1-1200x675.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andreas M\u00fcller\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas M\u00fcller\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/\"},\"author\":{\"name\":\"Andreas M\u00fcller\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/person\\\/7b1593b33567ba798d300c8a1b0b85b1\"},\"headline\":\"Progetto DiSTILL in Lusazia concluso con successo\",\"datePublished\":\"2026-04-15T12:57:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/\"},\"wordCount\":658,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/04\\\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png\",\"keywords\":[\"analyse des flux de transport de marchandises\",\"BASF InfraService Lausitz\",\"capacity risks identification\",\"Chambre de commerce de Cottbus logistique\",\"Cottbus Chamber of Commerce logistics\",\"Deutsch DiSTILL-Projekt\",\"d\u00e9veloppement des infrastructures Lausitz\",\"digital planning and simulation tools\",\"digitale Planungs- und Simulations-Tools\",\"Fachkr\u00e4ftemangel Logistik English DiSTILL project\",\"freight transport flow analysis\",\"future scenario simulation\",\"G\u00fcterverkehrsstr\u00f6me Analyse\",\"identification des risques de capacit\u00e9\",\"IHK Cottbus Logistik\",\"infrastructure development Lausitz\",\"Infrastrukturentwicklung Lausitz\",\"international logistics hub\",\"internationale Logistikdrehscheibe\",\"Kapazit\u00e4tsrisiken identifizieren\",\"Lausitz logistics\",\"Lausitz Logistik\",\"Lobbe Industrieservice GmbH\",\"logistics hub Lausitz\",\"logistics service providers Germany\",\"Logistikdienstleister Deutschland\",\"Logistikstandort Lausitz\",\"logistique Lausitz\",\"multimodal transport processes\",\"multimodale Verkehrsprozesse\",\"outils de planification et de simulation num\u00e9riques\",\"p\u00e9nurie de comp\u00e9tences logistique\",\"planification des cha\u00eenes de transport\",\"planification logistique strat\u00e9gique\",\"p\u00f4le logistique international\",\"p\u00f4le logistique Lausitz\",\"prestataires de services logistiques Allemagne\",\"processus de transport multimodal\",\"r\u00e9seau de transport TEN-T\",\"Rhenus Freight East\",\"road rail water transport\",\"simulation de sc\u00e9narios futurs\",\"skills shortage logistics Fran\u00e7ais projet DiSTILL\",\"Stra\u00dfen Schienen Wasserverkehr\",\"strategic logistics planning\",\"strategische Logistikplanung\",\"TEN-T transport network\",\"TEN-T Verkehrsnetz\",\"transport chain planning\",\"transport routier ferroviaire fluvial\",\"Transportketten Planung\",\"Verkehrs- und Standortdaten\",\"Zukunftsszenarien Simulation\"],\"articleSection\":[\"Europa\",\"Germania\",\"Spedizioniere e Logistica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/\",\"name\":\"Progetto DiSTILL in Lusazia concluso con successo - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/04\\\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png\",\"datePublished\":\"2026-04-15T12:57:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/04\\\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/04\\\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/04\\\/15\\\/progetto-distill-in-lusazia-concluso-con-successo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetto DiSTILL in Lusazia concluso con successo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/person\\\/7b1593b33567ba798d300c8a1b0b85b1\",\"name\":\"Andreas M\u00fcller\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/author\\\/logismedia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Progetto DiSTILL in Lusazia concluso con successo - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/","og_locale":"it_IT","og_type":"article","og_title":"Progetto DiSTILL in Lusazia concluso con successo - Loginfo24","og_description":"Il progetto DiSTILL ha sviluppato con successo uno strumento digitale per l'analisi dei processi logistici in Lusazia, che rimarr\u00e0 disponibile per almeno dieci anni.","og_url":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-04-15T12:57:25+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/04\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1-1200x675.png","type":"image\/png"}],"author":"Andreas M\u00fcller","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andreas M\u00fcller","Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/"},"author":{"name":"Andreas M\u00fcller","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/person\/7b1593b33567ba798d300c8a1b0b85b1"},"headline":"Progetto DiSTILL in Lusazia concluso con successo","datePublished":"2026-04-15T12:57:25+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/"},"wordCount":658,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/04\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png","keywords":["analyse des flux de transport de marchandises","BASF InfraService Lausitz","capacity risks identification","Chambre de commerce de Cottbus logistique","Cottbus Chamber of Commerce logistics","Deutsch DiSTILL-Projekt","d\u00e9veloppement des infrastructures Lausitz","digital planning and simulation tools","digitale Planungs- und Simulations-Tools","Fachkr\u00e4ftemangel Logistik English DiSTILL project","freight transport flow analysis","future scenario simulation","G\u00fcterverkehrsstr\u00f6me Analyse","identification des risques de capacit\u00e9","IHK Cottbus Logistik","infrastructure development Lausitz","Infrastrukturentwicklung Lausitz","international logistics hub","internationale Logistikdrehscheibe","Kapazit\u00e4tsrisiken identifizieren","Lausitz logistics","Lausitz Logistik","Lobbe Industrieservice GmbH","logistics hub Lausitz","logistics service providers Germany","Logistikdienstleister Deutschland","Logistikstandort Lausitz","logistique Lausitz","multimodal transport processes","multimodale Verkehrsprozesse","outils de planification et de simulation num\u00e9riques","p\u00e9nurie de comp\u00e9tences logistique","planification des cha\u00eenes de transport","planification logistique strat\u00e9gique","p\u00f4le logistique international","p\u00f4le logistique Lausitz","prestataires de services logistiques Allemagne","processus de transport multimodal","r\u00e9seau de transport TEN-T","Rhenus Freight East","road rail water transport","simulation de sc\u00e9narios futurs","skills shortage logistics Fran\u00e7ais projet DiSTILL","Stra\u00dfen Schienen Wasserverkehr","strategic logistics planning","strategische Logistikplanung","TEN-T transport network","TEN-T Verkehrsnetz","transport chain planning","transport routier ferroviaire fluvial","Transportketten Planung","Verkehrs- und Standortdaten","Zukunftsszenarien Simulation"],"articleSection":["Europa","Germania","Spedizioniere e Logistica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/","url":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/","name":"Progetto DiSTILL in Lusazia concluso con successo - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/04\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png","datePublished":"2026-04-15T12:57:25+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/04\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/04\/DiSTILL_Front.png_2-scaled-aspect-ratio-1400-788-scaled-1.png","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2026\/04\/15\/progetto-distill-in-lusazia-concluso-con-successo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Progetto DiSTILL in Lusazia concluso con successo"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/person\/7b1593b33567ba798d300c8a1b0b85b1","name":"Andreas M\u00fcller","url":"https:\/\/loginfo24.com\/it\/author\/logismedia\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/78432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=78432"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/78432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/78428"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=78432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=78432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=78432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}