{"id":77245,"date":"2026-03-23T16:27:35","date_gmt":"2026-03-23T16:27:35","guid":{"rendered":"https:\/\/loginfo24.com\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/"},"modified":"2026-03-23T16:27:35","modified_gmt":"2026-03-23T16:27:35","slug":"beumer-group-presenta-innovazioni-nella-robotica","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/","title":{"rendered":"BEUMER Group presenta innovazioni nella robotica"},"content":{"rendered":"<p>La BEUMER Group presenter\u00e0 i suoi approcci alla robotica mobile alla LogiMAT 2026, che si svolger\u00e0 dal 24 al 26 marzo a Stoccarda. Al centro dell&#8217;attenzione ci sar\u00e0 un prototipo umanoide, che servir\u00e0 da esempio per l&#8217;integrazione futura della robotica cognitiva nella intralogistica. Con questa presentazione, la BEUMER Group persegue una strategia di innovazione a lungo termine, che include anche una partnership strategica con l&#8217;Istituto Fraunhofer per il flusso di materiali e la logistica IML.<\/p>\n<h3>Approcci innovativi nella robotica<\/h3>\n<p>La BEUMER Group ha istituito un Enterprise Lab per la robotica mobile in collaborazione con l&#8217;Istituto Fraunhofer. Questo laboratorio di innovazione ha lo scopo di promuovere lo sviluppo di nuove tecnologie e di implementare i risultati in prototipi. Il prototipo umanoide, che sar\u00e0 presentato alla LogiMAT, svolge un&#8217;attivit\u00e0 manuale tipica della intralogistica e dimostra come la robotica e l&#8217;intelligenza artificiale potrebbero collaborare in futuro. Il robot funge da piattaforma di ricerca e dimostrazione, senza un termine di lancio sul mercato attualmente definito.<\/p>\n<p>Dr. Volker Jungbluth, Chief Technology Officer della BEUMER Group, sottolinea: \u201ePer noi non \u00e8 la tecnologia al centro, ma il valore per il cliente. Con il prototipo umanoide vogliamo stimolare la discussione su come la robotica possa essere pensata in modo pi\u00f9 flessibile in futuro e come approcci mobili standardizzati possano integrare in modo sensato l&#8217;automazione esistente.\u201d<\/p>\n<h3>Prospettive a lungo termine per i clienti<\/h3>\n<p>La BEUMER Group si considera un partner a lungo termine dei propri clienti e desidera garantire i loro investimenti attraverso un&#8217;innovazione continua e un supporto completo per il ciclo di vita. Con oltre 90 anni di esperienza nella tecnologia di trasporto e nella intralogistica, l&#8217;azienda combina progresso tecnologico con competenza di sistema e presenza globale. La presentazione alla LogiMAT fa parte di questa strategia, per discutere gli sviluppi attuali nella robotica e nell&#8217;automazione e per confrontarsi con clienti e partner.<\/p>\n<p>In totale, la BEUMER Group mostrer\u00e0 alla LogiMAT 2026 come intende plasmare la intralogistica del futuro attraverso approcci innovativi nella robotica mobile.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.beumergroup.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">www.beumer.com<\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La BEUMER Group presenta a LogiMAT 2026 un prototipo umanoide che dimostra l&#8217;integrazione della robotica cognitiva nell&#8217;intralogistica.<\/p>\n","protected":false},"author":12,"featured_media":77241,"comment_status":"open","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6679,6667,1633,1629],"tags":[3037,9801,16413,14600,16414,2744,2211,2212,8500,15132,11573,11574,2123,16415,16416,16417,16418,16419,11577,3278,3279,3280,16420,16421,16422,1891,2133,1831,2622,8160,8161,1800,16423,2148,16424,15141,15142,16425,16426,16427,16428,16429,16430,16431,8171,16432,2106,16433,2641,16434,3081,14620,16435,2242],"class_list":["post-77245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-europa","category-germania","category-intralogistica","category-spedizioni-e-logistica","tag-automation-technology","tag-automatisierungstechnik","tag-cognitive-robotics","tag-conveyor-technology","tag-customer-perspectives-francais-beumer-group","tag-deutsch-beumer-group","tag-digital-transformation","tag-digitale-transformation","tag-foerdertechnik","tag-forschung-und-entwicklung","tag-fraunhofer-institute","tag-fraunhofer-institut","tag-gestion-de-la-chaine-dapprovisionnement","tag-humanoid-robot","tag-humanoider-roboter","tag-innovation-strategy","tag-innovation-technologique","tag-innovationsstrategie","tag-institut-fraunhofer","tag-intralogistics","tag-intralogistik","tag-intralogistique","tag-kognitive-robotik","tag-kundenperspektiven-english-beumer-group","tag-lifecycle-support","tag-logimat-2026","tag-logistics-service-providers","tag-logistikdienstleister","tag-logistique-durable","tag-mobile-robotics","tag-mobile-robotik","tag-nachhaltige-logistik","tag-perspectives-clients","tag-prestataires-de-services-logistiques","tag-prototype-de-robotique","tag-recherche-et-developpement","tag-research-and-development","tag-robot-humanoide","tag-robotics-and-artificial-intelligence","tag-robotics-prototype","tag-robotik-und-kuenstliche-intelligenz","tag-robotik-prototyp","tag-robotique-cognitive","tag-robotique-et-intelligence-artificielle","tag-robotique-mobile","tag-strategie-dinnovation","tag-supply-chain-management","tag-support-de-cycle-de-vie","tag-sustainable-logistics","tag-technological-innovation","tag-technologie-dautomatisation","tag-technologie-de-convoyage","tag-technologische-innovation","tag-transformation-numerique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>BEUMER Group presenta innovazioni nella robotica - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BEUMER Group presenta innovazioni nella robotica - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La BEUMER Group presenta a LogiMAT 2026 un prototipo umanoide che dimostra l&#039;integrazione della robotica cognitiva nell&#039;intralogistica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-23T16:27:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/03\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1441\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andreas Haug\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andreas Haug\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/\"},\"author\":{\"name\":\"Andreas Haug\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\"},\"headline\":\"BEUMER Group presenta innovazioni nella robotica\",\"datePublished\":\"2026-03-23T16:27:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/03\\\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"keywords\":[\"automation technology\",\"Automatisierungstechnik\",\"cognitive robotics\",\"conveyor technology\",\"customer perspectives Fran\u00e7ais BEUMER Group\",\"Deutsch BEUMER Group\",\"digital transformation\",\"digitale Transformation\",\"F\u00f6rdertechnik\",\"Forschung und Entwicklung\",\"Fraunhofer Institute\",\"Fraunhofer-Institut\",\"gestion de la cha\u00eene d'approvisionnement\",\"humanoid robot\",\"humanoider Roboter\",\"innovation strategy\",\"innovation technologique\",\"Innovationsstrategie\",\"Institut Fraunhofer\",\"intralogistics\",\"Intralogistik\",\"intralogistique\",\"kognitive Robotik\",\"Kundenperspektiven English BEUMER Group\",\"Lifecycle Support\",\"LogiMAT 2026\",\"logistics service providers\",\"Logistikdienstleister\",\"logistique durable\",\"mobile robotics\",\"mobile Robotik\",\"nachhaltige Logistik\",\"perspectives clients\",\"prestataires de services logistiques\",\"prototype de robotique\",\"recherche et d\u00e9veloppement\",\"research and development\",\"robot humano\u00efde\",\"robotics and artificial intelligence\",\"robotics prototype\",\"Robotik und k\u00fcnstliche Intelligenz\",\"Robotik-Prototyp\",\"robotique cognitive\",\"robotique et intelligence artificielle\",\"robotique mobile\",\"strat\u00e9gie d'innovation\",\"Supply Chain Management\",\"support de cycle de vie\",\"sustainable logistics\",\"technological innovation\",\"technologie d'automatisation\",\"technologie de convoyage\",\"technologische Innovation\",\"transformation num\u00e9rique\"],\"articleSection\":[\"Europa\",\"Germania\",\"Intralogistica\",\"Spedizioniere e Logistica\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/\",\"name\":\"BEUMER Group presenta innovazioni nella robotica - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/03\\\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"datePublished\":\"2026-03-23T16:27:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/03\\\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/03\\\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg\",\"width\":2560,\"height\":1441},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2026\\\/03\\\/23\\\/beumer-group-presenta-innovazioni-nella-robotica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BEUMER Group presenta innovazioni nella robotica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/person\\\/cf538b3157f15afd7589245a4b3dbd25\",\"name\":\"Andreas Haug\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/author\\\/andreas\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"BEUMER Group presenta innovazioni nella robotica - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/","og_locale":"it_IT","og_type":"article","og_title":"BEUMER Group presenta innovazioni nella robotica - Loginfo24","og_description":"La BEUMER Group presenta a LogiMAT 2026 un prototipo umanoide che dimostra l'integrazione della robotica cognitiva nell'intralogistica.","og_url":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2026-03-23T16:27:35+00:00","og_image":[{"width":2560,"height":1441,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/03\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg","type":"image\/jpeg"}],"author":"Andreas Haug","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andreas Haug","Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/"},"author":{"name":"Andreas Haug","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25"},"headline":"BEUMER Group presenta innovazioni nella robotica","datePublished":"2026-03-23T16:27:35+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/03\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg","keywords":["automation technology","Automatisierungstechnik","cognitive robotics","conveyor technology","customer perspectives Fran\u00e7ais BEUMER Group","Deutsch BEUMER Group","digital transformation","digitale Transformation","F\u00f6rdertechnik","Forschung und Entwicklung","Fraunhofer Institute","Fraunhofer-Institut","gestion de la cha\u00eene d'approvisionnement","humanoid robot","humanoider Roboter","innovation strategy","innovation technologique","Innovationsstrategie","Institut Fraunhofer","intralogistics","Intralogistik","intralogistique","kognitive Robotik","Kundenperspektiven English BEUMER Group","Lifecycle Support","LogiMAT 2026","logistics service providers","Logistikdienstleister","logistique durable","mobile robotics","mobile Robotik","nachhaltige Logistik","perspectives clients","prestataires de services logistiques","prototype de robotique","recherche et d\u00e9veloppement","research and development","robot humano\u00efde","robotics and artificial intelligence","robotics prototype","Robotik und k\u00fcnstliche Intelligenz","Robotik-Prototyp","robotique cognitive","robotique et intelligence artificielle","robotique mobile","strat\u00e9gie d'innovation","Supply Chain Management","support de cycle de vie","sustainable logistics","technological innovation","technologie d'automatisation","technologie de convoyage","technologische Innovation","transformation num\u00e9rique"],"articleSection":["Europa","Germania","Intralogistica","Spedizioniere e Logistica"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/","url":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/","name":"BEUMER Group presenta innovazioni nella robotica - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/03\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg","datePublished":"2026-03-23T16:27:35+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/03\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/03\/Dr-Volker-Jungbluth_small-scaled-aspect-ratio-1400-788-scaled-1.jpg","width":2560,"height":1441},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2026\/03\/23\/beumer-group-presenta-innovazioni-nella-robotica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"BEUMER Group presenta innovazioni nella robotica"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]},{"@type":"Person","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/person\/cf538b3157f15afd7589245a4b3dbd25","name":"Andreas Haug","url":"https:\/\/loginfo24.com\/it\/author\/andreas\/"}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/77245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=77245"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/77245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/77241"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=77245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=77245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=77245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}