{"id":70474,"date":"2025-09-18T18:42:40","date_gmt":"2025-09-18T16:42:40","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/"},"modified":"2025-09-18T18:42:40","modified_gmt":"2025-09-18T16:42:40","slug":"dvf-chiede-riforme-complete-per-porti-e-navigazione","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/","title":{"rendered":"DVF chiede riforme complete per porti e navigazione"},"content":{"rendered":"<h5><strong>Durante la serata parlamentare sui porti e la navigazione del Deutsches Verkehrsforum, Matthias Magnor, membro del consiglio direttivo del DVF e presidente del consiglio di amministrazione della BLG LOGISTICS GROUP AG &amp; Co. KG, ha chiesto riforme ampie. Queste riguardano sia il finanziamento delle infrastrutture portuali, l&#8217;ampliamento degli accessi marittimi e delle connessioni con l&#8217;entroterra, sia la fornitura di combustibili sostenibili.<\/strong><\/h5>\n<p>(Berlino) &#8220;Che si tratti di trasformazione, approvvigionamento energetico o capacit\u00e0 di difesa: i porti tedeschi svolgono compiti di rilevanza nazionale. Senza una partecipazione sostanziale del governo federale dai fondi speciali, queste sfide non possono essere affrontate&#8221;, ha sottolineato Magnor, chiedendo di porre le basi per un nuovo finanziamento delle infrastrutture portuali. \u00c8 fondamentale anche per le vie navigabili che i tassi di ristrutturazione delle infrastrutture aumentino e che il finanziamento venga migliorato - diversamente da quanto previsto nel progetto di bilancio federale 2026.<\/p>\n<p>Il dott. Christoph Plo\u00df MdB, coordinatore del governo federale per l&#8217;economia marittima e il turismo, ha sottolineato l&#8217;importanza nazionale dei porti: &#8220;Indipendentemente da dove si trovano in Germania: i nostri porti garantiscono l&#8217;approvvigionamento, la forza esportativa e la resilienza dell&#8217;intero paese - e devono essere urgentemente ampliati in modo sostenibile. Pertanto, il governo federale deve supportare finanziariamente i L\u00e4nder con i vari fondi speciali. Inoltre, \u00e8 necessario adattare il diritto di pianificazione, ad esempio attraverso l&#8217;introduzione di una regolamentazione temporale, in modo che i grandi progetti infrastrutturali possano essere realizzati rapidamente. Le risorse finanziarie devono tradursi in progetti concreti che portino avanti il nostro paese.&#8221;<\/p>\n<p>Anche Uwe Schmidt MdB, membro della commissione bilancio e relatore per il piano di spesa per i trasporti del gruppo parlamentare SPD, ha chiesto una maggiore partecipazione finanziaria del governo federale e ha richiamato l&#8217;attenzione anche sulle connessioni con l&#8217;entroterra: &#8220;L&#8217;efficienza delle infrastrutture portuali e delle connessioni con l&#8217;entroterra \u00e8 essenziale per la Germania. Dobbiamo semplicemente fare ci\u00f2 che \u00e8 necessario per garantire il futuro. Anche l&#8217;aumento del compenso per il carico portuale \u00e8 legalmente possibile. Se siamo d&#8217;accordo, si pu\u00f2 fare. La maggior parte degli investimenti provenienti dal fondo speciale per infrastrutture e neutralit\u00e0 climatica deve chiaramente beneficiare le infrastrutture - obiettivo del 80%. Le risorse che il governo federale mette a disposizione devono essere utilizzate in modo completo, rapido ed efficace. A tal fine, abbiamo bisogno di una capacit\u00e0 di copertura reciproca tra i mezzi di trasporto.&#8221;<\/p>\n<h5>Solo con supporto possiamo continuare a esistere<\/h5>\n<p>Markus Bangen, presidente del consiglio di amministrazione di duisport - Duisburger Hafen AG, ha fatto riferimento alla concorrenza, in cui i porti tedeschi possono continuare a esistere solo con supporto: &#8220;L&#8217;industria portuale tedesca affronta una doppia sfida: dobbiamo affrontare enormi investimenti in infrastrutture, digitalizzazione e trasformazione, mentre il finanziamento statale stagna. Senza un quadro di finanziamento affidabile e sostenibile per le infrastrutture portuali e le connessioni con l&#8217;entroterra, rischiamo svantaggi competitivi e mettiamo a repentaglio compiti centrali per il futuro come le importazioni di energia, la resilienza delle catene di approvvigionamento e la logistica militare. La politica e l&#8217;industria devono ora sviluppare soluzioni insieme, affinch\u00e9 i nostri porti possano continuare a svolgere il loro ruolo di hub della trasformazione in futuro.&#8221;<\/p>\n<p>A questo proposito, Claudia M\u00fcller MdB, deputata del Bundestag per B\u00fcndnis 90\/Die Gr\u00fcnen della Meclemburgo-Pomerania Anteriore e relatrice per l&#8217;economia marittima, ha chiesto una maggiore coordinazione della politica portuale: &#8220;In tempi di crisi, una buona collaborazione tra i porti tedeschi \u00e8 vitale. Il governo federale deve supportare in modo mirato - all&#8217;interno di una strategia portuale europea complessiva. Dovrebbe anche finalmente pubblicare lo studio DENA sulle infrastrutture portuali, in modo da poter prendere decisioni informate. Per i nostri porti \u00e8 necessaria una divisione del lavoro e collaborazione, anche solo per avere a disposizione sufficiente spazio.&#8221;<\/p>\n<p>Un altro tema importante della serata \u00e8 stata la trasformazione verso la neutralit\u00e0 climatica e la fornitura di nuove fonti di energia. I porti hanno un ruolo centrale in questo. Per la navigazione, \u00e8 urgente costruire una fornitura di combustibili sostenibili.<\/p>\n<h5>Il settore si assume la responsabilit\u00e0<\/h5>\n<p>Il dott. Arnt Vespermann, membro del consiglio direttivo dell&#8217;Associazione dei navigatori tedeschi e CEO della CPO Holding GmbH &amp; Co. KG, ha ribadito: &#8220;Il nostro settore si assume la responsabilit\u00e0 e noi la accettiamo. La navigazione commerciale dimostra che efficienza, innovazione e protezione climatica vanno di pari passo: gi\u00e0 oggi puntiamo su navi moderne, propulsori innovativi, gestione intelligente delle rotte e combustibili alternativi. Ci stiamo dirigendo in modo coerente verso la neutralit\u00e0 climatica entro il 2050. Ci\u00f2 di cui abbiamo bisogno ora \u00e8 il passo decisivo: combustibili verdi disponibili e accessibili a livello mondiale e l&#8217;infrastruttura adeguata.&#8221;<\/p>\n<p>Foto: \u00a9 DVF \/ <strong><em>Didascalia: <\/em><\/strong><em>Matthias Magnor, membro del consiglio direttivo del DVF e presidente del consiglio di amministrazione della BLG LOGISTICS GROUP AG &amp; Co. KG<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante la serata parlamentare sui porti e la navigazione del Deutsches Verkehrsforum, Matthias Magnor, membro del consiglio direttivo del DVF e presidente del consiglio di amministrazione<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-70474","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DVF chiede riforme complete per porti e navigazione - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DVF chiede riforme complete per porti e navigazione - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Durante la serata parlamentare sui porti e la navigazione del Deutsches Verkehrsforum, Matthias Magnor, membro del consiglio direttivo del DVF e presidente del consiglio di amministrazione [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-18T16:42:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_18.9.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1272\" \/>\n\t<meta property=\"og:image:height\" content=\"835\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DVF chiede riforme complete per porti e navigazione\",\"datePublished\":\"2025-09-18T16:42:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/\"},\"wordCount\":799,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_18.9.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/\",\"name\":\"DVF chiede riforme complete per porti e navigazione - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_18.9.25.jpg\",\"datePublished\":\"2025-09-18T16:42:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_18.9.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/DVF_18.9.25.jpg\",\"width\":1272,\"height\":835},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/09\\\/18\\\/dvf-chiede-riforme-complete-per-porti-e-navigazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DVF chiede riforme complete per porti e navigazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DVF chiede riforme complete per porti e navigazione - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/","og_locale":"it_IT","og_type":"article","og_title":"DVF chiede riforme complete per porti e navigazione - Loginfo24","og_description":"Durante la serata parlamentare sui porti e la navigazione del Deutsches Verkehrsforum, Matthias Magnor, membro del consiglio direttivo del DVF e presidente del consiglio di amministrazione [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-09-18T16:42:40+00:00","og_image":[{"width":1272,"height":835,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_18.9.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"4 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/"},"author":{"name":"","@id":""},"headline":"DVF chiede riforme complete per porti e navigazione","datePublished":"2025-09-18T16:42:40+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/"},"wordCount":799,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_18.9.25.jpg","articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/","url":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/","name":"DVF chiede riforme complete per porti e navigazione - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_18.9.25.jpg","datePublished":"2025-09-18T16:42:40+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_18.9.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/DVF_18.9.25.jpg","width":1272,"height":835},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/09\/18\/dvf-chiede-riforme-complete-per-porti-e-navigazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"DVF chiede riforme complete per porti e navigazione"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/70474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=70474"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/70474\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/4492"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=70474"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=70474"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=70474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}