{"id":69832,"date":"2025-07-13T17:58:36","date_gmt":"2025-07-13T15:58:36","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/"},"modified":"2025-07-13T17:58:36","modified_gmt":"2025-07-13T15:58:36","slug":"logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/","title":{"rendered":"Logsol crea un piano master logistico per Alstom a Bautzen"},"content":{"rendered":"<h5><strong>Il pianificatore logistico e di fabbrica LOGSOL deve creare un piano master logistico per Alstom Transportation Germany a Bautzen, il produttore di veicoli ferroviari con sede in Francia. \u00c8 previsto di raddoppiare la superficie di magazzino interna ed esterna a 51.000 m2 presso il sito. Una trasformazione del sito prevede in futuro a Bautzen una specializzazione nel settore del montaggio finale, mentre altre competenze chiave saranno trasferite in altri stabilimenti Alstom.<\/strong><\/h5>\n<p>(Dresda\/Bautzen) L&#8217;area industriale di Alstom a Bautzen respira storia industriale, che risale al 1846. Tra piccole hall distribuite, dove dal 1897 venivano costruiti i primi tram elettrici, Marcel Richter e il suo collega Simon Schr\u00f6der hanno esaminato i percorsi di trasporto all&#8217;inizio del 2023. Quando il Senior Logistics and Factory Planner ha sentito le piastrelle con grandi fughe sotto le sue scarpe, Marcel Richter ha capito: &#8220;I pavimenti datati non sono ottimali per i carrelli elevatori.&#8221;<\/p>\n<h5><strong>Spazio di produzione liberato per la logistica<\/strong><\/h5>\n<p>&#8220;Nell&#8217;ambito della nostra trasformazione del sito, vogliamo insourcing della logistica da siti esterni&#8221;, afferma Tobias Sturm, che come responsabile della logistica presso Alstom a Bautzen gestisce un&#8217;area con oltre 250 dipendenti, inclusi i fornitori di servizi logistici. Una serie di spazi logistici affittati esternamente dovrebbe tornare nello stabilimento.<\/p>\n<p>&#8220;Avevamo bisogno di un concetto su come utilizzare al meglio gli spazi di produzione che si liberano per la logistica&#8221;, spiega. Con LOGSOL lo collega una lunga e fidata cooperazione attraverso il software di gestione delle finestre temporali RampMan\u00ae e il software di gestione dei contenitori BinMan\u00ae. Inoltre: &#8220;L&#8217;esperienza del piano master logistico per lo stabilimento Alstom di Henningsdorf vicino a Berlino ci ha convinto a lavorare con il partner giusto.&#8221;<\/p>\n<p>La raccolta dei dati e l&#8217;analisi dello stato attuale hanno inizialmente significato lavoro manuale per Richter e il suo team. Gli esperti dovevano non solo registrare dettagliatamente le aree nel sito di Bautzen, ma anche in sei siti esterni fino a 40 km di distanza, che dovevano essere integrati.<\/p>\n<p>Hanno considerato tutte le leve rilevanti del flusso di materiali e delle strutture di magazzino:<\/p>\n<ul>\n<li>Dove avviene la ricezione delle merci?<\/li>\n<li>Quale tecnologia di magazzino viene utilizzata?<\/li>\n<li>Come sono progettate le aree di picking?<\/li>\n<\/ul>\n<p>Ma la strada verso il piano master \u00e8 stata difficile. LOGSOL ha molta esperienza nell&#8217;impostare una struttura logistica e nel calcolare le proiezioni per lo scenario obiettivo. Tuttavia, per poter calcolare tutto e condurre analisi, sono necessari molti dati di base e di movimento. &#8220;La sfida era che non avevamo una buona base di dati&#8221;, afferma Tobias Sturm.<\/p>\n<h5>L&#8217;analisi dello stato attuale ha richiesto pi\u00f9 tempo del previsto<\/h5>\n<p>Nella vita quotidiana mancavano capacit\u00e0 per inserire tutto per &#8220;un quadro completo&#8221; nel sistema di pianificazione delle risorse aziendali SAP. Tanto pi\u00f9 apprezza che LOGSOL sia riuscita a &#8220;risolvere in modo flessibile e intelligente&#8221; la raccolta dei dati: &#8220;Le richieste a breve termine sono state considerate molto rapidamente e senza burocrazia.&#8221; Per Marcel Richter fa parte del lavoro quotidiano del progetto gestire in modo strutturato e analitico anche con pochi dati di partenza. Anche se questo significava essere &#8220;in giro pi\u00f9 a lungo&#8221; del previsto per la raccolta dello stato attuale.<\/p>\n<p>&#8220;La frammentazione del sito storicamente cresciuto ha avuto un impatto sulla logistica&#8221;, afferma Marcel Richter. Se un&#8217;area non era sufficiente per un magazzino a scaffale, doveva riassemblare i pezzi del puzzle in modo diverso. Dopo solo quattro mesi, LOGSOL ha fornito un risultato ben pianificato per ulteriori aree logistiche, comprese le necessarie misure di costruzione.<\/p>\n<h5>Implementazione entro il 2026<\/h5>\n<p>&#8220;Abbiamo ricevuto un&#8217;eccellente base decisionale in un periodo molto gestibile&#8221;, si rallegrano Tobias Sturm. &#8220;Utilizziamo volentieri LOGSOL per ulteriore supporto concettuale&#8221;, afferma. Per questo, Marcel Richter si sta gi\u00e0 preparando: entro il 2026 il concetto dovrebbe essere implementato a Bautzen, con la prima parziale realizzazione che vedr\u00e0 di nuovo coinvolta LOGSOL.<\/p>\n<p>Foto: \u00a9 Logsol<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il pianificatore logistico e di fabbrica LOGSOL deve creare un piano master logistico per Alstom Transportation Germany a Bautzen, il produttore di veicoli ferroviari con sede<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4763,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-69832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Logsol crea un piano master logistico per Alstom a Bautzen - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Logsol crea un piano master logistico per Alstom a Bautzen - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il pianificatore logistico e di fabbrica LOGSOL deve creare un piano master logistico per Alstom Transportation Germany a Bautzen, il produttore di veicoli ferroviari con sede [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-13T15:58:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logsol_13.7.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1207\" \/>\n\t<meta property=\"og:image:height\" content=\"704\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Logsol crea un piano master logistico per Alstom a Bautzen\",\"datePublished\":\"2025-07-13T15:58:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/\"},\"wordCount\":639,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logsol_13.7.25.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/\",\"name\":\"Logsol crea un piano master logistico per Alstom a Bautzen - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logsol_13.7.25.jpg\",\"datePublished\":\"2025-07-13T15:58:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logsol_13.7.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Logsol_13.7.25.jpg\",\"width\":1207,\"height\":704},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/13\\\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Logsol crea un piano master logistico per Alstom a Bautzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Logsol crea un piano master logistico per Alstom a Bautzen - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/","og_locale":"it_IT","og_type":"article","og_title":"Logsol crea un piano master logistico per Alstom a Bautzen - Loginfo24","og_description":"Il pianificatore logistico e di fabbrica LOGSOL deve creare un piano master logistico per Alstom Transportation Germany a Bautzen, il produttore di veicoli ferroviari con sede [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-07-13T15:58:36+00:00","og_image":[{"width":1207,"height":704,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logsol_13.7.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/"},"author":{"name":"","@id":""},"headline":"Logsol crea un piano master logistico per Alstom a Bautzen","datePublished":"2025-07-13T15:58:36+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/"},"wordCount":639,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logsol_13.7.25.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/","url":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/","name":"Logsol crea un piano master logistico per Alstom a Bautzen - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logsol_13.7.25.jpg","datePublished":"2025-07-13T15:58:36+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logsol_13.7.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Logsol_13.7.25.jpg","width":1207,"height":704},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/13\/logsol-crea-un-piano-master-logistico-per-alstom-a-bautzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Logsol crea un piano master logistico per Alstom a Bautzen"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=69832"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/4763"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=69832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=69832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=69832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}