{"id":69802,"date":"2025-07-10T17:06:22","date_gmt":"2025-07-10T15:06:22","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/"},"modified":"2025-07-10T17:06:22","modified_gmt":"2025-07-10T15:06:22","slug":"autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/","title":{"rendered":"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche"},"content":{"rendered":"<h5><strong>Con un simbolico colpo di vanga, BLG LOGISTICS ha celebrato insieme ai partner l&#8217;inizio dei lavori per una copertura ampia di posti auto con moduli fotovoltaici presso l&#8217;AutoTerminal di Kelheim. Circa 23 megawatt di energia rinnovabile saranno prodotti in futuro dai Solarport.<\/strong><\/h5>\n<p>(Bremen\/Kelheim) Mercoled\u00ec scorso, Axel Krichel, membro del consiglio e Chief Operating Officer (COO) di BLG LOGISTICS, insieme al presidente dell&#8217;Associazione dei porti della contea di Kelheim, il sindaco Martin Neumeyer, il direttore dell&#8217;associazione, i sindaci di Kelheim e Saal, e il progettista SOLEA, ha avviato la costruzione di una copertura sostenibile per 10.000 posti auto presso l&#8217;AutoTerminal BLG di Kelheim.<\/p>\n<p>Circa 53.000 moduli fotovoltaici con una potenza di oltre 23 megawatt picco saranno installati nell&#8217;area del cosiddetto &#8220;Hopfenfeld&#8221;. Il progetto viene realizzato insieme a SOLEA, un esperto specializzato in impianti fotovoltaici su larga scala. Il sito utilizza energia solare dal 2019.<\/p>\n<h5>Punto centrale nella rete<\/h5>\n<p>Axel Krichel sottolinea l&#8217;importanza strategica del progetto: &#8220;Kelheim \u00e8 per noi molto pi\u00f9 di un semplice sito: \u00e8 un punto centrale nella nostra rete di soluzioni logistiche sostenibili - collegato in trimodale, altamente automatizzato e orientato al cliente. BLG LOGISTICS \u00e8 uno dei maggiori datori di lavoro a Kelheim. Questo investimento \u00e8 un segnale positivo per il sito.&#8221;<\/p>\n<p>L&#8217;AutoTerminal di Kelheim \u00e8 uno dei porti interni pi\u00f9 importanti per il trasbordo di veicoli. Su una superficie totale di 550.000 metri quadrati, circa 300 dipendenti gestiscono veicoli che vengono consegnati via nave, treno e camion dall&#8217;Ungheria, dalla Slovacchia, dai porti adriatici e dalla Germania meridionale. L&#8217;attrezzatura tecnica in loco consente processi di lavaggio e riparazione, cos\u00ec come configurazioni specifiche per il mercato.<\/p>\n<h5>Ponte tra sostenibilit\u00e0 e redditivit\u00e0<\/h5>\n<p>Il responsabile del sito, G\u00f6rgen Brockbalz, \u00e8 convinto: &#8220;Questo progetto esemplare crea un ponte tra sostenibilit\u00e0 e redditivit\u00e0. I Solarport non solo producono energia verde, ma creano anche circa 10.000 posti auto coperti, che proteggono i prodotti di alta qualit\u00e0 dei nostri clienti dalle intemperie.&#8221;<\/p>\n<p>Foto: \u00a9 BLG \/ <em><strong>Didascalia dell&#8217;immagine<\/strong> (da sinistra a destra): Martin Neumeyer (sindaco di Kelheim), Axel Krichel (membro del consiglio e COO di BLG), Christian Nerb (sindaco del comune di Saal), Christian Schweiger (sindaco della citt\u00e0 di Kelheim), Tobias Schlauderer (direttore dell&#8217;Associazione dei porti di Kelheim), Andreas Hillinger (direttore di Solea GmbH), Georg Sterner (CFO di Solea AG) e G\u00f6rgen Brockbalz (responsabile dell&#8217;AutoTerminal BLG di Kelheim)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con un simbolico colpo di vanga, BLG LOGISTICS ha celebrato insieme ai partner l&#8217;inizio dei lavori per una copertura ampia di posti auto con moduli fotovoltaici<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4773,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-69802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Con un simbolico colpo di vanga, BLG LOGISTICS ha celebrato insieme ai partner l&#8217;inizio dei lavori per una copertura ampia di posti auto con moduli fotovoltaici [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-10T15:06:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLG_10.7.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1399\" \/>\n\t<meta property=\"og:image:height\" content=\"848\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche\",\"datePublished\":\"2025-07-10T15:06:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/\"},\"wordCount\":393,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLG_10.7.25.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/\",\"name\":\"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLG_10.7.25.jpg\",\"datePublished\":\"2025-07-10T15:06:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLG_10.7.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/BLG_10.7.25.jpg\",\"width\":1399,\"height\":848},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/07\\\/10\\\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/","og_locale":"it_IT","og_type":"article","og_title":"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche - Loginfo24","og_description":"Con un simbolico colpo di vanga, BLG LOGISTICS ha celebrato insieme ai partner l&#8217;inizio dei lavori per una copertura ampia di posti auto con moduli fotovoltaici [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-07-10T15:06:22+00:00","og_image":[{"width":1399,"height":848,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLG_10.7.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/"},"author":{"name":"","@id":""},"headline":"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche","datePublished":"2025-07-10T15:06:22+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/"},"wordCount":393,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLG_10.7.25.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/","url":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/","name":"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLG_10.7.25.jpg","datePublished":"2025-07-10T15:06:22+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLG_10.7.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/BLG_10.7.25.jpg","width":1399,"height":848},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/07\/10\/autoterminal-di-blg-a-kehlheim-con-ampie-superfici-fotovoltaiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"AutoTerminal di BLG a Kehlheim con ampie superfici fotovoltaiche"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=69802"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69802\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/4773"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=69802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=69802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=69802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}