{"id":69357,"date":"2025-05-30T19:40:39","date_gmt":"2025-05-30T17:40:39","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/"},"modified":"2025-05-30T19:40:39","modified_gmt":"2025-05-30T17:40:39","slug":"wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/","title":{"rendered":"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica"},"content":{"rendered":"<h5><strong>L&#8217;elettrificazione dei veicoli commerciali pesanti porta nuove esigenze nella gestione delle flotte. Pertanto, W&amp;P GmbH equipaggia l&#8217;intera flotta di camion elettrici con soluzioni telematiche di GPSoverIP. Il sistema GPSauge fornisce dati telemetrici completi in tempo reale \u2013 dall&#8217;autonomia residua allo stato della batteria. Questo crea la necessaria trasparenza dei dati per una gestione del caricamento efficiente e intelligente nella flotta.<\/strong><\/h5>\n<p>(Schweinfurt\/Prichsenstadt) W&amp;P GmbH sta portando avanti l&#8217;elettrificazione della sua flotta di veicoli in modo coerente, puntando su GPSoverIP come partner telematico. In totale, circa 25-30 camion elettrici pesanti saranno equipaggiati con hardware GPSauge specializzato e il sistema di gestione centrale della flotta GPS-Explorer.<\/p>\n<p>Con la nuova infrastruttura di ricarica di W&amp;P \u2013 il pi\u00f9 grande parco di ricarica privato per camion in Baviera, composto da 56 stazioni di ricarica e una capacit\u00e0 di accumulo di 15 megawatt \u2013 si crea un modello innovativo per l&#8217;intero settore. Tuttavia, l&#8217;infrastruttura da sola non \u00e8 sufficiente: per gestire veicoli elettrici in modo economico e affidabile, \u00e8 necessaria una gestione basata sui dati, trasparenza e pianificazione intelligente della ricarica.<\/p>\n<h5><strong>Gestione delle flotte elettriche a un nuovo livello<\/strong><\/h5>\n<p>La soluzione telematica di GPSoverIP fornisce in tempo reale dati cruciali sui veicoli e telemetrici \u2013 tra cui chilometraggio, stato di carica, autonomia residua, temperatura della batteria e durata della ricarica. Questi dati vengono raccolti tramite l&#8217;hardware GPSauge e trasmessi direttamente al portale web GPS-Explorer tramite CAN-Bus o tecniche di acquisizione alternative. Anche se lo standard FMS (Fleet Management System) attualmente non fornisce dati telemetrici completi per i veicoli elettrici, la tecnologia GPSauge consente gi\u00e0 oggi l&#8217;accesso a parametri centrali come consumo energetico, cicli di carica o energia recuperata.<\/p>\n<p>&#8220;Con il passaggio ai camion elettrici, W&amp;P GmbH compie un passo audace verso una logistica sostenibile \u2013 e punta anche su un&#8217;intelligenza digitale nella gestione dei veicoli&#8221;, spiega Dirk Jurleit, responsabile vendite e personale di GPSoverIP GmbH. &#8220;Le nostre soluzioni forniscono la trasparenza e l&#8217;efficienza necessarie per trarre un reale beneficio economico dalla mobilit\u00e0 elettrica.&#8221;<\/p>\n<h5><strong>Pianificare i tempi di ricarica, ottimizzare i costi energetici \u2013 con intelligenza connessa<\/strong><\/h5>\n<p>Un elemento centrale per il futuro nella gestione delle flotte elettriche \u00e8 la coordinazione intelligente dei processi di ricarica. L&#8217;uso di energia autoprodotta \u2013 ad esempio da impianti fotovoltaici \u2013 spesso collide con le esigenze di ricarica temporizzate, mentre i prezzi dell&#8217;energia subiscono forti fluttuazioni. In futuro, sar\u00e0 fondamentale gestire queste dinamiche in modo mirato. W&amp;P GmbH si propone di integrare i dati dei veicoli, l&#8217;infrastruttura di ricarica e i sistemi di gestione energetica in un sistema complessivo integrato.<\/p>\n<p>Le soluzioni telematiche come quelle di GPSoverIP supportano questo approccio e uno strumento centrale di gestione della ricarica potrebbe in futuro consentire di pianificare in modo proattivo le routine di ricarica, coordinare le operazioni aziendali con le tariffe energetiche e svolgere i processi di ricarica in modo ottimizzato per rete e costi.<\/p>\n<h5><strong>Ruolo della telematica nella transizione energetica nel trasporto pesante<\/strong><\/h5>\n<p>W&amp;P affronta con la sua strategia di flotte elettriche le sfide centrali della transizione energetica nel trasporto pesante. GPSoverIP fornisce l&#8217;infrastruttura tecnologica per supportare questa strategia con una raccolta e trasmissione dei dati precisa. La raccolta di informazioni rilevanti in una piattaforma connessa consente decisioni basate sui dati nella gestione quotidiana della flotta \u2013 un passo decisivo verso una maggiore efficienza, un uso economico delle risorse e una logistica sostenibile.<\/p>\n<p>Foto: \u00a9 GPSoverIP GmbH<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;elettrificazione dei veicoli commerciali pesanti porta nuove esigenze nella gestione delle flotte. Pertanto, W&amp;P GmbH equipaggia l&#8217;intera flotta di camion elettrici con soluzioni telematiche di GPSoverIP.<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":4941,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-69357","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>W&amp;P punta sulle soluzioni di GPSoverIP per la telematica - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"L&#8217;elettrificazione dei veicoli commerciali pesanti porta nuove esigenze nella gestione delle flotte. Pertanto, W&amp;P GmbH equipaggia l&#8217;intera flotta di camion elettrici con soluzioni telematiche di GPSoverIP. [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-30T17:40:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GP_31.5.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1284\" \/>\n\t<meta property=\"og:image:height\" content=\"795\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica\",\"datePublished\":\"2025-05-30T17:40:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/\"},\"wordCount\":577,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GP_31.5.25.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/\",\"name\":\"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GP_31.5.25.jpg\",\"datePublished\":\"2025-05-30T17:40:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GP_31.5.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/GP_31.5.25.jpg\",\"width\":1284,\"height\":795},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/30\\\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/","og_locale":"it_IT","og_type":"article","og_title":"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica - Loginfo24","og_description":"L&#8217;elettrificazione dei veicoli commerciali pesanti porta nuove esigenze nella gestione delle flotte. Pertanto, W&amp;P GmbH equipaggia l&#8217;intera flotta di camion elettrici con soluzioni telematiche di GPSoverIP. [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-05-30T17:40:39+00:00","og_image":[{"width":1284,"height":795,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GP_31.5.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/"},"author":{"name":"","@id":""},"headline":"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica","datePublished":"2025-05-30T17:40:39+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/"},"wordCount":577,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GP_31.5.25.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/","url":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/","name":"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GP_31.5.25.jpg","datePublished":"2025-05-30T17:40:39+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GP_31.5.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/GP_31.5.25.jpg","width":1284,"height":795},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/30\/wp-punta-sulle-soluzioni-di-gpsoverip-per-la-telematica\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"W&amp;P punta sulle soluzioni di GPSoverIP per la telematica"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69357","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=69357"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69357\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/4941"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=69357"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=69357"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=69357"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}