{"id":69148,"date":"2025-05-15T16:29:22","date_gmt":"2025-05-15T14:29:22","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/"},"modified":"2025-05-15T16:29:22","modified_gmt":"2025-05-15T14:29:22","slug":"bertschi-inaugura-il-terminal-zomerweg-ad-anversa","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/","title":{"rendered":"Bertschi inaugura il Terminal Zomerweg ad Anversa"},"content":{"rendered":"<h5><strong>Il Gruppo Bertschi, leader nel settore della logistica chimica intermodale, ha inaugurato ufficialmente il nuovo Terminal Antwerp Zomerweg (AZT) alla presenza di ospiti. Situato strategicamente nel pi\u00f9 grande cluster chimico integrato d&#8217;Europa, il terminal rappresenta un hub ideale per le importazioni e le esportazioni da e verso l&#8217;estero, consolidando la posizione di Bertschi in uno dei nodi logistici pi\u00f9 significativi a livello globale.<\/strong><\/h5>\n<p>(D\u00fcrren\u00e4sch\/Anversa) Con una superficie totale di 60.000 m\u00b2, il terminal AZT \u00e8 perfettamente attrezzato per lo stoccaggio di merci pericolose (DG) e non pericolose in container cisterna. La struttura offre spazio per oltre 2.500 TEU (Twenty-Foot Equivalent Unit) in container, di cui 1.290 TEU specificamente per merci pericolose. Oltre allo stoccaggio, l&#8217;accento \u00e8 posto su un&#8217;offerta di trasporto trimodale ampliata, che include collegamenti ferroviari, fluviali e su strada, ottimizzando cos\u00ec il trasporto intermodale.<\/p>\n<p>Il terminal \u00e8 dotato di un&#8217;infrastruttura di sicurezza all&#8217;avanguardia, che include zone resistenti al fuoco, pompe antincendio ridondanti e una gru portale telecomandata. Queste avanzate misure di sicurezza garantiscono un&#8217;operazione sicura ed efficiente e soddisfano gli elevati standard di Bertschi.<\/p>\n<p>La struttura dispone inoltre di 60 posti di riscaldamento per container cisterna, dove i prodotti possono essere riscaldati in loco. Un&#8217;altra caratteristica distintiva \u00e8 la possibilit\u00e0 di stoccaggio in regime di dogana, che offre ulteriore flessibilit\u00e0 logistica.<\/p>\n<p>Grazie ai quattro binari di carico, ciascuno lungo 650 metri, il terminal \u00e8 in grado di ricevere interi treni, consentendo una distribuzione delle merci senza soluzione di continuit\u00e0. Attraverso collegamenti fluviali dal porto in acque profonde, le importazioni possono essere trasportate direttamente all&#8217;AZT, dove vengono stoccate in modo efficiente e successivamente distribuite via ferrovia o camion fino alla destinazione finale.<\/p>\n<h5><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-28808 size-full\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_15.5.25_1.jpg\" alt=\"\" width=\"1390\" height=\"824\" \/>Cerimonia di inaugurazione con oltre 100 ospiti<\/strong><\/h5>\n<p>Dopo che la struttura \u00e8 stata gradualmente messa in funzione negli ultimi mesi, il 7 maggio si \u00e8 tenuta l&#8217;inaugurazione ufficiale con oltre 100 ospiti invitati. La celebrazione ha incluso discorsi di Jacques Pitteloud, Ambasciatore svizzero in Belgio, e Johan Klaps, Assessore del Porto di Anversa, seguiti con attenzione dai presenti. Anche Jan Arnet, CEO del Gruppo Bertschi, ha espresso la sua gioia: &#8220;Siamo orgogliosi di poter inaugurare questo nuovo terminal e di ampliare cos\u00ec le nostre capacit\u00e0 logistiche qui ad Anversa. Grazie all&#8217;infrastruttura moderna, possiamo offrire ai nostri clienti una gestione efficiente e sicura delle importazioni ed esportazioni di merci pericolose liquide, includendo stoccaggio e distribuzione intermodale.&#8221;<\/p>\n<p>Durante il tour successivo del terminal, gli ospiti invitati hanno potuto farsi un&#8217;idea delle dimensioni della struttura e informarsi in dettaglio sui servizi logistici offerti e sui processi operativi.<\/p>\n<p>Foto: \u00a9 Bertschi<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Gruppo Bertschi, leader nel settore della logistica chimica intermodale, ha inaugurato ufficialmente il nuovo Terminal Antwerp Zomerweg (AZT) alla presenza di ospiti. Situato strategicamente nel<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5019,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561],"tags":[],"class_list":["post-69148","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bertschi inaugura il Terminal Zomerweg ad Anversa - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bertschi inaugura il Terminal Zomerweg ad Anversa - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il Gruppo Bertschi, leader nel settore della logistica chimica intermodale, ha inaugurato ufficialmente il nuovo Terminal Antwerp Zomerweg (AZT) alla presenza di ospiti. Situato strategicamente nel [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-15T14:29:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_15.5.25_2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1296\" \/>\n\t<meta property=\"og:image:height\" content=\"784\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Bertschi inaugura il Terminal Zomerweg ad Anversa\",\"datePublished\":\"2025-05-15T14:29:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/\"},\"wordCount\":426,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_15.5.25_2.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/\",\"name\":\"Bertschi inaugura il Terminal Zomerweg ad Anversa - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_15.5.25_2.jpg\",\"datePublished\":\"2025-05-15T14:29:22+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_15.5.25_2.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Bertschi_15.5.25_2.jpg\",\"width\":1296,\"height\":784},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/05\\\/15\\\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bertschi inaugura il Terminal Zomerweg ad Anversa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bertschi inaugura il Terminal Zomerweg ad Anversa - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/","og_locale":"it_IT","og_type":"article","og_title":"Bertschi inaugura il Terminal Zomerweg ad Anversa - Loginfo24","og_description":"Il Gruppo Bertschi, leader nel settore della logistica chimica intermodale, ha inaugurato ufficialmente il nuovo Terminal Antwerp Zomerweg (AZT) alla presenza di ospiti. Situato strategicamente nel [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-05-15T14:29:22+00:00","og_image":[{"width":1296,"height":784,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_15.5.25_2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/"},"author":{"name":"","@id":""},"headline":"Bertschi inaugura il Terminal Zomerweg ad Anversa","datePublished":"2025-05-15T14:29:22+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/"},"wordCount":426,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_15.5.25_2.jpg","articleSection":["Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/","url":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/","name":"Bertschi inaugura il Terminal Zomerweg ad Anversa - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_15.5.25_2.jpg","datePublished":"2025-05-15T14:29:22+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_15.5.25_2.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Bertschi_15.5.25_2.jpg","width":1296,"height":784},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/05\/15\/bertschi-inaugura-il-terminal-zomerweg-ad-anversa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Bertschi inaugura il Terminal Zomerweg ad Anversa"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=69148"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/69148\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/5019"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=69148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=69148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=69148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}