{"id":68564,"date":"2025-03-21T19:02:52","date_gmt":"2025-03-21T18:02:52","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/"},"modified":"2025-03-21T19:02:52","modified_gmt":"2025-03-21T18:02:52","slug":"mercedes-consegna-il-15-000-camion-al-gruppo-rethmann","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/","title":{"rendered":"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann"},"content":{"rendered":"<h5>Un altro traguardo nella lunga collaborazione tra Mercedes\u2011Benz Trucks e il gruppo Rethmann: presso il centro clienti Mercedes\u2011Benz Trucks a W\u00f6rth, \u00e8 stato ufficialmente consegnato il 15.000\u00b0 veicolo all&#8217;azienda. Il robusto e potente Arocs 3243 L rafforzer\u00e0 in futuro il parco veicoli di Remondis, giocando cos\u00ec un ruolo importante nella gestione dei rifiuti lungo le arterie stradali tedesche.<\/h5>\n<p>(Leinfelden-Echterdingen\/W\u00f6rth am Rhein\/Knetzgau) Alla cerimonia di consegna della chiave, guidata dal Dr. Andreas Bachhofer, responsabile del sito di W\u00f6rth e della produzione di Mercedes\u2011Benz Trucks, erano presenti Norbert Rethmann, presidente onorario del consiglio di sorveglianza del gruppo Rethmann e pioniere dell&#8217;economia circolare, Bernhard Heiker, CFO di REMONDIS SE &amp; Co KG e altri rappresentanti di Daimler Truck AG, del cliente Remondis e dei partner contrattuali responsabili. La consegna segna un ulteriore culmine di una partnership che \u00e8 iniziata nel 1959 con il primo camion Mercedes\u2011Benz per la raccolta dei rifiuti per Rethmann ed \u00e8 da allora caratterizzata da stabilit\u00e0 e fiducia.<\/p>\n<p>Norbert Rethmann in occasione della consegna ha dichiarato: &#8220;In effetti, Mercedes\u2011Benz Trucks e la nostra azienda condividono una lunga e proficua partnership. Sono certo che continueremo questa collaborazione anche nella generazione dei miei figli.&#8221; Il gruppo aziendale \u00e8 uno dei maggiori clienti di Mercedes\u2011Benz Trucks e punta attivamente allo sviluppo della propria flotta di veicoli, prendendo continuamente decisioni importanti per il futuro. Dal 2020\/2021, Rethmann SE &amp; Co. KG utilizza anche i primi camion elettrici Mercedes\u2011Benz, avviando cos\u00ec un orientamento coerente verso l&#8217;elettrificazione. Oltre ai tradizionali camion diesel, l&#8217;azienda sta puntando sempre di pi\u00f9 su forme di propulsione alternative e ora utilizza sia il Mercedes\u2011Benz eEconic che il Mercedes\u2011Benz eActros 600.<\/p>\n<h5><strong>Massima efficienza per una gestione sostenibile dei rifiuti<\/strong><\/h5>\n<p>Il Mercedes\u2011Benz Arocs 3243 L, come veicolo commemorativo, \u00e8 stato progettato specificamente per compiti di smaltimento impegnativi in parcheggi e aree di sosta lungo le autostrade e le strade statali tedesche e sar\u00e0 utilizzato in futuro da Remondis. Il camion da 32 tonnellate \u00e8 dotato di un motore OM470, con una cilindrata di 10,7 litri e 315 kW (430 CV). Il Mercedes\u2011Benz Arocs si distingue per la sua elevata robustezza e versatilit\u00e0 ed \u00e8 stato progettato specificamente per l&#8217;uso in cantieri e trasporti pesanti. Con motori potenti e una costruzione del telaio particolarmente stabile, l&#8217;Arocs offre eccellenti caratteristiche di guida, anche in condizioni estreme. Inoltre, si distingue per il suo utilizzo efficiente del carburante e la tecnologia innovativa che consente un utilizzo ottimale in ambienti di lavoro impegnativi. Il potente camion con cabina ClassicSpace viene utilizzato in diverse regioni della Germania meridionale e orientale come veicolo per la raccolta dei rifiuti domestici e contribuisce all&#8217;efficiente svuotamento dei contenitori lungo importanti arterie stradali.<\/p>\n<p>Foto: \u00a9 Mercedes-Benz Trucks<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un altro traguardo nella lunga collaborazione tra Mercedes\u2011Benz Trucks e il gruppo Rethmann: presso il centro clienti Mercedes\u2011Benz Trucks a W\u00f6rth, \u00e8 stato ufficialmente consegnato il<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5248,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1556,1561],"tags":[],"class_list":["post-68564","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intermodal-road","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Un altro traguardo nella lunga collaborazione tra Mercedes\u2011Benz Trucks e il gruppo Rethmann: presso il centro clienti Mercedes\u2011Benz Trucks a W\u00f6rth, \u00e8 stato ufficialmente consegnato il [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-21T18:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_21.3.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1604\" \/>\n\t<meta property=\"og:image:height\" content=\"709\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann\",\"datePublished\":\"2025-03-21T18:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/\"},\"wordCount\":456,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_21.3.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intermodal \\\/ Road\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/\",\"name\":\"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_21.3.25.jpg\",\"datePublished\":\"2025-03-21T18:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_21.3.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Mercedes_Truck_21.3.25.jpg\",\"width\":1604,\"height\":709},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/21\\\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/","og_locale":"it_IT","og_type":"article","og_title":"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann - Loginfo24","og_description":"Un altro traguardo nella lunga collaborazione tra Mercedes\u2011Benz Trucks e il gruppo Rethmann: presso il centro clienti Mercedes\u2011Benz Trucks a W\u00f6rth, \u00e8 stato ufficialmente consegnato il [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-03-21T18:02:52+00:00","og_image":[{"width":1604,"height":709,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_21.3.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/"},"author":{"name":"","@id":""},"headline":"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann","datePublished":"2025-03-21T18:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/"},"wordCount":456,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_21.3.25.jpg","articleSection":["Forwarding &amp; Logistics","Intermodal \/ Road","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/","url":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/","name":"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_21.3.25.jpg","datePublished":"2025-03-21T18:02:52+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_21.3.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Mercedes_Truck_21.3.25.jpg","width":1604,"height":709},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/21\/mercedes-consegna-il-15-000-camion-al-gruppo-rethmann\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Mercedes consegna il 15.000\u00b0 camion al gruppo Rethmann"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/68564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=68564"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/68564\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/5248"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=68564"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=68564"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=68564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}