{"id":68494,"date":"2025-03-18T19:02:13","date_gmt":"2025-03-18T18:02:13","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/"},"modified":"2025-03-18T19:02:13","modified_gmt":"2025-03-18T18:02:13","slug":"il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/","title":{"rendered":"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2%"},"content":{"rendered":"<h5><strong>Il gruppo Fraport ha concluso l&#8217;anno fiscale 2024 con una crescita nei principali indicatori economici. L&#8217;operatore aeroportuale internazionale ha aumentato i ricavi derivanti dal traffico e dai prezzi all&#8217;aeroporto di Francoforte e nel portafoglio internazionale di partecipazioni. Anche il risultato del gruppo ha beneficiato di un aumento del 16,6% a 501,9 milioni di euro.<\/strong><\/h5>\n<p>(Francoforte) &#8220;Nonostante le difficolt\u00e0, abbiamo ottenuto uno sviluppo commerciale solido&#8221;, afferma il Dr. Stefan Schulte, presidente del consiglio di amministrazione di Fraport AG. &#8220;Mentre all&#8217;inizio del 2024 a Francoforte avevamo ancora tassi di crescita di circa il dieci percento, il numero di passeggeri \u00e8 diminuito progressivamente nel corso dell&#8217;anno. Oltre ai vincoli nella disponibilit\u00e0 di nuovi aerei, i costi elevati delle sedi governative rimangono una ragione fondamentale. Se non ci saranno interventi politici, i costi delle sedi regolamentati aumenteranno ulteriormente nel 2025, gravando le compagnie aeree di ulteriori 1,2 miliardi. Fortunatamente, molti dei nostri aeroporti internazionali partecipati hanno mostrato tassi di crescita dinamici, presentando un quadro pi\u00f9 positivo. Le partecipazioni a Lima, Lubiana, Antalya e Grecia hanno registrato sviluppi particolarmente forti.&#8221;<\/p>\n<h5><strong>Risultati record nei principali indicatori finanziari<\/strong><\/h5>\n<p>Gli effetti dei prezzi e l&#8217;aumento del numero di passeggeri hanno portato a un aumento del fatturato annuale del 10,7% a un nuovo massimo di 4,43 miliardi di euro (2023: 4,00 miliardi di euro). Al netto dei ricavi legati agli investimenti di espansione nelle societ\u00e0 consolidate internazionali (IFRIC 12), il fatturato \u00e8 cresciuto dell&#8217;11,7% a 3,89 miliardi di euro. L&#8217;EBITDA del gruppo \u00e8 salito anch&#8217;esso a un nuovo record di 1,30 miliardi di euro, corrispondente a un aumento dell&#8217;8,1% (2023: 1,20 miliardi di euro). Il risultato del gruppo \u00e8 aumentato del 16,6% a 501,9 milioni di euro (2023: 430,5 milioni di euro).<\/p>\n<p>Il rapporto tra debito finanziario netto e EBITDA \u00e8 rimasto stabile a 6,4, lo stesso livello dell&#8217;anno precedente (2023: 6,4). Gli aumenti nel flusso di cassa operativo di 315,9 milioni di euro a 1.179,1 milioni di euro sono stati compensati da elevati deflussi di cassa, in particolare a causa degli investimenti per il completamento dei grandi progetti di espansione a Lima e Francoforte. Il flusso di cassa libero \u00e8 diminuito leggermente del 2,8% a -674,7 milioni di euro (2023: -656,4 milioni di euro).<\/p>\n<h5><strong>Aumenti nel traffico passeggeri e cargo<\/strong><\/h5>\n<p>Nel 2024, il numero di passeggeri \u00e8 aumentato in gran parte a livello di gruppo. A Francoforte, il traffico turistico ha continuato a dominare. Anche la domanda di viaggi d&#8217;affari \u00e8 aumentata, sebbene con una dinamica leggermente attenuata. All&#8217;hub di casa, Fraport ha accolto circa 61,6 milioni di passeggeri. Questo corrisponde a un aumento del 3,7% rispetto al 2023. Il traffico nazionale \u00e8 aumentato del due percento, rimanendo comunque significativamente al di sotto dei livelli pre-crisi. Il traffico europeo ha registrato un aumento del 4,2%. In particolare, le destinazioni balneari e i viaggi in citt\u00e0 sono stati molto richiesti. Il traffico intercontinentale \u00e8 cresciuto complessivamente del 3,4%. Il motore di crescita \u00e8 stato il traffico verso l&#8217;Asia orientale, che \u00e8 aumentato del 13,3%. In questo contesto, il traffico verso la Cina ha registrato il pi\u00f9 alto aumento assoluto. Anche un aumento del traffico verso destinazioni indiane ha sostenuto lo sviluppo.<\/p>\n<p>Il volume di cargo a Francoforte \u00e8 aumentato del 6,2% rispetto all&#8217;anno precedente, raggiungendo circa 2,1 milioni di tonnellate. Francoforte, come principale hub cargo in Europa, ha beneficiato di una maggiore domanda di merci aeree dovuta all&#8217;e-commerce. I problemi di capacit\u00e0 nel trasporto marittimo a causa delle crisi geopolitiche sono stati ulteriori fattori trainanti.<\/p>\n<p>Gli aeroporti internazionali partecipati hanno registrato anch&#8217;essi una crescita nella maggior parte dei casi. La maggiore dinamica \u00e8 stata registrata rispetto all&#8217;anno precedente a Lima (+15,2%), Lubiana (+13,3%), Antalya (+6,5%) e nei 14 aeroporti greci nel portafoglio Fraport (+6,4%). Complessivamente, il livello di passeggeri internazionali ha superato il record dell&#8217;anno pre-crisi 2019 (+1,3%).<\/p>\n<h5><strong>Grandi progressi nei principali progetti futuri<\/strong><\/h5>\n<p>Fraport sta per completare importanti progetti di espansione: a Lima, l&#8217;apertura di un nuovo terminal \u00e8 imminente. Questo raddoppier\u00e0 gradualmente la capacit\u00e0 dell&#8217;aeroporto Fraport nella capitale peruviana a 40 milioni di passeggeri nei prossimi mesi. Anche all&#8217;aeroporto di Antalya, un ampio programma di espansione sar\u00e0 lanciato prima dell&#8217;inizio della prossima stagione di viaggi. La destinazione balneare sulla Riviera turca potr\u00e0 quindi accogliere fino a 65 milioni di viaggiatori all&#8217;anno. A Francoforte, i lavori per il Terminal 3 stanno procedendo. L&#8217;inaugurazione \u00e8 prevista dopo Pasqua 2026.<\/p>\n<p>Allo stesso tempo, l&#8217;operatore aeroportuale dimostra che i due obiettivi strategici di crescita e sostenibilit\u00e0 non si escludono a vicenda: nel 2024, Fraport ha ridotto le emissioni di gas serra a livello di gruppo di circa il 14%. Il gruppo prevede di raggiungere ulteriori importanti traguardi nei prossimi anni, in particolare per quanto riguarda l&#8217;approvvigionamento di energia verde. Questi includono il completamento di un impianto fotovoltaico con 37.000 pannelli solari lungo la pista ovest dell&#8217;aeroporto di Francoforte e l&#8217;approvvigionamento di energia verde su larga scala da un parco eolico offshore nel Mare del Nord a partire dal 2026.<\/p>\n<p>Inoltre, Fraport ha ampliato i suoi obiettivi di sostenibilit\u00e0. In precedenza, le misure erano focalizzate sulla riduzione delle emissioni di CO<sub>2<\/sub>. La nuova visione \u00e8 molto pi\u00f9 ampia e considera tutti i gas serra rilevanti per il clima (= equivalenti di CO<sub>2<\/sub>). Fino al 2045, il gruppo Fraport si impegna a raggiungere lo stato di Net Zero in tutte le sedi consolidate all&#8217;interno degli Scopes 1 e 2. Net Zero significa neutralit\u00e0 delle emissioni di gas serra. Inoltre, fino al 2030: Fraport ridurr\u00e0 le emissioni di CO<sub>2<\/sub> a Francoforte a 50.000 tonnellate, a livello di gruppo a 95.000 tonnellate.<\/p>\n<h5><strong>Prospettive<\/strong><\/h5>\n<p>Per l&#8217;anno fiscale in corso, l&#8217;operatore aeroportuale prevede un volume di passeggeri a Francoforte di fino a 64 milioni. Si prevede un moderato aumento dell&#8217;EBITDA del gruppo. Il risultato del gruppo \u00e8 atteso in un intervallo che va da uno sviluppo stabile a una leggera diminuzione. La causa \u00e8 l&#8217;assenza dell&#8217;effetto straordinario derivante dalla vendita della partecipazione di minoranza nell&#8217;aeroporto di Pulkovo, che nel 2024 ha contribuito con oltre 40 milioni di euro al risultato del gruppo. A causa dell&#8217;elevato indebitamento del gruppo, il consiglio di sorveglianza e il consiglio di amministrazione hanno deciso di non proporre nuovamente un dividendo all&#8217;assemblea generale di quest&#8217;anno. Invece, l&#8217;utile di bilancio dovrebbe essere destinato alle riserve di utili e rafforzare la base di capitale proprio.<\/p>\n<h4><a href=\"https:\/\/www.geschaeftsbericht.fraport.de\/annual-report\/2024\/de\/\" target=\"_blank\" rel=\"noopener\">Scarica qui il rapporto annuale 2024<\/a><\/h4>\n<p>Foto: \u00a9 Fraport<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il gruppo Fraport ha concluso l&#8217;anno fiscale 2024 con una crescita nei principali indicatori economici. L&#8217;operatore aeroportuale internazionale ha aumentato i ricavi derivanti dal traffico e<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1558,1665,1561],"tags":[],"class_list":["post-68494","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-air-freight","category-categories","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2% - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2% - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il gruppo Fraport ha concluso l&#8217;anno fiscale 2024 con una crescita nei principali indicatori economici. L&#8217;operatore aeroportuale internazionale ha aumentato i ricavi derivanti dal traffico e [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-18T18:02:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_18.3.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1365\" \/>\n\t<meta property=\"og:image:height\" content=\"688\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2%\",\"datePublished\":\"2025-03-18T18:02:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/\"},\"wordCount\":1015,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_18.3.25.jpg\",\"articleSection\":[\"Air Freight\",\"Categories\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/\",\"name\":\"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2% - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_18.3.25.jpg\",\"datePublished\":\"2025-03-18T18:02:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_18.3.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Fraport_18.3.25.jpg\",\"width\":1365,\"height\":688},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/18\\\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2%\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2% - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/","og_locale":"it_IT","og_type":"article","og_title":"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2% - Loginfo24","og_description":"Il gruppo Fraport ha concluso l&#8217;anno fiscale 2024 con una crescita nei principali indicatori economici. L&#8217;operatore aeroportuale internazionale ha aumentato i ricavi derivanti dal traffico e [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-03-18T18:02:13+00:00","og_image":[{"width":1365,"height":688,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_18.3.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/"},"author":{"name":"","@id":""},"headline":"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2%","datePublished":"2025-03-18T18:02:13+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/"},"wordCount":1015,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_18.3.25.jpg","articleSection":["Air Freight","Categories","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/","url":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/","name":"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2% - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_18.3.25.jpg","datePublished":"2025-03-18T18:02:13+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_18.3.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Fraport_18.3.25.jpg","width":1365,"height":688},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/18\/il-volume-di-merci-aeree-a-francoforte-e-aumentato-del-62\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Il volume di merci aeree a Francoforte \u00e8 aumentato del 6,2%"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/68494","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=68494"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/68494\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/5276"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=68494"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=68494"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=68494"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}