{"id":68464,"date":"2025-03-14T19:00:48","date_gmt":"2025-03-14T18:00:48","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/"},"modified":"2025-03-14T19:00:48","modified_gmt":"2025-03-14T18:00:48","slug":"lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/","title":{"rendered":"L&#8217;Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale"},"content":{"rendered":"<h5>I dati economici attuali presentati oggi dall&#8217;Associazione dei Naviganti Tedeschi (VDR) durante la sua conferenza stampa annuale confermano: nonostante le turbolenze geopolitiche e i tempi incerti nella politica commerciale internazionale, la navigazione tedesca rimane un garante affidabile per la forza economica e la sicurezza dell&#8217;approvvigionamento della Repubblica Federale. Circa il 62% delle esportazioni tedesche e il 60% delle importazioni vengono gestite via mare, una prova di quanto sia essenziale un commercio marittimo funzionante e una flotta commerciale competitiva per la sopravvivenza della nostra nazione esportatrice.<\/h5>\n<p>(Hamburgo) I numeri sono impressionanti: con quasi 290 compagnie di navigazione con sede in Germania e una flotta di 1.764 navi, nonch\u00e9 un tonnellaggio lordo (BRZ) di 47,4 milioni, la Germania si posiziona anche quest&#8217;anno al settimo posto tra le nazioni leader nella navigazione commerciale mondiale. La flotta commerciale tedesca garantisce circa 500.000 posti di lavoro nell&#8217;economia marittima e costituisce, in caso di crisi, il vettore vitale per garantire l&#8217;approvvigionamento della Repubblica Federale con beni, materie prime ed energia.<\/p>\n<p>La presidente del VDR, Gaby Bornheim, sottolinea: &#8220;Senza una navigazione commerciale forte e indipendente non ci sono n\u00e9 stabilit\u00e0 economica n\u00e9 sicurezza nazionale, soprattutto in tempi in cui i rischi geo- e commerciali aumentano costantemente.&#8221;<\/p>\n<h5><strong>Tra crisi geopolitiche e cambi di rotta protezionistici<\/strong><\/h5>\n<p>Le crescenti tensioni su importanti rotte commerciali marittime internazionali \u2013 dal Mar Cinese Meridionale allo Stretto di Taiwan fino alle acque intorno al Mar Nero e al Mar Rosso \u2013 non solo disturbano il commercio globale via mare, ma comportano anche il rischio significativo di attacchi alle navi commerciali tedesche e di blocchi di rotte marittime cruciali per le importazioni e le esportazioni tedesche.<\/p>\n<p>Il VDR avverte: gli interessi nazionali non devono andare a scapito del libero flusso di merci globale. Anche le crescenti tendenze protezionistiche nel commercio mondiale pongono sfide alla navigazione tedesca. Aumenti dei dazi e misure restrittive che mirano a isolare i mercati nazionali portano a catene di approvvigionamento interrotte e costi di trasporto in aumento. Per le compagnie di navigazione, ci\u00f2 significa non solo possibili percorsi commerciali pi\u00f9 lunghi e costi operativi pi\u00f9 elevati, ma soprattutto una notevole incertezza nella pianificazione nel commercio globale delle merci.<\/p>\n<p>Queste sfide sono ulteriormente amplificate dagli ultimi annunci protezionistici provenienti dagli Stati Uniti. L&#8217;introduzione da parte del presidente Trump di dazi del 25% sulle merci europee da parte degli Stati Uniti, cos\u00ec come una tassa multimilionaria pianificata dagli Stati Uniti sulle navi costruite in Cina all&#8217;arrivo nei porti statunitensi, generano notevole incertezza nella flotta commerciale tedesca e globale. Allo stesso tempo, non si pu\u00f2 pi\u00f9 escludere che il governo degli Stati Uniti si ritiri sempre pi\u00f9 dagli impegni di sicurezza. Di conseguenza, cresce anche per la Germania la necessit\u00e0 di garantire a lungo termine il proprio approvvigionamento e, come risposta strategica all&#8217;evoluzione dell&#8217;architettura commerciale e di sicurezza globale, rafforzare la propria flotta commerciale e garantirne l&#8217;esistenza.<\/p>\n<p>&#8220;In quanto nazione esportatrice leader e paese povero di materie prime, dipendiamo da rotte commerciali e marittime sicure e libere. \u00c8 necessaria una strategia nazionale di sicurezza marittima coerente, una maggiore presenza navale e una cooperazione pi\u00f9 intensa tra le autorit\u00e0 di sicurezza e la flotta commerciale. La sicurezza costa \u2013 esitare costa di pi\u00f9&#8221;, avverte il direttore generale del VDR, Martin Kr\u00f6ger.<\/p>\n<h5><strong>La Svizzera \u00e8 al primo posto nella navigazione container<\/strong><\/h5>\n<p>Sebbene la Germania rimanga un importante centro di navigazione, il confronto internazionale rivela delle sfide: nella navigazione container, la Germania (30,2 milioni di BRZ) \u00e8 attualmente al terzo posto, dietro alla Svizzera (34,7 milioni di BRZ) e alla Cina (31 milioni di BRZ) \u2013 un chiaro segnale della forte concorrenza a livello globale. Pertanto, il VDR richiede un potenziamento mirato e a lungo termine della competitivit\u00e0 delle compagnie di navigazione tedesche e del sito di navigazione tedesco, per non perdere il contatto a livello internazionale.<\/p>\n<p>&#8220;La concorrenza internazionale tra le flotte commerciali e i centri di navigazione \u00e8 alta e dinamica \u2013 la pressione competitiva \u00e8 sempre pi\u00f9 avvertibile. Dobbiamo garantire a lungo termine la competitivit\u00e0 della nostra flotta commerciale tedesca e rafforzare in modo coerente soprattutto la nostra media impresa marittima&#8221;, richiede Kr\u00f6ger.<\/p>\n<p>La maggior parte delle compagnie di navigazione tedesche \u00e8 caratterizzata da una struttura di piccole e medie imprese. L&#8217;80% delle aziende ha meno di dieci navi. Ogni seconda nave della flotta commerciale tedesca naviga sotto la bandiera di un paese dell&#8217;UE, in particolare sotto quella tedesca e portoghese.<\/p>\n<h5><strong>Nuovo impulso positivo per la nuova generazione<\/strong><\/h5>\n<p>Particolarmente incoraggiante: il numero di neolaureati nella navigazione \u00e8 aumentato del 14% nell&#8217;anno formativo 2024. Con 499 nuovi ingressi in mare (anno precedente 418) e 214 a terra (anno precedente 208), si dimostra che sempre pi\u00f9 giovani riconoscono le molteplici opportunit\u00e0 e prospettive future della navigazione \u2013 un importante tassello per garantire il know-how marittimo e quindi rafforzare il sito di navigazione tedesco, ma anche per la trasformazione del settore verso la neutralit\u00e0 climatica.<\/p>\n<p>&#8220;La navigazione ha bisogno di giovani talenti visionari e motivati, che non solo vogliono plasmare attivamente il futuro del settore, ma che osano anche compiere il passo decisivo verso un&#8217;era climatica neutra insieme a noi. \u00c8 estremamente incoraggiante osservare come sempre pi\u00f9 giovani talenti riconoscano le enormi opportunit\u00e0 nella navigazione e affrontino con entusiasmo questa sfida&#8221;, spiega Bornheim.<\/p>\n<h5><strong>La burocrazia frena la crescita<\/strong><\/h5>\n<p>Oltre alle incertezze geo- e commerciali, le compagnie di navigazione tedesche si trovano ad affrontare una giungla burocratica sempre pi\u00f9 fitta in Europa. Obblighi di segnalazione doppi e regolamenti speciali regionali in materia di protezione climatica gravano inutilmente sull&#8217;operativit\u00e0 delle navi e riducono la competitivit\u00e0. &#8220;\u00c8 giunto il momento che l&#8217;Europa e la Germania abbandonino il loro discutibile ruolo di leadership in una burocrazia eccessiva e in regolamenti speciali regionali. Processi pi\u00f9 snelli e requisiti di protezione climatica uniformi a livello internazionale sono indispensabili per garantire la forza economica della Germania in mare&#8221;, spiega Kr\u00f6ger.<\/p>\n<p>Foto: \u00a9 Loginfo24<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I dati economici attuali presentati oggi dall&#8217;Associazione dei Naviganti Tedeschi (VDR) durante la sua conferenza stampa annuale confermano: nonostante le turbolenze geopolitiche e i tempi incerti<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1561,1559],"tags":[],"class_list":["post-68464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-regions","category-shipping-ports"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"I dati economici attuali presentati oggi dall&#8217;Associazione dei Naviganti Tedeschi (VDR) durante la sua conferenza stampa annuale confermano: nonostante le turbolenze geopolitiche e i tempi incerti [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-14T18:00:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schiff_Container_1-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1901\" \/>\n\t<meta property=\"og:image:height\" content=\"898\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"L&#8217;Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale\",\"datePublished\":\"2025-03-14T18:00:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/\"},\"wordCount\":965,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schiff_Container_1-1.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Regions\",\"Shipping &amp; Ports\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/\",\"name\":\"L'Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schiff_Container_1-1.jpg\",\"datePublished\":\"2025-03-14T18:00:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schiff_Container_1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Schiff_Container_1-1.jpg\",\"width\":1901,\"height\":898},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/03\\\/14\\\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/","og_locale":"it_IT","og_type":"article","og_title":"L'Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale - Loginfo24","og_description":"I dati economici attuali presentati oggi dall&#8217;Associazione dei Naviganti Tedeschi (VDR) durante la sua conferenza stampa annuale confermano: nonostante le turbolenze geopolitiche e i tempi incerti [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-03-14T18:00:48+00:00","og_image":[{"width":1901,"height":898,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schiff_Container_1-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"5 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/"},"author":{"name":"","@id":""},"headline":"L&#8217;Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale","datePublished":"2025-03-14T18:00:48+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/"},"wordCount":965,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schiff_Container_1-1.jpg","articleSection":["Forwarding &amp; Logistics","Regions","Shipping &amp; Ports"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/","url":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/","name":"L'Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schiff_Container_1-1.jpg","datePublished":"2025-03-14T18:00:48+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schiff_Container_1-1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Schiff_Container_1-1.jpg","width":1901,"height":898},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/03\/14\/lassociazione-dei-naviganti-tedeschi-tiene-la-conferenza-stampa-annuale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;Associazione dei Naviganti Tedeschi tiene la conferenza stampa annuale"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/68464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=68464"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/68464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/5286"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=68464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=68464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=68464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}