{"id":67798,"date":"2025-01-21T18:28:31","date_gmt":"2025-01-21T17:28:31","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/"},"modified":"2025-01-21T18:28:31","modified_gmt":"2025-01-21T17:28:31","slug":"henkel-presenta-un-adesivo-speciale-per-le-commerce","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/","title":{"rendered":"Henkel presenta un adesivo speciale per l&#8217;e-commerce"},"content":{"rendered":"<h5><strong>Commissionare, imballare e spedire a ritmo serrato: milioni di pacchi hanno lasciato i magazzini dell&#8217;e-commerce nelle ultime settimane intorno al Black Friday e al Natale. Molti prodotti sono stati imballati in modo eccessivo e con materiale di riempimento superfluo. Altri sono stati danneggiati durante il trasporto e sono tornati come resi. Il comune denominatore di entrambi i problemi: imballaggi inefficienti. <\/strong><\/h5>\n<p>(D\u00fcsseldorf) N\u00e9 troppo n\u00e9 troppo poco materiale di riempimento: con il Right-Sized Packaging, le aziende di logistica evitano sia l&#8217;imballaggio insufficiente che quello eccessivo, poich\u00e9 la tecnologia di imballaggio automatizzata adatta esattamente la dimensione delle scatole di spedizione al prodotto. In questo modo si risparmiano non solo materiali e costi di trasporto, ma si aumenta anche notevolmente l&#8217;efficienza dell&#8217;imballaggio nei periodi di punta. Grazie alle dimensioni efficienti dei pacchi, il volume di trasporto diminuisce fino al 20% e, di conseguenza, anche le emissioni di CO\u2082 per consegna, mentre il numero di pacchi spediti al giorno aumenta. Allo stesso tempo, l&#8217;imballaggio su misura garantisce che i prodotti delicati siano meglio protetti e che la percentuale di resi causati da danni durante il trasporto diminuisca.<\/p>\n<p>Nel Right-Sized Packaging, i pacchi vengono incollati con un adesivo termofusibile, il che consente di risparmiare grandi quantit\u00e0 di nastro adesivo e pellicola da trasporto. Henkel Adhesive Technologies offre un adesivo particolarmente sostenibile per questa soluzione di imballaggio automatizzata con il nuovo Technomelt E-COM G5 Eco Cool, sviluppato appositamente per l&#8217;e-commerce. Questo \u00e8 composto in gran parte da materie prime di origine biologica e consente di risparmiare energia grazie alla sua bassa temperatura di lavorazione. Inoltre, la compatibilit\u00e0 dell&#8217;adesivo con il processo di riciclaggio contribuisce a ridurre ulteriormente l&#8217;impronta ecologica delle soluzioni di imballaggio. Henkel presenta questo nuovo prodotto anche alla LogiMAT che si svolger\u00e0 a met\u00e0 marzo.<\/p>\n<h5>Momento giusto per tecnologie di imballaggio sostenibili e automatizzate<\/h5>\n<p>L&#8217;automazione del processo di imballaggio consente alle aziende di rispondere in modo flessibile a fluttuazioni degli ordini, riducendo al contempo costi e rifiuti. Eike Dominiak, Business Development Manager E-Commerce Packaging di Henkel, sottolinea: &#8220;Dopo un anno con fatturati record e processi logistici intensi, ora \u00e8 il momento giusto per passare a tecnologie di imballaggio sostenibili e automatizzate. Con Henkel come partner affidabile, le aziende possono ottimizzare la loro catena del valore e posizionarsi come pionieri nella logistica sostenibile.&#8221;<\/p>\n<p>Foto: \u00a9 Henkel<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Commissionare, imballare e spedire a ritmo serrato: milioni di pacchi hanno lasciato i magazzini dell&#8217;e-commerce nelle ultime settimane intorno al Black Friday e al Natale. Molti<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5508,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1557,1560,1561],"tags":[],"class_list":["post-67798","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-forwarding-logistics","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Henkel presenta un adesivo speciale per l&#039;e-commerce - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Henkel presenta un adesivo speciale per l&#039;e-commerce - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Commissionare, imballare e spedire a ritmo serrato: milioni di pacchi hanno lasciato i magazzini dell&#8217;e-commerce nelle ultime settimane intorno al Black Friday e al Natale. Molti [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-21T17:28:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Henkel_21.1.25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"540\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Henkel presenta un adesivo speciale per l&#8217;e-commerce\",\"datePublished\":\"2025-01-21T17:28:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/\"},\"wordCount\":395,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Henkel_21.1.25.jpg\",\"articleSection\":[\"Forwarding &amp; Logistics\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/\",\"name\":\"Henkel presenta un adesivo speciale per l'e-commerce - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Henkel_21.1.25.jpg\",\"datePublished\":\"2025-01-21T17:28:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Henkel_21.1.25.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Henkel_21.1.25.jpg\",\"width\":540,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2025\\\/01\\\/21\\\/henkel-presenta-un-adesivo-speciale-per-le-commerce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Henkel presenta un adesivo speciale per l&#8217;e-commerce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Henkel presenta un adesivo speciale per l'e-commerce - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/","og_locale":"it_IT","og_type":"article","og_title":"Henkel presenta un adesivo speciale per l'e-commerce - Loginfo24","og_description":"Commissionare, imballare e spedire a ritmo serrato: milioni di pacchi hanno lasciato i magazzini dell&#8217;e-commerce nelle ultime settimane intorno al Black Friday e al Natale. Molti [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2025-01-21T17:28:31+00:00","og_image":[{"width":540,"height":360,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Henkel_21.1.25.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/"},"author":{"name":"","@id":""},"headline":"Henkel presenta un adesivo speciale per l&#8217;e-commerce","datePublished":"2025-01-21T17:28:31+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/"},"wordCount":395,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Henkel_21.1.25.jpg","articleSection":["Forwarding &amp; Logistics","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/","url":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/","name":"Henkel presenta un adesivo speciale per l'e-commerce - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Henkel_21.1.25.jpg","datePublished":"2025-01-21T17:28:31+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Henkel_21.1.25.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Henkel_21.1.25.jpg","width":540,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2025\/01\/21\/henkel-presenta-un-adesivo-speciale-per-le-commerce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"Henkel presenta un adesivo speciale per l&#8217;e-commerce"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/67798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=67798"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/67798\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/5508"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=67798"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=67798"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=67798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}