{"id":66940,"date":"2024-10-18T19:14:12","date_gmt":"2024-10-18T17:14:12","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/"},"modified":"2024-10-18T19:14:12","modified_gmt":"2024-10-18T17:14:12","slug":"tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/","title":{"rendered":"TGW supera il limite di fatturato di un miliardo di euro"},"content":{"rendered":"<h5><strong>Il fornitore austriaco di intralogistica TGW Logistics ha concluso con successo l&#8217;anno fiscale 2023\/2024 (1 luglio 2023 - 30 giugno 2024). Il fatturato dell&#8217;azienda tecnologica attiva a livello internazionale \u2013 che progetta, costruisce e gestisce centri logistici altamente automatizzati \u2013 \u00e8 salito a oltre un miliardo di euro, mentre l&#8217;EBIT \u00e8 aumentato a 29,6 milioni di euro.\u00a0\u00a0\u00a0 <\/strong><\/h5>\n<p>(Marchtrenk) &#8220;Il nostro fatturato \u00e8 cresciuto del dodici percento e ha superato per la prima volta nella nostra storia di 55 anni la soglia del miliardo. Siamo riusciti a trasformare il risultato (EBIT) da un valore leggermente negativo dell&#8217;anno precedente a un chiaro surplus di circa 30 milioni di euro&#8221;, sottolinea Henry Puhl, Amministratore Delegato di TGW Logistics. &#8220;Alla luce delle condizioni economiche, molte aziende sono ancora caute negli investimenti nella loro intralogistica. Tuttavia, le nostre previsioni mostrano che il mercato dovrebbe riprendersi nel 2025 \u2013 siamo convinti del potenziale e della sostenibilit\u00e0 del settore.&#8221;<\/p>\n<h5><strong>54 milioni per ricerca e sviluppo\u00a0\u00a0 <\/strong><\/h5>\n<div id=\"attachment_27255\" style=\"width: 251px\" class=\"wp-caption alignleft\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-27255\" class=\" wp-image-27255\" src=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_18.10.24_2-134x300.jpg\" alt=\"\" width=\"241\" height=\"539\" \/><p id=\"caption-attachment-27255\" class=\"wp-caption-text\">Henry Puhl, CEO TGW Logistics GmbH<\/p><\/div>\n<p>Rispetto all&#8217;anno precedente, TGW Logistics ha aumentato il budget per ricerca e sviluppo del 13 percento, superando i 54 milioni di euro: ci\u00f2 corrisponde al cinque percento del fatturato. In particolare, l&#8217;attenzione \u00e8 rivolta a: robotica, intelligenza artificiale e digitalizzazione. Con RovoFlex, nella primavera del 2024 ha debuttato un innovativo robot per la preparazione degli ordini, che ha il potenziale per rivoluzionare il settore. Grazie alle scoperte nei campi dell&#8217;intelligenza artificiale e della robotica cognitiva, esso \u00e8 in grado di preparare gli ordini in modo completamente autonomo e senza intervento umano.<\/p>\n<p>Le aziende di medie dimensioni cos\u00ec come noti player globali si affidano al know-how intralogistico di TGW Logistics: da K\u00e4rcher e Intersport a Mango e Puma fino a Zalando.<\/p>\n<p>&#8220;Tutti noi ordiniamo regolarmente online, facciamo acquisti nel commercio al dettaglio o andiamo al supermercato. Ci\u00f2 che pochi sono consapevoli durante lo shopping: affinch\u00e9 gli ordini online arrivino rapidamente e i punti vendita siano riforniti in modo affidabile, una potente intralogistica \u00e8 la chiave indispensabile&#8221;, sottolinea Henry Puhl. &#8220;La tecnologia made in Upper Austria garantisce che le aziende possano fornire rapidamente e in modo affidabile i propri clienti in tutto il mondo.&#8221;<\/p>\n<h5><strong>Investimento nel nuovo quartier generale\u00a0 <\/strong><\/h5>\n<p>TGW Logistics continua inoltre a investire nella propria infrastruttura. Il 25 settembre \u00e8 stata inaugurata ufficialmente l&#8217;espansione del quartier generale a Marchtrenk con una cerimonia di posa della prima pietra. Fino all&#8217;estate del 2026, l&#8217;azienda tecnologica investir\u00e0 fino a 100 milioni di euro in un capannone di produzione di 25.000 m\u00b2 e in un sistema di magazzino altamente automatizzato \u2013 come base per la crescita di domani.<\/p>\n<p>Foto: \u00a9 TGW Logistics<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il fornitore austriaco di intralogistica TGW Logistics ha concluso con successo l&#8217;anno fiscale 2023\/2024 (1 luglio 2023 - 30 giugno 2024). Il fatturato dell&#8217;azienda tecnologica attiva<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":5851,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1560,1561],"tags":[],"class_list":["post-66940","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-intralogistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>TGW supera il limite di fatturato di un miliardo di euro - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"TGW supera il limite di fatturato di un miliardo di euro - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"Il fornitore austriaco di intralogistica TGW Logistics ha concluso con successo l&#8217;anno fiscale 2023\/2024 (1 luglio 2023 - 30 giugno 2024). Il fatturato dell&#8217;azienda tecnologica attiva [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-18T17:14:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_18.10.24_1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1672\" \/>\n\t<meta property=\"og:image:height\" content=\"790\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"TGW supera il limite di fatturato di un miliardo di euro\",\"datePublished\":\"2024-10-18T17:14:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/\"},\"wordCount\":432,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_18.10.24_1.jpg\",\"articleSection\":[\"Categories\",\"Intralogistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/\",\"name\":\"TGW supera il limite di fatturato di un miliardo di euro - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_18.10.24_1.jpg\",\"datePublished\":\"2024-10-18T17:14:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_18.10.24_1.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/TGW_18.10.24_1.jpg\",\"width\":1672,\"height\":790},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/10\\\/18\\\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"TGW supera il limite di fatturato di un miliardo di euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"TGW supera il limite di fatturato di un miliardo di euro - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/","og_locale":"it_IT","og_type":"article","og_title":"TGW supera il limite di fatturato di un miliardo di euro - Loginfo24","og_description":"Il fornitore austriaco di intralogistica TGW Logistics ha concluso con successo l&#8217;anno fiscale 2023\/2024 (1 luglio 2023 - 30 giugno 2024). Il fatturato dell&#8217;azienda tecnologica attiva [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-10-18T17:14:12+00:00","og_image":[{"width":1672,"height":790,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_18.10.24_1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/"},"author":{"name":"","@id":""},"headline":"TGW supera il limite di fatturato di un miliardo di euro","datePublished":"2024-10-18T17:14:12+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/"},"wordCount":432,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_18.10.24_1.jpg","articleSection":["Categories","Intralogistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/","url":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/","name":"TGW supera il limite di fatturato di un miliardo di euro - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_18.10.24_1.jpg","datePublished":"2024-10-18T17:14:12+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_18.10.24_1.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/TGW_18.10.24_1.jpg","width":1672,"height":790},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2024\/10\/18\/tgw-supera-il-limite-di-fatturato-di-un-miliardo-di-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"TGW supera il limite di fatturato di un miliardo di euro"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/66940","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=66940"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/66940\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/5851"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=66940"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=66940"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=66940"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}