{"id":65578,"date":"2024-06-11T18:29:20","date_gmt":"2024-06-11T16:29:20","guid":{"rendered":"https:\/\/blog.brand-architecture.at\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/"},"modified":"2024-06-11T18:29:20","modified_gmt":"2024-06-11T16:29:20","slug":"dachser-service-e-formazione-gmbh-compie-10-anni","status":"publish","type":"post","link":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/","title":{"rendered":"DACHSER Service e Formazione GmbH compie 10 anni"},"content":{"rendered":"<h5>La carenza di autisti e professionisti specializzati preoccupa l&#8217;economia e in particolare la logistica. \u00c8 considerata uno dei fattori critici che ostacolano la crescita futura. Dieci anni fa, DACHSER Service e Formazione GmbH ha avviato un&#8217;iniziativa di qualificazione sostenibile. Oggi DACHSER \u00e8 uno dei maggiori formatori di autisti professionisti in Germania.<\/h5>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<p>(Kempten\/Senza autisti professionisti, praticamente nulla funziona. L&#8217;economia si fermerebbe, gli scaffali nei supermercati e nei grandi magazzini rimarrebbero vuoti. Tuttavia, il settore della logistica manca di nuovi autisti. Uno studio consortile pubblicato all&#8217;inizio del 2023, &#8220;Affrontare le carenze di capacit\u00e0 nella logistica con focus sul personale di guida&#8221;, stima il deficit in Germania in oltre 70.000 professionisti. E ogni anno circa 20.000 ulteriori posti di lavoro alla guida non possono essere coperti. Le cause sono molteplici: orari di lavoro poco attraenti, stipendi poco competitivi e anche la mancanza di riconoscimento sociale. Il risultato: il settore dei trasporti soffre di un problema d&#8217;immagine, la professione di autista \u00e8 spesso percepita negativamente. Un rapporto dell&#8217;Unione Internazionale dei Trasporti Stradali (IRU) vede la carenza di autisti, con oltre tre milioni di posti di lavoro per autisti di camion vacanti in 36 paesi studiati, come un problema europeo e mondiale.<\/p>\n<p>&#8220;La carenza di professionisti \u00e8 un&#8217;evoluzione generale del mercato che colpisce l&#8217;intero settore della logistica&#8221;, afferma Alexander Tonn, COO Road Logistics di DACHSER. &#8220;Dobbiamo fare sempre maggiori sforzi per coprire i posti vacanti.&#8221; Per questo motivo, DACHSER ha iniziato dieci anni fa a lavorare in questo senso e, come una delle prime aziende di logistica, ha avviato un&#8217;iniziativa di qualificazione con la fondazione della &#8220;DACHSER Service e Formazione GmbH&#8221;. L&#8217;obiettivo: attrarre giovani al mestiere di autista, entusiasmarli, formarli e garantirli a lungo termine - idealmente in seguito come partner di trasporto autonomi - per il mercato.<\/p>\n<p>&#8220;Riconoscimento, prospettive, responsabilit\u00e0 personale e stipendio sono i fattori pi\u00f9 importanti per rendere la professione pi\u00f9 attraente&#8221;, ha dichiarato Hendrik Jansen, Managing Director di DACHSER Service e Formazione GmbH, che accompagna l&#8217;iniziativa sin dai suoi inizi.<\/p>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<h5>Trovare e motivare autisti<\/h5>\n<\/div>\n<\/div>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<p>Da allora, ogni anno circa cento apprendisti hanno intrapreso il loro percorso di qualificazione per diventare autisti professionisti. &#8220;Abbiamo professionalizzato la formazione e la formazione continua, il TQ1, e abbiamo messo sotto esame tutti i processi legati al mondo degli autisti&#8221;, afferma Jansen. Questo ha incluso, ad esempio, l&#8217;assunzione di manager della flotta in ogni filiale tedesca di DACHSER, che ricoprono un ruolo chiave all&#8217;interno del concetto e si occupano specificamente delle esigenze degli autisti.<\/p>\n<div class=\"article__item-wrap\">\n<div class=\"article__item\">\n<p>&#8220;In DACHSER, i dipendenti a tutti i livelli operativi hanno un significato e un valore proprio. Questo riconoscimento e questa cultura del lavoro si riflettono anche a livello degli autisti in posti di lavoro moderni e confortevoli. Ci\u00f2 include anche il fatto che vengono affrontati temi come una dieta sana, movimento e prevenzione delle dipendenze&#8221;, spiega Jansen. Le analisi del flusso di valore, che DACHSER conduce regolarmente nelle sue filiali, rappresentano tutti i processi legati alla vita lavorativa degli autisti e mostrano potenziali di ottimizzazione e opportunit\u00e0 di sviluppo. Anche qui vengono sempre esplicitamente considerate le esigenze degli autisti.<\/p>\n<h5>Promuovere un cambiamento nell&#8217;approccio<\/h5>\n<p>&#8220;Trovare buoni autisti \u00e8 una cosa. \u00c8 altrettanto importante mantenere buone persone e motivarle ulteriormente&#8221;, osserva Hendrik Jansen. \u00c8 necessario anche tenere conto di un cambiamento nell&#8217;atteggiamento delle persone nei confronti del lavoro. &#8220;Oggi si tratta di temi come l&#8217;equilibrio tra vita lavorativa e vita privata, una comunicazione cambiata o un lavoro significativo e gratificante. E questi sono esattamente i punti su cui dobbiamo lavorare: se riusciamo - e questo vale non solo per DACHSER - a promuovere un cambiamento nell&#8217;approccio nei confronti dei nostri autisti, allora riusciremo a realizzare un cambiamento culturale e un conseguente maggiore riconoscimento per questa professione e per le persone che la esercitano.&#8221;<\/p>\n<div class=\"text-with-image__text text-with-image__text--align-right\">\n<p>Anche se questo da solo non risolver\u00e0 la carenza di autisti, strutturalmente causata e presente a livello mondiale, la DACHSER Service e Formazione GmbH ha lanciato un segnale. &#8220;La logistica sostenibile si decide sulla qualit\u00e0 del servizio e delle persone che lo forniscono giorno dopo giorno&#8221;, afferma Alexander Tonn. &#8220;Vogliamo abilitarli, fornire loro le migliori condizioni e apprezzarli nel loro operato. Le basi vengono create nella formazione e nella formazione continua. Su questo punto ci concentriamo con la nostra iniziativa.&#8221;<\/p>\n<p>Foto: \u00a9 DACHSER<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La carenza di autisti e professionisti specializzati preoccupa l&#8217;economia e in particolare la logistica. \u00c8 considerata uno dei fattori critici che ostacolano la crescita futura. Dieci<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":0,"featured_media":6397,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1665,1557,1561],"tags":[],"class_list":["post-65578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-categories","category-forwarding-logistics","category-regions"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>DACHSER Service e Formazione GmbH compie 10 anni - Loginfo24<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"DACHSER Service e Formazione GmbH compie 10 anni - Loginfo24\" \/>\n<meta property=\"og:description\" content=\"La carenza di autisti e professionisti specializzati preoccupa l&#8217;economia e in particolare la logistica. \u00c8 considerata uno dei fattori critici che ostacolano la crescita futura. Dieci [\u2026]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/\" \/>\n<meta property=\"og:site_name\" content=\"Loginfo24\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T16:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_11.6.24.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1286\" \/>\n\t<meta property=\"og:image:height\" content=\"713\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"DACHSER Service e Formazione GmbH compie 10 anni\",\"datePublished\":\"2024-06-11T16:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/\"},\"wordCount\":715,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_11.6.24.jpg\",\"articleSection\":[\"Categories\",\"Forwarding &amp; Logistics\",\"Regions\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/\",\"name\":\"DACHSER Service e Formazione GmbH compie 10 anni - Loginfo24\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_11.6.24.jpg\",\"datePublished\":\"2024-06-11T16:29:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#primaryimage\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_11.6.24.jpg\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2025\\\/12\\\/Dachser_11.6.24.jpg\",\"width\":1286,\"height\":713},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/2024\\\/06\\\/11\\\/dachser-service-e-formazione-gmbh-compie-10-anni\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"DACHSER Service e Formazione GmbH compie 10 anni\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"name\":\"Loginfo24\",\"description\":\"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.\",\"publisher\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#organization\",\"name\":\"Logismedia Group AG\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"contentUrl\":\"https:\\\/\\\/loginfo24.com\\\/wp-content\\\/uploads\\\/sites\\\/7\\\/2026\\\/01\\\/Logo_LogInfo24.png\",\"width\":938,\"height\":351,\"caption\":\"Logismedia Group AG\"},\"image\":{\"@id\":\"https:\\\/\\\/loginfo24.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/people\\\/Loginfo24\\\/100057360583332\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/lofinfo24\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"DACHSER Service e Formazione GmbH compie 10 anni - Loginfo24","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/","og_locale":"it_IT","og_type":"article","og_title":"DACHSER Service e Formazione GmbH compie 10 anni - Loginfo24","og_description":"La carenza di autisti e professionisti specializzati preoccupa l&#8217;economia e in particolare la logistica. \u00c8 considerata uno dei fattori critici che ostacolano la crescita futura. Dieci [\u2026]","og_url":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/","og_site_name":"Loginfo24","article_publisher":"https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","article_published_time":"2024-06-11T16:29:20+00:00","og_image":[{"width":1286,"height":713,"url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_11.6.24.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"3 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#article","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/"},"author":{"name":"","@id":""},"headline":"DACHSER Service e Formazione GmbH compie 10 anni","datePublished":"2024-06-11T16:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/"},"wordCount":715,"commentCount":0,"publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_11.6.24.jpg","articleSection":["Categories","Forwarding &amp; Logistics","Regions"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/","url":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/","name":"DACHSER Service e Formazione GmbH compie 10 anni - Loginfo24","isPartOf":{"@id":"https:\/\/loginfo24.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#primaryimage"},"image":{"@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#primaryimage"},"thumbnailUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_11.6.24.jpg","datePublished":"2024-06-11T16:29:20+00:00","breadcrumb":{"@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#primaryimage","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_11.6.24.jpg","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2025\/12\/Dachser_11.6.24.jpg","width":1286,"height":713},{"@type":"BreadcrumbList","@id":"https:\/\/loginfo24.com\/it\/2024\/06\/11\/dachser-service-e-formazione-gmbh-compie-10-anni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/loginfo24.com\/it\/"},{"@type":"ListItem","position":2,"name":"DACHSER Service e Formazione GmbH compie 10 anni"}]},{"@type":"WebSite","@id":"https:\/\/loginfo24.com\/it\/#website","url":"https:\/\/loginfo24.com\/it\/","name":"Loginfo24","description":"Loginfo24 \u00e8 la piattaforma dedicata alla logistica e alle catene di fornitura con informazioni disponibili 24 ore su 24.","publisher":{"@id":"https:\/\/loginfo24.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/loginfo24.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/loginfo24.com\/it\/#organization","name":"Logismedia Group AG","url":"https:\/\/loginfo24.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","contentUrl":"https:\/\/loginfo24.com\/wp-content\/uploads\/sites\/7\/2026\/01\/Logo_LogInfo24.png","width":938,"height":351,"caption":"Logismedia Group AG"},"image":{"@id":"https:\/\/loginfo24.com\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Loginfo24\/100057360583332\/","https:\/\/www.linkedin.com\/company\/lofinfo24\/"]}]}},"_links":{"self":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/65578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/comments?post=65578"}],"version-history":[{"count":0,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/posts\/65578\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media\/6397"}],"wp:attachment":[{"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/media?parent=65578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/categories?post=65578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/loginfo24.com\/it\/wp-json\/wp\/v2\/tags?post=65578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}